{"id":138,"count":17,"description":"","link":"https:\/\/louma-jobs.com\/cameroun\/villes\/edea\/","name":"Edea","slug":"edea","taxonomy":"villes","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes\/138"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/taxonomies\/villes"}],"wp:post_type":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois?villes=138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}