{"id":9826,"date":"2021-01-20T10:14:16","date_gmt":"2021-01-20T09:14:16","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=9826"},"modified":"2021-01-20T10:14:19","modified_gmt":"2021-01-20T09:14:19","slug":"offre-demploi-collectrices-cofidem-finance","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/offre-demploi-collectrices-cofidem-finance\/","title":{"rendered":"Offre d\u2019emploi : Collectrices -COFIDEM FINANCE"},"content":{"rendered":"\n<p><strong>COFIDEM FINANCE<\/strong>&nbsp;recrute des collectrices pour les besoins de ses services.<br>Elles auront pour mission des actions de collecte, management, prospection et fid\u00e9lisation des clients.<br><strong>Conditions :<\/strong><\/p>\n\n\n\n<ul><li>\u00catre de sexe f\u00e9minin<\/li><li>Avoir une bonne capacit\u00e9 de marketing et relationnelle<\/li><li>Convaincante, d\u00e9termin\u00e9e et adapt\u00e9e \u00e0 sa client\u00e8le<\/li><li>Rigueur, ponctualit\u00e9<\/li><li>Bonne pr\u00e9sentation<\/li><\/ul>\n\n\n\n<p><strong>Composition du dossier :<\/strong><\/p>\n\n\n\n<ul><li>Lettre de motivation<\/li><li>CV<\/li><li>Photocopie CNI<\/li><li>Plan de localisation<\/li><\/ul>\n\n\n\n<p>Bien vouloir d\u00e9poser vos dossiers \u00e0 la direction g\u00e9n\u00e9rale sis au Carrefour carri\u00e8re &#8211; Yaound\u00e9 tous les jours ouvrables de 9heures \u00e0 14heures<br><strong>Contact :<\/strong><\/p>\n\n\n\n<ul><li><a href=\"tel:697 94 68 47\" class=\"rank-math-link\">697 94 68 47<\/a><\/li><li><a href=\"tel:670 87 81 68\" class=\"rank-math-link\">670 87 81 68<\/a><\/li><\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Offre d\u2019emploi : Collectrices -COFIDEM FINANCE ,<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[23],"tags":[1762],"villes":[136],"contrats":[236,234],"diplomes":[164,163,162],"louma_meta":{"emploi_title":"Offre d\u2019emploi : Collectrices -COFIDEM FINANCE ","emplois_employeur":9827,"emplois_date_publication":"2021-01-20","emplois_heure_publication":"","emplois_date_cloture":"2021-01-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"697 94 68 47\/670 87 81 68"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/9826"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=9826"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/9826\/revisions"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=9826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=9826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=9826"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=9826"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=9826"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=9826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}