{"id":9803,"date":"2021-01-19T12:19:50","date_gmt":"2021-01-19T11:19:50","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=9803"},"modified":"2021-01-19T12:19:54","modified_gmt":"2021-01-19T11:19:54","slug":"opportunites-de-carriere-programme-policy-associate-vam-data-analyst-g7-_-yaounde-135482","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/opportunites-de-carriere-programme-policy-associate-vam-data-analyst-g7-_-yaounde-135482\/","title":{"rendered":"Opportunit\u00e9s de carri\u00e8re : Programme Policy Associate (VAM Data Analyst) &#8211; G7 _ Yaound\u00e9 (135482)"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Opportunit\u00e9s de carri\u00e8re&nbsp;: Programme Policy Associate (VAM Data Analyst) &#8211; G7 _ Yaound\u00e9 (135482)<\/h1>\n\n\n\n<p>Identifiant de demande de recrutement&nbsp;<strong>135482<\/strong>&nbsp;&#8211;&nbsp;Publi\u00e9&nbsp;<strong>18\/01\/2021<\/strong>&nbsp;&#8211;&nbsp;<strong>Fixed Term<\/strong>&nbsp;&#8211;&nbsp;<strong>Africa, Western<\/strong>&nbsp;&#8211;&nbsp;<strong>Cameroon<\/strong>&nbsp;&#8211;&nbsp;<strong>Yaounde<\/strong>&nbsp;&#8211;&nbsp;Langue de travail (2)&nbsp;&#8211;&nbsp;<strong>PROGRAMME &amp; POLICY<\/strong><a href=\"void(0)\">\ue099 &nbsp;Aper\u00e7u avant impression du descriptif de poste<\/a>Postuler&nbsp;Enregistrer le poste&nbsp;Communiquer le poste \u00e0 un ami par e-mail&nbsp;Revenir \u00e0 la liste<\/p>\n\n\n\n<p>Intitul\u00e9 du poste&nbsp;:&nbsp;<strong>&nbsp;Programme Policy Associate (VAM Data Analyst)<\/strong><\/p>\n\n\n\n<p>Grade&nbsp;:<strong>&nbsp;G-7 (Contrat \u00e0 Dur\u00e9e D\u00e9termin\u00e9e &#8211; renouvelable)<\/strong><\/p>\n\n\n\n<p>Nombre de poste&nbsp;:&nbsp;<strong>01<\/strong><\/p>\n\n\n\n<p>Unit\u00e9\/ Division&nbsp;:&nbsp;<strong>VAM\/M&amp;E<\/strong><\/p>\n\n\n\n<p>Dur\u00e9e du contrat&nbsp;:&nbsp;<strong>12 mois<\/strong><\/p>\n\n\n\n<p>Lieu d\u2019affectation&nbsp;:&nbsp;<strong>Yaound\u00e9<\/strong><\/p>\n\n\n\n<p><strong>About WFP<\/strong><\/p>\n\n\n\n<p>Le Programme Alimentaire Mondial des Nations Unies (PAM) est la plus grande agence humanitaire qui lutte contre la faim dans le monde.<\/p>\n\n\n\n<p>La mission du PAM est d&rsquo;aider le monde \u00e0 atteindre l\u2019objectif Faim Z\u00e9ro d\u2019ici 2030.<\/p>\n\n\n\n<p>Chaque jour, le PAM travaille pour s&rsquo;assurer que les populations les plus vuln\u00e9rables, en particulier les femmes et les enfants, puissent avoir acc\u00e8s aux aliments nutritifs dont ils ont besoin pour mener une vie productive et saine<em>.<\/em><\/p>\n\n\n\n<p><strong>Contexte Organisationnel<\/strong><\/p>\n\n\n\n<p><em>Au Cameroun, le Plan Strat\u00e9gique de Pays du PAM [CSP] (2018 \u2013 2021) s&rsquo;efforce de garantir que les populations vuln\u00e9rables et en situation d&rsquo;ins\u00e9curit\u00e9 alimentaire cibl\u00e9es b\u00e9n\u00e9ficient de syst\u00e8mes alimentaires plus durables. Lesdits syst\u00e8mes devront \u00eatre aussi inclusifs et d&rsquo;une r\u00e9silience accrue aux chocs pour r\u00e9pondre \u00e0 leurs besoins alimentaires et nutritionnels. En ligne avec ce plan strat\u00e9gique, le PAM concevra et mettra en \u0153uvre des interventions pour relever les d\u00e9fis de la s\u00e9curit\u00e9 alimentaire et nutritionnelle, de la production \u00e0 la consommation.<\/em><\/p>\n\n\n\n<p><em>Conform\u00e9ment au CSP, le PAM appliquera ses vastes avantages comparatifs, notamment ses exp\u00e9riences en mati\u00e8re de fourniture d&rsquo;une aide alimentaire \u00e0 des centaines de milliers de personnes parmi les plus vuln\u00e9rables. pour: a) renforcer les syst\u00e8mes et capacit\u00e9s nationaux pour assurer la s\u00e9curit\u00e9 alimentaire et nutritionnelle; b) contribuer \u00e0 une plus grande efficacit\u00e9 des interventions de r\u00e9ponse aux crises; c) garantir l&rsquo;acc\u00e8s \u00e0 des aliments nutritifs plut\u00f4t qu&rsquo;\u00e0 l&rsquo;approvisionnement tout en renfor\u00e7ant les capacit\u00e9s et les syst\u00e8mes nationaux de protection sociale, de pr\u00e9paration et d&rsquo;intervention d&rsquo;urgence et de programmes et services dirig\u00e9s par le gouvernement; et d) accro\u00eetre la r\u00e9silience en se concentrant sur les syst\u00e8mes alimentaires plut\u00f4t que sur l&rsquo;acc\u00e8s \u00e0 la nourriture, gr\u00e2ce au d\u00e9veloppement de solutions int\u00e9gr\u00e9es pouvant \u00eatre mises \u00e0 l&rsquo;\u00e9chelle par le gouvernement et le secteur priv\u00e9.<\/em><\/p>\n\n\n\n<p><strong>Qu\u2019allez-vous faire \u00e0 ce poste&nbsp;?<\/strong><\/p>\n\n\n\n<p>Vous appuierez qualit\u00e9 des donn\u00e9es et des analyses de l\u2019Unit\u00e9 VAM du PAM Cameroun, un analyste est requis. Ceci permettra \u00e0 l\u2019unit\u00e9 d\u2019augmenter le rendement en termes de rapports sur la s\u00e9curit\u00e9 alimentaire et la nutrition. Vous ferez aussi le lien avec les sous bureaux afin de renforcer leurs capacit\u00e9s. Vous assurerez aussi du respect des plus hauts standards du PAM en mati\u00e8re de gestion des bases de donn\u00e9es et de collecte, d\u2019analyse et de pr\u00e9sentation des donn\u00e9es et r\u00e9sultats sur la s\u00e9curit\u00e9 alimentaire et la nutrition.<\/p>\n\n\n\n<p><strong>Pourquoi travailler avec nous?&nbsp;<\/strong>&nbsp;<\/p>\n\n\n\n<ul><li>Le PAM fournit une aide alimentaire \u00e0 plus de 86 millions de personnes dans 83 pays, dont le Cameroun. Votre travail aura un impact positif sur la vie des personnes les plus vuln\u00e9rables du monde.<\/li><li>Vous rejoindrez une \u00e9quipe diversifi\u00e9e de professionnels et aurez l&rsquo;occasion d&rsquo;\u00e9changer vos exp\u00e9riences avec vos coll\u00e8gues et d&rsquo;apprendre continuellement les uns des autres.<\/li><li>Le PAM investit dans la formation et le d\u00e9veloppement de ses employ\u00e9s gr\u00e2ce \u00e0 une gamme de programmes de formation, d&rsquo;accr\u00e9ditation, de mentorat et d&rsquo;autres programmes ainsi que des possibilit\u00e9s de mobilit\u00e9 internationale.<\/li><li>Notre \u00e9quipe se d\u00e9veloppe \u00e0 l&rsquo;\u00e9chelle nationale et internationale et le moment choisi pour nous rejoindre ne peut \u00eatre meilleur !<\/li><\/ul>\n\n\n\n<p><strong><em>Cliquez sur le lien ci-apr\u00e8s pour regarder la vid\u00e9o et en apprendre plus sur nous !!&nbsp;<\/em><\/strong>:&nbsp;<a href=\"https:\/\/www.youtube.com\/watch?v=RnaxfnNKdsM\">https:\/\/www.youtube.com\/watch?v=RnaxfnNKdsM<\/a><\/p>\n\n\n\n<p><strong>Responsabilit\u00e9s (non-exhaustives):<\/strong><\/p>\n\n\n\n<p>Plac\u00e9 sous la supervision directe du VAM Officer, vous aurez pour principales responsabilit\u00e9s :<\/p>\n\n\n\n<ul><li>Participer au d\u00e9veloppement des m\u00e9thodologies des \u00e9tudes et de suivi de la s\u00e9curit\u00e9 alimentaire pour permettre \u00e0 la direction du PAM et aux responsables des projets de prendre des d\u00e9cisions en mati\u00e8re d\u2019identification des facteurs conjoncturels et structurels affectant la s\u00e9curit\u00e9 alimentaire et son \u00e9volution dans le temps et dans l\u2019espace ;<\/li><li>Participer \u00e0 la coordination technique des enqu\u00eates d\u2019\u00e9valuation pour toutes les activit\u00e9s du programme, \u00e9chantillonnage, collecte et analyse statistique des donn\u00e9es puis \u00e0 la r\u00e9daction de rapports en assurer un suivi r\u00e9gulier, par le biais d\u2019un syst\u00e8me et d\u2019un r\u00e9seau de collecte de donn\u00e9es et la mise \u00e0 jour sur la s\u00e9curit\u00e9 alimentaire et des prix des denr\u00e9es alimentaires servant \u00e0 l\u2019analyse et \u00e0 la prise des d\u00e9cisions&nbsp;;<\/li><li>Produire des bulletins d\u2019information ainsi que des rapports p\u00e9riodiques sur l\u2019analyse de la vuln\u00e9rabilit\u00e9 \u00e0 l\u2019ins\u00e9curit\u00e9 alimentaire et de l\u2019\u00e9volution des tendances dans le temps afin d\u2019orienter le processus de planification et de programmation des interventions d\u2019assistance alimentaire du PAM et de ses partenaires ;<\/li><li>Pr\u00e9parer les TDRs et participer \u00e0 la conception des questionnaires d\u2019enqu\u00eates, la formation des enqu\u00eateurs, harmoniser et codifier les formulaires d&rsquo;entr\u00e9e de donn\u00e9es;<\/li><li>D\u00e9velopper et mettre \u00e0 jour sur ODK, ONA, etc. et les autres plateformes les formulaires pour faciliter la collecte des donn\u00e9es sur Smartphone ;<\/li><li>Mettre r\u00e9guli\u00e8rement \u00e0 jour les bases de donn\u00e9es du PAM \u00e0 travers la cr\u00e9ation et la mise \u00e0 jour de formulaires et de tableaux de saisie bas\u00e9s sur les outils existants \u00e0 adapter et am\u00e9liorer selon les besoins du Programme et en conformit\u00e9 avec les standards IT du PAM ;<\/li><li>Apporter un appui technique aux bureaux de terrain, et un appui dans le renforcement des capacit\u00e9s en analyse de la s\u00e9curit\u00e9 alimentaire et de la vuln\u00e9rabilit\u00e9, sur l\u2019utilisation des outils standardis\u00e9s de collecte des donn\u00e9es ;<\/li><li>&nbsp;Participer \u00e0 la formation des staffs du PAM et ses partenaires dans l\u2019exploitation et la visualisation des donn\u00e9es avec les logiciels sp\u00e9cialis\u00e9s (SPSS, STATA, R, ArcGIS, Tableau, etc.), dans l&rsquo;analyse de la s\u00e9curit\u00e9 alimentaire et le suivi des march\u00e9s ;<\/li><li>Appuyer l\u2019\u00e9quipe du bureau pays dans la mise en place d\u2019un syst\u00e8me de mise \u00e0 jour automatique \u00e0 travers des tableaux de bord interactifs pour assurer un suivi en temps r\u00e9el des indicateurs cl\u00e9s de la s\u00e9curit\u00e9 alimentaire et nutritionnelle, et du suivi des projets&nbsp;;<\/li><li>&nbsp;Appuyer la r\u00e9alisation de cartes des interventions du PAM et des donn\u00e9es des enqu\u00eates r\u00e9alis\u00e9es ;<\/li><li>Am\u00e9liorer les capacit\u00e9s de gestion et d\u2019analyse des donn\u00e9es des staffs du PAM au niveau du bureau pays, des sou-bureaux et de leurs partenaires ;<\/li><li>Promouvoir l\u2019utilisation des nouvelles technologies de l&rsquo;information et de la communication pour la collecte des donn\u00e9es d\u2019enqu\u00eate aupr\u00e8s du PAM et de ses partenaires par le renforcement des capacit\u00e9s sur le d\u00e9veloppement et l\u2019utilisation et l\u2019analyse des donn\u00e9es ;<\/li><li>Effectuer toute autre t\u00e2che requise selon les besoins de l\u2019unit\u00e9.<\/li><\/ul>\n\n\n\n<p><strong>Qualifications et Exigences cl\u00e9s<\/strong><\/p>\n\n\n\n<p><strong>Formation<\/strong>&nbsp;: Un dipl\u00f4me universitaire de niveau Master (Bac+4) en statistique, sciences \u00e9conomiques et de gestion, suivi-\u00e9valuation, sciences sociales, \u00e9tudes du d\u00e9veloppement, ou similaire est n\u00e9cessaire pour le poste.<\/p>\n\n\n\n<p><strong>Exp\u00e9rience<\/strong>&nbsp;: Au moins 4 ans d&rsquo;exp\u00e9rience professionnelle en analyse statistique, en \u00e9conom\u00e9trie, cartographie et\/ou gestion des bases de donn\u00e9es avec une agence des Nations Unies ou dans une structure reconnue pour la qualit\u00e9 de ses analyses statistiques ; Une exp\u00e9rience ou une formation dans les services sociaux, la s\u00e9curit\u00e9 alimentaire et la nutrition, la finance ou un autre domaine connexe serait un plus.<\/p>\n\n\n\n<p><strong>Comp\u00e9tences&nbsp;:<\/strong><\/p>\n\n\n\n<ul><li>Bonne connaissance du secteur humanitaire et en mod\u00e9lisation statistiques ;<\/li><li>Bonnes capacit\u00e9s d&rsquo;analyse quantitative et qualitative ;<\/li><li>Excellentes capacit\u00e9s d&rsquo;analyse, de communication et de r\u00e9daction ;<\/li><li>Souci du d\u00e9tail, efficace et capable de respecter les d\u00e9lais ;<\/li><li>\u00catre capable de s\u00e9journer en milieu rural et de travailler en milieux difficiles&nbsp;;<\/li><li>\u00catre capable de travailler en \u00e9quipe, de fa\u00e7on autonome et sous pression dans les d\u00e9lais courts ;<\/li><li>Excellentes comp\u00e9tences en informatique, MS Office y compris le traitement de texte, Outlook, les feuilles de calcul et autres progiciels.<\/li><li>Excellente maitrise des logiciels de cartographie (ArcGIS, QGIS, etc.).<\/li><li>Connaissance des logiciels statistiques (SPSS, Stata et\/ou R) et de visualisation comme Tableau est un atout.<\/li><\/ul>\n\n\n\n<p><strong>Langues<\/strong>&nbsp;: Ma\u00eetrise du fran\u00e7ais ou de l\u2019anglais et une connaissance pratique de la seconde langue.&nbsp;<\/p>\n\n\n\n<p><strong>Date limite de d\u00e9p\u00f4t des dossiers&nbsp;<\/strong><\/p>\n\n\n\n<p>Date : 01er F\u00e9vrier&nbsp;2021 \u00e0 23h59.<\/p>\n\n\n\n<p><strong>Ce poste est ouvert uniquement aux candidat (e) s de nationalit\u00e9 camerounaise.<\/strong><\/p>\n\n\n\n<p><strong>Conditions G\u00e9n\u00e9rales<\/strong><\/p>\n\n\n\n<p><strong><em>Le PAM s&rsquo;est engag\u00e9 \u00e0 promouvoir un environnement de travail inclusif dans lequel la diversit\u00e9 est valoris\u00e9e et o\u00f9 aucune forme de discrimination n&rsquo;est tol\u00e9r\u00e9e. Nous promouvons le leadership des femmes au sein de notre organisation et visons \u00e0 atteindre la parit\u00e9 dans nos \u00e9quipes en Afrique de l&rsquo;Ouest et du Centre.<\/em><\/strong><\/p>\n\n\n\n<p><strong><em><u>Les candidatures f\u00e9minines qualifi\u00e9es sont donc particuli\u00e8rement encourag\u00e9es<\/u><\/em><\/strong><strong><em>.<\/em><\/strong><\/p>\n\n\n\n<p><em>Le PAM n&rsquo;a aucune tol\u00e9rance \u00e0 l&rsquo;\u00e9gard de la discrimination et ne fait aucune discrimination fond\u00e9e sur le statut VIH \/ SIDA.<\/em><\/p>\n\n\n\n<p><em>Aucune nomination dans le cadre de tout type de contrat ne sera propos\u00e9e aux membres du Comit\u00e9 consultatif des Nations Unies pour les questions administratives et budg\u00e9taires (CCQAB), de la Commission de la fonction publique internationale (CFPI), du Comit\u00e9 des finances de la FAO, du Commissaire aux comptes du PAM, du Comit\u00e9 d&rsquo;audit du PAM, du Corps commun d&rsquo;inspection (CCI) et d&rsquo;autres organes similaires au sein du syst\u00e8me des Nations Unies ayant des responsabilit\u00e9s de supervision du PAM, tant pendant leur service que dans les trois ans suivant la fin de leur contrat<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Opportunit\u00e9s de carri\u00e8re : Programme Policy Associate (VAM Data Analyst) &#8211; G7 _ Yaound\u00e9 (135482)<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[436],"tags":[],"villes":[136],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"Opportunit\u00e9s de carri\u00e8re : Programme Policy Associate (VAM Data Analyst) - G7 _ Yaound\u00e9 (135482)","emplois_employeur":2947,"emplois_date_publication":"2021-01-19","emplois_heure_publication":"","emplois_date_cloture":"2021-01-05","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/career012.successfactors.eu\/career?career%5fns=job%5flisting&company=C0000168410P&navBarLevel=JOB%5fSEARCH&rcm%5fsite%5flocale=fr%5fFR&career_job_req_id=135482&selected_lang=en_GB&jobAlertController_jobAlertId=&jobAlertController_jobAlertName=&_s.crb=5YV4lDYhaY00n8uKRYW2KZfdJQnQ1wp295Va8MCbBPw%3d"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/9803"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=9803"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/9803\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2948"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=9803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=9803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=9803"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=9803"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=9803"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=9803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}