{"id":9736,"date":"2021-01-18T11:19:00","date_gmt":"2021-01-18T10:19:00","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=9736"},"modified":"2021-01-18T11:19:07","modified_gmt":"2021-01-18T10:19:07","slug":"webmaster-senior","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/webmaster-senior\/","title":{"rendered":"Webmaster Senior"},"content":{"rendered":"\n<p>RECRUTEMENT Webmaster Senior &#8211; Lisez bien toute la note avant de postuler je vous prie.<\/p>\n\n\n\n<p>Dans le cadre du d\u00e9veloppement de ses activit\u00e9s, Optim.Net Agency est \u00e0 la recherche d&rsquo;un Webmaster Senior. Nous cherchons une personne exp\u00e9riment\u00e9e qui a le go\u00fbt du challenge et qui sait faire preuve de flexibilit\u00e9.<\/p>\n\n\n\n<p>Les t\u00e2ches \u00e0 r\u00e9aliser seront donc:<\/p>\n\n\n\n<ul><li>Cr\u00e9ation &amp; h\u00e9bergement de sites web<\/li><li>Int\u00e9grations de moyens de paiements locaux et internationaux<\/li><li>Maintenance pr\u00e9ventive de sites (SSL, s\u00e9curit\u00e9, etc.)<\/li><li>Maintenance corrective de sites (bugs ponctuels)<\/li><li>Optimiser l&rsquo;UX pour l&rsquo;am\u00e9lioration des taux de conversion<\/li><li>Bonne ma\u00eetrise des langages (CSS, Javascipt, xHTML, etc.)<\/li><li>Gestion des noms de domaines et adresses mail pro<\/li><li>Etc.<\/li><\/ul>\n\n\n\n<p>Pr\u00e9requis obligatoires<\/p>\n\n\n\n<ul><li>Avoir un minimum de 3 ans d&rsquo;exp\u00e9rience dans le domaine<\/li><li>Habiter la ville de Douala<\/li><\/ul>\n\n\n\n<p>Comment postuler ?<\/p>\n\n\n\n<ul><li>Pr\u00e9parer votre CV et lettre de motivation<\/li><li>Pr\u00e9parer les r\u00e9f\u00e9rences des travaux d\u00e9j\u00e0 r\u00e9alis\u00e9s<\/li><li>Envoyez l&rsquo;ensemble \u00e0 recrutementoptimnet@gmail.com<\/li><\/ul>\n\n\n\n<p>Infoline (Whatsapp): 6 82 96 04 59<\/p>\n\n\n\n<p>Date limite : 20 Janvier 2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre du d\u00e9veloppement de ses activit\u00e9s, Optim.Net Agency est \u00e0 la recherche d&rsquo;un Webmaster Senior. Nous cherchons une personne exp\u00e9riment\u00e9e qui a le go\u00fbt du challenge et qui sait faire preuve de flexibilit\u00e9.<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[22],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Webmaster Senior ","emplois_employeur":3046,"emplois_date_publication":"2021-01-14","emplois_heure_publication":"","emplois_date_cloture":"2021-01-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"Envoyez l'ensemble \u00e0 recrutementoptimnet@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/9736"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=9736"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/9736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=9736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=9736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=9736"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=9736"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=9736"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=9736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}