{"id":9706,"date":"2021-01-16T12:25:30","date_gmt":"2021-01-16T11:25:30","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=9706"},"modified":"2021-01-16T12:25:32","modified_gmt":"2021-01-16T11:25:32","slug":"gestionnaire-de-site-cible-emploi","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/gestionnaire-de-site-cible-emploi\/","title":{"rendered":"Gestionnaire de site &#8211; Cible Emploi"},"content":{"rendered":"\n<p><strong>R\u00e9f\u00e9rence<\/strong>&nbsp;: GS-RH-002-01-21 _ Type de contrat : CDI _M\u00e9tier\/sp\u00e9cialit\u00e9 : Gestion<\/p>\n\n\n\n<p>Localisation : NKONGSAMBA ; Publication : 12-01-21<\/p>\n\n\n\n<p><strong>NOTRE CLIENT<\/strong><\/p>\n\n\n\n<p>Entreprise sp\u00e9cialis\u00e9e dans l\u2019agriculture et le commerce international au Cameroun&nbsp; &nbsp; &nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>ACTIVITES DU POSTE<\/strong>&nbsp; &nbsp;<\/h2>\n\n\n\n<p><strong>A<\/strong><em><strong>dministration et supervision des \u00e9quipes<\/strong><\/em><\/p>\n\n\n\n<p>Participer au recrutement et \u00e0 l\u2019int\u00e9gration du personnel<\/p>\n\n\n\n<p>R\u00e9diger les contrats de travail&nbsp;<\/p>\n\n\n\n<p>Organiser et superviser le travail des \u00e9quipes<\/p>\n\n\n\n<p>Mettre en place et suivre les fiches de pointage du personnel<\/p>\n\n\n\n<p>Assurer la paie<\/p>\n\n\n\n<p>Effectuer les d\u00e9clarations de bail<\/p>\n\n\n\n<p>Veiller \u00e0 la bonne tenue des dossiers du personnel du site (immatriculation CNPS, dossier m\u00e9dical\u2026)<\/p>\n\n\n\n<p>G\u00e9rer le budget du site de production<\/p>\n\n\n\n<p>Contr\u00f4ler les factures et effectuer les enregistrements comptables<\/p>\n\n\n\n<p>Effectuer un reporting r\u00e9gulier aupr\u00e8s de la hi\u00e9rarchie<\/p>\n\n\n\n<p><em><strong>Gestion des activit\u00e9s du site<\/strong><\/em><\/p>\n\n\n\n<p>Contr\u00f4ler le mat\u00e9riel du site<\/p>\n\n\n\n<p>G\u00e9rer les flux entrants et sortant<\/p>\n\n\n\n<p>Effectuer les inventaires permanents de stocks<\/p>\n\n\n\n<p>Coordonner et contr\u00f4ler les travaux&nbsp;<\/p>\n\n\n\n<p>Veiller au respect des mesures d\u2019hygi\u00e8ne et de s\u00e9curit\u00e9&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>PROFIL DE POSTE :<\/strong><\/h2>\n\n\n\n<p>Minimum BAC+3 en agronomie et \/ou en science de gestion<\/p>\n\n\n\n<p>Minimum 03 ans d\u2019exp\u00e9rience \u00e0 un poste similaire<\/p>\n\n\n\n<p>Exp\u00e9rience dans l\u2019activit\u00e9 agricole serait un atout<\/p>\n\n\n\n<p>Pratique du droit social et du travail<\/p>\n\n\n\n<p>Pratique de la gestion des stocks et de la logistique<\/p>\n\n\n\n<p>Bonnes bases de la comptabilit\u00e9 analytique&nbsp;<\/p>\n\n\n\n<p>Pratique de la paie<\/p>\n\n\n\n<p>Maitrise du pack office<\/p>\n\n\n\n<p>Aptitude \u00e0 la conduite des v\u00e9hicules automobiles et motocyclettes<\/p>\n\n\n\n<p>Comp\u00e9tences comportementales : Proactivit\u00e9, leadership et management, discr\u00e9tion et confidentialit\u00e9, rigueur et int\u00e9grit\u00e9, sens de l\u2019organisation, sens du dialogue, Gestion du stress<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>AVANTAGES DU POSTE :&nbsp;&nbsp;<\/strong><\/h2>\n\n\n\n<p>Logement,&nbsp;<\/p>\n\n\n\n<p>V\u00e9hicule de fonction<\/p>\n\n\n\n<p>Bien vouloir envoyer votre curriculum vitae (CV) d\u00e9taill\u00e9 via le lien suivant :&nbsp;<strong>www.emplois.groupe-cible.com&nbsp;<\/strong>&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>DATE LIMITE :&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;18 Janvier 2021 \u00e0 16 H :00&nbsp;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entreprise sp\u00e9cialis\u00e9e dans l\u2019agriculture et le commerce international au Cameroun recrute un Gestionnaire de site<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","categories":[21,71],"tags":[],"villes":[147],"contrats":[234,148],"diplomes":[212,159],"louma_meta":{"emploi_title":"Gestionnaire de site","emplois_employeur":2630,"emplois_date_publication":"2021-01-16","emplois_heure_publication":"","emplois_date_cloture":"2021-01-19","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"www.emplois.groupe-cible.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/9706"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=9706"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/9706\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2631"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=9706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=9706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=9706"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=9706"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=9706"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=9706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}