{"id":9463,"date":"2020-12-31T10:09:41","date_gmt":"2020-12-31T09:09:41","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=9463"},"modified":"2020-12-31T10:09:43","modified_gmt":"2020-12-31T09:09:43","slug":"offre-demploi-assistante-commerciale","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/offre-demploi-assistante-commerciale\/","title":{"rendered":"Offre d\u2019emploi : Assistante Commerciale"},"content":{"rendered":"\n<p>Nous recherchons une assistante en vente dans notre boutique de decoration, qui a les bases dans la decoration!!! et qui est surtout une passionn\u00e9e!!!.<br>Le travail: 3jrs\/semaine<br>Horaire: 9h30-19h30<br>Salaire: 45000f, plus bonus si objectif atteind.<br>Lieux: Yaounde-nkondengui.<br>Envoyez vos CV et lettres de motivations \u00e0 decobyfifo@gmail.com<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Offfe d\u2019emploi nous recherchons une assistante commerciale <\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[251],"tags":[1685],"villes":[135,136],"contrats":[234],"diplomes":[163,162],"louma_meta":{"emploi_title":"Offre d\u2019emploi :Une Assistante Commerciale  ","emplois_employeur":3046,"emplois_date_publication":"2020-12-31","emplois_heure_publication":"","emplois_date_cloture":"2021-01-14","emplois_heure_cloture":"","emplois_experience_min":"2","emplois_experience_max":"3","emploi_email":"decobyfifo@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/9463"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=9463"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/9463\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3031"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=9463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=9463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=9463"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=9463"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=9463"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=9463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}