{"id":9371,"date":"2020-12-22T11:46:55","date_gmt":"2020-12-22T10:46:55","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=9371"},"modified":"2020-12-22T11:46:59","modified_gmt":"2020-12-22T10:46:59","slug":"chef-de-projet-protection-cameroun","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/chef-de-projet-protection-cameroun\/","title":{"rendered":"Chef de projet protection\u2013 Cameroun"},"content":{"rendered":"\n<p>Chef de projet protection\u2013 Cameroun<\/p>\n\n\n\n<p>Organization<\/p>\n\n\n\n<p>INTERSOS<\/p>\n\n\n\n<p>Posted18 Dec 2020Closing date31 Dec 2020INTERSOS est une Organisation Humanitaire Non Gouvernementale, \u00e0 but non lucratif, qui a l\u2019objectif d\u2019assister les victimes de d\u00e9sastres naturelles et de conflits arm\u00e9s. INTERSOS base son action sur les valeurs de la solidarit\u00e9, de la justice, de la dignit\u00e9 humaine, de l\u2019\u00e9galit\u00e9 des droits et des opportunit\u00e9s pour tous les peuples, du respect des diversit\u00e9s, de la cohabitation, de l\u2019attention aux groups sociales les plus vuln\u00e9rables.Termes de r\u00e9f\u00e9renceIntitul\u00e9 du poste: Chef de projet protectionCode: SR-48-1677Pays: CamerounLieu d\u2019affectation: Maroua &#8211; Extr\u00eame Nord du Cameroun, avec d\u00e9placements fr\u00e9quents dans la base de Kouss\u00e9ri et les sous bases de Mora et MokoloDate de prise de fonction: 03\/01\/2021Dur\u00e9e du contrat: 12 mois<\/p>\n\n\n\n<p>Sous la supervision de: Chef de missionSupervision directe de: Plus de 30 staffs<\/p>\n\n\n\n<p>Personnes \u00e0 charge: Non-family Duty Station \/non-accompaniedContexte g\u00e9n\u00e9ral du projetLa situation humanitaire \u00e0 l\u2019Extr\u00eame Nord du Cameroun reste assez pr\u00e9occupante. En effet, depuis 2014, la situation s\u00e9curitaire dans la r\u00e9gion de l&rsquo;extr\u00eame nord du Cameroun est rest\u00e9e instable et impr\u00e9visible compte tenu de la recrudescence des attaques de Boko Haram dans le Nord Est du Nig\u00e9ria mais aussi dans les d\u00e9partements de Logone et Chari, Mayo-Tsanaga, Mayo-Sava et plus particuli\u00e8rement dans la r\u00e9gion du lac Tchad au Cameroun. Cette situation a occasionn\u00e9 \u00e0 ce jour 321,886 PDI; 114, 496 R\u00e9fugi\u00e9s nig\u00e9riens ayant besoin d&rsquo;aide humanitaire.<\/p>\n\n\n\n<p>Dans ces d\u00e9partements, INTERSOS a lanc\u00e9 depuis 2015 des plusieurs projets de s\u00e9curit\u00e9 et de protection avec financements de OFDA, ECHO, AICS et UNHCR pour assurer le monitoring de protection et r\u00e9pondre aux besoins des survivantes de VBG et des Enfants Soldats (ES)\/Enfants Non-Accompagn\u00e9s (ENA).Le projet de protection financ\u00e9 par l\u2019UNHCR s\u2019articulera sur deux volets :<\/p>\n\n\n\n<p>Le monitoring de protection visant \u00e0 am\u00e9liorer la situation de protection des populations d\u00e9plac\u00e9es et demandeurs d\u2019asiles hors camp de Minawao et h\u00f4tes affect\u00e9es par les violences et le d\u00e9placement, \u00e0 la consolidation des structures de protection mises en place pour le suivi de la situation de protection dans les zones affect\u00e9es et dans les arrondissements des trois d\u00e9partements, \u00e0 l\u2019encadrement et au renforcement des structures communautaires sur des th\u00e9matiques li\u00e9es \u00e0 la protection et la collecte des donn\u00e9es sur les tendances de protection dans les zones d\u2019accueils, le r\u00e9f\u00e9rencement des cas de protection identifi\u00e9s vers les services de prise en charge juridique, psychosocial et m\u00e9dical pour la r\u00e9ponse appropri\u00e9e.<\/p>\n\n\n\n<p>Le Services Communautaires vise \u00e0 apporter une r\u00e9ponse de qualit\u00e9 aux personnes \u00e0 besoins sp\u00e9cifiques (PBS), refugi\u00e9s vivant dans le camp de Minawao, en assurant la gestion directe des cas de protection, en supportant les m\u00e9canismes de participation communautaire inclusive des diff\u00e9rentes couches sociales de la population r\u00e9fugi\u00e9e et en promouvant la coexistence pacifique au sein de la communaut\u00e9 r\u00e9fugi\u00e9e ainsi qu\u2019entre la population r\u00e9fugi\u00e9e et la communaut\u00e9 h\u00f4te.<\/p>\n\n\n\n<p>Objectif g\u00e9n\u00e9ral de la position<\/p>\n\n\n\n<p>Le Chef de Projet doit garantir la mise en \u0153uvre du projet et la r\u00e9alisation de l&rsquo;ensemble des activit\u00e9s pr\u00e9vues dans la zone d&rsquo;int\u00e9r\u00eat. Il est essentiel de pr\u00eater attention aux proc\u00e9dures de s\u00e9curit\u00e9 et la mise en place des normes de s\u00e9curit\u00e9 de INTERSOS et d\u2019analyser en permanence l&rsquo;impact de la pr\u00e9sence de Boko Haram sur la population et les activit\u00e9s. En raison de l&rsquo;extr\u00eame volatilit\u00e9 de la s\u00e9curit\u00e9 dans la zone couverte par le projet, le Chef de Projet doit assurer strictement l&rsquo;application des principes humanitaires lors de la distribution et d&rsquo;autres activit\u00e9s du projet, en particulier le principe du \u00abne pas nuire\u00bb. <\/p>\n\n\n\n<p>Par ailleurs, l&rsquo;un des objectifs du Chef de Projet concerne l\u2019identification de nouvelles opportunit\u00e9s pour la participation de INTERSOS dans la r\u00e9ponse humanitaire et de les communiquer au Chef de Mission.<\/p>\n\n\n\n<p> Il\/elle sera donc amen\u00e9 \u00e0 effectuer des \u00e9valuations et r\u00e9diger de nouvelles propositions d\u2019intervention.<\/p>\n\n\n\n<p>Principales responsabilit\u00e9s et t\u00e2ches<\/p>\n\n\n\n<p>G\u00e9rer directement le projet INTERSOS, au niveau logistique et financi\u00e8re en collaboration avec les responsables de chaque d\u00e9partement concern\u00e9;<\/p>\n\n\n\n<p>Assurer la planification des activit\u00e9s du projet dans la zone d\u2019intervention en \u00e9troite collaboration la Coordination de INTERSOS \u00e0 Yaound\u00e9;<\/p>\n\n\n\n<p>Assurer la gestion des ressources humaines, en supervisant le processus de recrutement et d\u2019installation du nouveau staff, en apportant un support technique \u00e0 l\u2019\u00e9quipe et un renforcement de capacit\u00e9s;<\/p>\n\n\n\n<p>Assurer la r\u00e9daction des rapports d\u2019activit\u00e9s narratifs et tout autre document de monitorage selon les \u00e9ch\u00e9ances donn\u00e9es et selon les exigences du bailleur;<\/p>\n\n\n\n<p>Assurer la r\u00e9daction des rapports hebdomadaires et mensuels (PAT) interne \u00e0 INTERSOS;<\/p>\n\n\n\n<p>Assurer la supervision r\u00e9guli\u00e8re des op\u00e9rations d\u2019achat et approvisionnement en conformit\u00e9 avec le plan de passation de march\u00e9 dans le respect des proc\u00e9dures du bailleur et de INTERSOS, en \u00e9troite collaboration avec le logisticien du projet;<\/p>\n\n\n\n<p>Superviser tous les aspects logistiques et organisationnels, veillant \u00e0 ce que toutes les structures pr\u00e9vues par le projet soient en place et efficaces;<\/p>\n\n\n\n<p>Veiller \u00e0 ce que tous les aspects \u00e9conomiques, mon\u00e9taires et administratifs sont pris en charge selon la norme des r\u00e8gles et INTERSOS;<\/p>\n\n\n\n<p>Superviser l&rsquo;expert agronome et autres sp\u00e9cialistes dans la conception et la mise en \u0153uvre du plan de formation visant \u00e0 renforcer la capacit\u00e9 du personnel et des partenaires INTERSOS<\/p>\n\n\n\n<p>Veiller \u00e0 ce que les principes humanitaires sont suivis et respect\u00e9s tout au long du programme;<\/p>\n\n\n\n<p>Assurer la participation active aux Groupes de travail <\/p>\n\n\n\n<p>Protection afin d&rsquo;\u00e9tablir des relations strat\u00e9giques avec les membres des groupes de travail, les autorit\u00e9s locales et les agences \/ organisations travaillant dans l&rsquo;Extr\u00eame-Nord;<\/p>\n\n\n\n<p>Assurer la documentation des m\u00e9thodologies de projet, les le\u00e7ons apprises, et de recueillir des \u00e9tudes de cas;<\/p>\n\n\n\n<p>Mise \u00e0 jour r\u00e9guli\u00e8res de la liste de contacts (autorit\u00e9s, soci\u00e9t\u00e9s civile, ONGs et b\u00e9n\u00e9ficiaires inclus) et participer activement \u00e0 son d\u00e9veloppement.<\/p>\n\n\n\n<p>Participer activement \u00e0 la r\u00e9alisation d\u2019\u00e9valuations et \u00e0 la conception de nouveaux projets afin de r\u00e9pondre aux besoins de la population touch\u00e9e par la crise;<\/p>\n\n\n\n<p>Effectuer d&rsquo;autres t\u00e2ches connexes tel que requis par le chef de mission;<\/p>\n\n\n\n<p>Profil requis<\/p>\n\n\n\n<p>EducationDipl\u00f4me universitaire sup\u00e9rieur en science de l\u2019\u00e9ducation et de la formation, en droit, science politique, Sciences sociales, Psychologie, Sciences humaines ou autre domaine pertinent.Exp\u00e9rience Professionnelle<\/p>\n\n\n\n<p>Au moins 2 ans d\u2019exp\u00e9rience \u00e0 l&rsquo;\u00e9tranger significative dans des postes similaires ou dans le secteur humanitaire;<\/p>\n\n\n\n<p>Exp\u00e9rience professionnelle significative dans le domaine de la Protection dans les situations d\u2019urgence;<\/p>\n\n\n\n<p>Exp\u00e9rience pr\u00e9c\u00e9dente dans la supervision des activit\u00e9s et gestion du projet li\u00e9es au domaine susmentionn\u00e9;<\/p>\n\n\n\n<p>Connaissance approfondie des lignes directrices et des standards sectoriels internationaux;<\/p>\n\n\n\n<p>Exp\u00e9rience de travail avec les r\u00e9fugi\u00e9es et IDPs;<\/p>\n\n\n\n<p>Exp\u00e9rience pr\u00e9c\u00e9dente au Cameroun est un atout;<\/p>\n\n\n\n<p>Exigences professionnellesSolide compr\u00e9hension du contexte d&rsquo;urgence humanitaire;<\/p>\n\n\n\n<p>Capacit\u00e9 de travail dans un contexte s\u00e9curitaire volatile;<\/p>\n\n\n\n<p>Comp\u00e9tences organisationnelles, y compris la gestion du temps, la capacit\u00e9 de respecter les d\u00e9lais, \u00eatre multit\u00e2che et savoir donner la priorit\u00e9 aux t\u00e2ches;<\/p>\n\n\n\n<p>Capacit\u00e9 \u00e0 travailler dans un d\u00e9lai serr\u00e9, avec peu de supervision et sous pression;<\/p>\n\n\n\n<p>Grande capacit\u00e9 de communication, \u00e9crite et orale, et \u00e0 entretenir des relations avec une exp\u00e9rience dans la gestion des \u00e9quipes de travail;<\/p>\n\n\n\n<p>Aptitude \u00e0 travailler en \u00e9quipe et de mani\u00e8re autonome;<\/p>\n\n\n\n<p>Connaissance des proc\u00e9dures et des lignes guides UNHCR (souhaitable);Langues Fran\u00e7ais courants (parl\u00e9, lu, \u00e9crit);<\/p>\n\n\n\n<p>Bonne connaissance de l\u2019anglais (souhaitable);<\/p>\n\n\n\n<p>Qualit\u00e9s requises<\/p>\n\n\n\n<p>Esprit d\u2019adaptation \u00e0 des conditions de vie simples, \u00e0 un climat chaud\/tr\u00e8s chaud et \u00e0 des contraints de s\u00e9curit\u00e9 (couvre-feu);<\/p>\n\n\n\n<p>Sens de l\u2019organisation, de la gestion et de la planification;<\/p>\n\n\n\n<p>Excellent sens relationnel, diplomatie et approche partenariale;<\/p>\n\n\n\n<p>Flexibilit\u00e9 et capacit\u00e9 de travail dans un contexte difficile, sous pression et dans un milieu souvent non confortable;<\/p>\n\n\n\n<p>Capacit\u00e9 de communication et de travail en \u00e9quipe et dans un contexte multiculturel;<\/p>\n\n\n\n<p>Aptitude \u00e0 travailler dans un environnement de s\u00e9curit\u00e9 tr\u00e8s volatile et dans des conditions de vie basique;<\/p>\n\n\n\n<p>Respect des valeurs\/mission INTERSOS;How to apply<\/p>\n\n\n\n<p>COMMENT POSTULER :Les candidats int\u00e9ress\u00e9s sont invit\u00e9s \u00e0 postuler en suivant le lien ci-dessous:https:\/\/www.intersos.org\/en\/work-with-us\/field\/#intersosorg-vacancies\/va&#8230;<\/p>\n\n\n\n<p>Veuillez noter que notre processus de candidature est compos\u00e9 de 3 \u00e9tapes tr\u00e8s rapides: s\u2019inscrire (incluant votre nom, mail, mot de passe, nationalit\u00e9 et adresse Skype), se connecter et postuler en joignant CV et lettre de motivation en version PDF. Avec cette plateforme les candidats pourront suivre l&rsquo;historique de leurs candidatures avec INTERSOS.<\/p>\n\n\n\n<p>Si vous rencontrez de graves difficult\u00e9s \u00e0 postuler via notre plateforme, vous pouvez envoyer un email \u00e0 recruitment@intersos.org joignant votre CV et votre lettre de motivation (les deux en version PDF) avec comme objet du message: \u00ab Platform issue \u2013 SR-48-1677 \u2013 Chef de projet protection \u00bb.<\/p>\n\n\n\n<p>Veuillez \u00e9galement mentionner le nom, le poste et les coordonn\u00e9es d&rsquo;au moins trois r\u00e9f\u00e9rences, y compris le responsable hi\u00e9rarchique lors de votre dernier emploi. Les membres de la famille sont \u00e0 exclure.Seulement les candidats s\u00e9lectionn\u00e9s pour le premier entretien seront contact\u00e9s.<\/p>\n\n\n\n<p>CountryCameroonCityMaroua &#8211; Extr\u00eame Nord du Cameroun, avec d\u00e9placements fr\u00e9quents dans la base de Kouss\u00e9ri et les sous bases de Mora et MokoloOrganization<\/p>\n\n\n\n<p>INTERSOSTypeJobCareer CategoryProgram\/Project ManagementYears of experience0-2 yearsThemeProtection and Human RightsShare<\/p>\n","protected":false},"excerpt":{"rendered":"<p>INTERSOS recrute actuellement au poste de Chef de projet de Protection<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[436],"tags":[1551],"villes":[141,136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Chef de projet protection\u2013 Cameroun","emplois_employeur":4116,"emplois_date_publication":"2020-12-22","emplois_heure_publication":"","emplois_date_cloture":"2020-12-31","emplois_heure_cloture":"","emplois_experience_min":"2","emplois_experience_max":"3","emploi_email":"dessous:https:\/\/www.intersos.org\/en\/work-with-us\/field\/#intersosorg-vacancies\/va..."},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/9371"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=9371"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/9371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4117"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=9371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=9371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=9371"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=9371"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=9371"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=9371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}