{"id":9119,"date":"2020-12-10T10:52:15","date_gmt":"2020-12-10T09:52:15","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=9119"},"modified":"2020-12-10T10:52:53","modified_gmt":"2020-12-10T09:52:53","slug":"human-resource-business-partner","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/human-resource-business-partner\/","title":{"rendered":"Human Resource Business Partner"},"content":{"rendered":"\n<p>Avis de recrutement: Human resource business Avis de recrutement: Human resource businessIntitul\u00e9 du poste: Human Resource BusinessPartner : (Cat 10)Job description<\/p>\n\n\n\n<p>Aligner en tant que partenaire strat\u00e9gique, les objectifs de l&rsquo;entreprise avec le personnel et la direction dans les unit\u00e9s d\u00e9sign\u00e9es.<\/p>\n\n\n\n<p>Servir de consultant en gestion des ressources humaines sur des questions connexes.<\/p>\n\n\n\n<p>Agir en tant que champion des employ\u00e9s et agent de changement tout en \u00e9valuant et anticipantles besoins li\u00e9s aux RH.<\/p>\n\n\n\n<p>Formuler<\/p>\n\n\n\n<p> des partenariats dans l&rsquo;ensemble de la fonction RH et offrir une valeur ajout\u00e9e \u00e0 la direction et le personnel qui refl\u00e8tent les objectifs de l&rsquo;activit\u00e9 de l&rsquo;organisation.<\/p>\n\n\n\n<p>Que Ferez vous ?<\/p>\n\n\n\n<p>Tenir des r\u00e9unions p\u00e9riodiques avec les services et les D\u00e9partements respectifs.<\/p>\n\n\n\n<p>Elaborer et analyser les donn\u00e9es des fonctions et d\u00e9gager les principales tendances avec suivies des recommandations appropri\u00e9es.<\/p>\n\n\n\n<p>G\u00e9rer et r\u00e9soudre les questions li\u00e9es aux relations avec les employ\u00e9s.<\/p>\n\n\n\n<p> Mener des enqu\u00eates internes efficaces chaque fois que n\u00e9cessaire<\/p>\n\n\n\n<p>Analyser sur une base mensuelle les donn\u00e9es li\u00e9es \u00e0 la main d\u2019\u0153uvre et \u00e0 la productivit\u00e9 du personnel<\/p>\n\n\n\n<p>Veiller \u00e0 la r\u00e9alisation des processus de Talent Management (identification des talents et \u00e9laboration des plans d\u2019actions), de performance management (Elaboration des IPA et PDP)<\/p>\n\n\n\n<p>Travailler conjointement avec les fonctions pour la mise en \u0153uvre des PIP (Performance Improvement Plan) et leur suivi pour le personnel concern\u00e9<\/p>\n\n\n\n<p>Elaborer chaque fois que n\u00e9cessaire de nouveaux organigrammes et proposer les ajustements n\u00e9cessaires en fonction de l\u2019\u00e9volution du business.<\/p>\n\n\n\n<p>S\u2019assurer que chaque poste de travail a un job description et l\u2019\u00e9laborer avec les sup\u00e9rieurs hi\u00e9rarchiques concern\u00e9s le cas \u00e9ch\u00e9ant.<\/p>\n\n\n\n<p>Veiller \u00e0 ce que chaque activit\u00e9 cl\u00e9 des ressources humaines soit couverte par une proc\u00e9dure appropri\u00e9e et \u00e0 jour.<\/p>\n\n\n\n<p>Susciter une adh\u00e9sion totale de la part des employ\u00e9s \u00e0 toutes les politiques et proc\u00e9dures de l\u2019entreprise.<\/p>\n\n\n\n<p>Faire des propositions de nature \u00e0 contribuer \u00e0 l\u2019\u00e9panouissement professionnel et au bien-\u00eatre des employ\u00e9s.<\/p>\n\n\n\n<p>Coordonner la mise \u00e0 jour et le respect des plannings de cong\u00e9 annuel du personnel.<\/p>\n\n\n\n<p>Coordonner la r\u00e9alisation des enqu\u00eates Groupes aupr\u00e8s des fonctions concern\u00e9es<\/p>\n\n\n\n<p>Conseiller les managers dans les relations avec leurs partenaires et veiller \u00e0\u0300 l\u2019application de la l\u00e9gislation sociale dans les domaines des conditions de travail, d\u2019hygi\u00e8ne et s\u00e9curit\u00e9\u0301.<\/p>\n\n\n\n<p>Accompagner l\u2019entreprise dans ses politiques de changement.<\/p>\n\n\n\n<p>Apporter un soutien aux managers dans la conduite des relations avec leurs \u00e9quipes pour expliquer et donner du sens aux d\u00e9cisions organisationnelles et strat\u00e9giques.<\/p>\n\n\n\n<p>Etre un relais pour le Talent &amp; Development Manager pour le suivi de la performance et du Talent management<\/p>\n\n\n\n<p>Quel sera votre apport ?<\/p>\n\n\n\n<p>Comp\u00e9tences : Minimum BAC+4 en Ressources Humaines ou disciplines assimil\u00e9es<\/p>\n\n\n\n<p>Exp\u00e9rience et qualifications : 3 ans d&rsquo;exp\u00e9rience dans le domaine, \u00e0 un poste d&rsquo;encadrement au sein d&rsquo;une entreprise agroalimentaire. <\/p>\n\n\n\n<p>Bon niveau de bilinguisme (Fran\u00e7ais et Anglais),<\/p>\n\n\n\n<p> Bonne ma\u00eetrise des syst\u00e8mes d&rsquo;informations (Microsoft Office\/progiciels RH),<\/p>\n\n\n\n<p> Bonne aptitudes de communication (orales \u00e9crites), cost &amp; result focus.Comment Postuler ?<\/p>\n\n\n\n<p>A quelle adresse nous faire parvenir vos CVs : Chococam.Recruit@tigerbrands.com. Les candidat(e)s int\u00e9ress\u00e9(e)s  devront postuler en mentionnant en objet l&rsquo;intitul\u00e9 du poste publi\u00e9 en t\u00e9l\u00e9chargeant leurs lettres de motivation et CVs sous format non \u00e9ditableDate de Cl\u00f4ture de r\u00e9ception des CVs: 23\/12\/2020<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avis de recrutement: Human resource business Avis de recrutement: Human resource businessIntitul\u00e9 du poste: Human Resource BusinessPartner : (Cat 10)Job description Aligner en tant que&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[26],"tags":[1632],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Human Resource BusinessPartner","emplois_employeur":5282,"emplois_date_publication":"2020-12-10","emplois_heure_publication":"","emplois_date_cloture":"2020-12-23","emplois_heure_cloture":"","emplois_experience_min":"2","emplois_experience_max":"3","emploi_email":"Chococam.Recruit@tigerbrands.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/9119"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=9119"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/9119\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/5283"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=9119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=9119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=9119"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=9119"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=9119"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=9119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}