{"id":8590,"date":"2020-11-18T03:21:53","date_gmt":"2020-11-18T02:21:53","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=8590"},"modified":"2020-11-18T03:21:53","modified_gmt":"2020-11-18T02:21:53","slug":"offre-demploi-distributeur-manager-afd","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/offre-demploi-distributeur-manager-afd\/","title":{"rendered":"Offre d&#8217;emploi : Distributeur Manager-AFD"},"content":{"rendered":"<p>AFRICA FOOD DISTRIBUTION SA recherche actuellement un (01) DISTRIBUTION MANAGER<\/p>\n<p>La R\u00e9daction 3 days ago ADMINISTRATION-SECR\u00c9TARIAT, CDI, Douala, Offres d&#8217;emplois<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>AFRICA FOOD DISTRIBUTION SA recherche actuellement pour son si\u00e8ge bas\u00e9 \u00e0 Douala, un (01) :<\/p>\n<p>&nbsp;<\/p>\n<p>DISTRIBUTION MANAGER<\/p>\n<p>&nbsp;<\/p>\n<p>Rattach\u00e9 (e) \u00e0 la Direction Commerciale, le Distribution Manager aura pour mission de :<\/p>\n<p>&nbsp;<\/p>\n<p>Veiller \u00e0 l\u2019atteinte des objectifs de vente et d\u2019encaissement ;<\/p>\n<p>Veiller \u00e0 la gestion et au d\u00e9veloppement des partenaires strat\u00e9giques ;<\/p>\n<p>Assurer la profitabilit\u00e9 des partenaires strat\u00e9giques et le recrutement des nouveaux partenaires ;<\/p>\n<p>Centraliser et traiter \u00e9galement toutes les plaintes et r\u00e9clamations de son portefeuille client ;<\/p>\n<p>Veiller au respect des proc\u00e9dures de ventes.<\/p>\n<p>ACTIVITES<\/p>\n<p>&nbsp;<\/p>\n<p>COMMERCIALES<\/p>\n<p>&nbsp;<\/p>\n<p>animer et f\u00e9d\u00e9rer les efforts de son \u00e9quipe pour r\u00e9aliser les objectifs de son territoire ;<\/p>\n<p>veiller \u00e0 la fixation des objectifs aux partenaires et assurer le suivi de leur r\u00e9alisation ;<\/p>\n<p>analyser les stocks des Partenaires et s\u2019assurer de disposer au moins 15 jours de stocks pour chacun des SKU ;<\/p>\n<p>produire hebdomadairement les plans d\u00e9taill\u00e9s par SKU de facturation et d\u2019encaissement et assurer leur r\u00e9alisation;<\/p>\n<p>mettre \u00e0 jour les diff\u00e9rents tableaux de bord de gestion et assurer le bon reporting de toutes les activit\u00e9s \u00e0 temps ;<\/p>\n<p>s\u2019assurer de fa\u00e7on journali\u00e8re du bon d\u00e9nouement de toutes les transactions commerciales de son territoire ;<\/p>\n<p>produire une analyse des tendances de ventes afin d\u2019anticiper sur les approvisionnements ;<\/p>\n<p>suivre les r\u00e9clamations clients et faire le reporting chaque semaine ;<\/p>\n<p>s\u2019assurer que tous ses partenaires gagnent des ristournes chaque fin de mois ;<\/p>\n<p>boucler les journ\u00e9es de Ventes ;<\/p>\n<p>COMPTABLES<\/p>\n<p>&nbsp;<\/p>\n<p>veiller \u00e0 une tenue r\u00e9glementaire des documents de gestion des stocks et de vente des partenaires strat\u00e9giques ;<\/p>\n<p>veiller \u00e0 une tenue extra-comptable des comptes clients ;<\/p>\n<p>veiller \u00e0 la collecte et transmission des bordereaux de versements et liasse commerciale ;<\/p>\n<p>suivre les cr\u00e9ances ;<\/p>\n<p>produire la situation du risk analysis PS chaque mois avec les actions \u00e0 entreprendre<\/p>\n<p>CONTROLES<\/p>\n<p>&nbsp;<\/p>\n<p>assurer le respect des proc\u00e9dures et la protection du patrimoine du territoire dont il a la charge ;<\/p>\n<p>s\u2019assurer du bon respect des proc\u00e9dures commerciales ;<\/p>\n<p>renforcer le dispositif de contr\u00f4le \u00e0 priori (conformit\u00e9 BL BC FACT. vs sp\u00e9cimen signature) ;<\/p>\n<p>assurer la gestion logistique et administrative ;<\/p>\n<p>assurer le suivi des livraisons des produits command\u00e9s.<\/p>\n<p>MANAGEMENT<\/p>\n<p>&nbsp;<\/p>\n<p>organiser et optimiser le temps de travail de son \u00e9quipe (\u00e9laboration ou contr\u00f4le des Plannings de son \u00e9quipe, r\u00e9partition des t\u00e2ches, adaptation en fonction de l\u2019affluence) ;<\/p>\n<p>organiser des r\u00e9unions d\u2019\u00e9quipes r\u00e9guli\u00e8res afin de redescendre l\u2019information de la direction ;<\/p>\n<p>veiller \u00e0 la mobilisation des \u00e9quipes en fonction de la strat\u00e9gie commerciale ;<\/p>\n<p>d\u00e9l\u00e9guer en fonction de l\u2019exp\u00e9rience de son personnel. ;<\/p>\n<p>\u00e9valuer les besoins en formation de son personnel.<\/p>\n<p>PROFIL<\/p>\n<p>&nbsp;<\/p>\n<p>Titulaire d\u2019un BAC + 4\/5 en Marketing \/ Commerce et ventes<\/p>\n<p>Avoir 8 ann\u00e9es d\u2019exp\u00e9rience et 04 ann\u00e9es dans un poste similaire ;<\/p>\n<p>Avoir une bonne connaissance des habitudes de l\u2019open market ;<\/p>\n<p>Avoir une bonne connaissance des techniques de management ;<\/p>\n<p>Avoir une Aisance \u00e0 manipuler les fonds ;<\/p>\n<p>Avoir un sens aigu du service et du contact ;<\/p>\n<p>Avoir une bonne connaissance du Pack Microsoft Office (Word, Excel, Power Point\u2026.)<\/p>\n<p>Etre Organis\u00e9, rigoureux, dynamique, m\u00e9thodique et motiv\u00e9 ;<\/p>\n<p>Dossier de candidature : CV, lettre de motivation<\/p>\n<p>&nbsp;<\/p>\n<p>Deadline : Vendredi 27 novembre 2020<\/p>\n<p>&nbsp;<\/p>\n<p>Envoyez votre dossier de candidature \u00e0 : recrutement@africafooddistribution.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Offre d&#8217;emploi au Cameroun : Africa Food Distribution recrute actuellement au poste de Distribution Manager pour sa repr\u00e9sentation \u00e0 Douala.<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21,251],"tags":[1522],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Offre d'emploi : Distributeur Manager-AFD","emplois_employeur":7626,"emplois_date_publication":"2020-11-18","emplois_heure_publication":"","emplois_date_cloture":"2020-11-27","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"recrutement@africafooddistribution.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/8590"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=8590"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/8590\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/7627"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=8590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=8590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=8590"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=8590"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=8590"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=8590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}