{"id":8528,"date":"2020-11-16T04:53:07","date_gmt":"2020-11-16T03:53:07","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=8528"},"modified":"2020-11-16T04:53:07","modified_gmt":"2020-11-16T03:53:07","slug":"un-formateur-technicien-de-production-en-industrie-cosmetique-h-f","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/un-formateur-technicien-de-production-en-industrie-cosmetique-h-f\/","title":{"rendered":"Un Formateur \/ Technicien de Production en Industrie Cosm\u00e9tique H\/F"},"content":{"rendered":"<p>OFFRE D\u2019EMPOI<\/p>\n<p>Nous recrutons,<br \/>\nUn Formateur \/ Technicien de Production en<br \/>\nIndustrie Cosm\u00e9tique H\/F<br \/>\nVitale Plus Cosmetics est une entreprise camerounaise, engag\u00e9e dans la production de<br \/>\nproduits cosm\u00e9tiques et la formation dans les m\u00e9tiers de la cosm\u00e9tique. Dans le souci<br \/>\nd\u2019\u00e9tendre notre \u00e9quipe, nous sommes \u00e0 la recherche d\u2019un chimiste et d\u2019un biochimiste.<\/p>\n<p>Pr\u00e9sentation des missions :<br \/>\n\uf0a7 Faire appliquer les r\u00e8gles en mati\u00e8re de s\u00e9curit\u00e9, d\u2019hygi\u00e8ne, de qualit\u00e9 et<br \/>\nd\u2019environnement (notamment accueil nouveaux embauch\u00e9s)<br \/>\n\uf0a7 Organiser les activit\u00e9s diverses d\u2019une ou plusieurs \u00e9quipes en fonction du<br \/>\nplanning pr\u00e9vu et des al\u00e9as de l\u2019activit\u00e9<br \/>\n\uf0a7 Animer et g\u00e9rer les \u00e9quipes de fabrication<br \/>\n\uf0a7 Participer \/ superviser la formation des autres membres de l\u2019\u00e9quipe pour les<br \/>\nactivit\u00e9s de formation (Vous recevrez une formation pratique pour cette<br \/>\nmission)<br \/>\n\uf0a7 Suivre, superviser et contr\u00f4ler le d\u00e9roulement de la fabrication.<\/p>\n<p>Profil recherch\u00e9 :<br \/>\n\uf0b7 Qualification requise : Bac + 2, Licence ou Master en Biochimie, chimie<br \/>\ndermatologie, pharmacologie ou autre disciplines associ\u00e9es ;<br \/>\n\uf0b7 Tr\u00e8s bonne aptitude d\u2019orateur et capable d\u2019expliquer des concepts simple ou<br \/>\ncompliqu\u00e9es (La formation des autres membres de l\u2019\u00e9quipe sera une des<br \/>\nprincipales missions du candidat retenu)<br \/>\n\uf0b7 Qualit\u00e9s professionnelles : Respect de la confidentialit\u00e9, motivation \u00e0 atteindre les<br \/>\nobjectifs, leadership, prise d\u2019initiative, Capacit\u00e9 \u00e0 travailler en \u00e9quipe, Souci du<br \/>\nd\u00e9tail, Bon jugement, Excellentes aptitudes en service \u00e0 la client\u00e8le.<br \/>\n\uf0b7 Qualit\u00e9s humaines : Rigueur, autonomie, dimension relationnelle.<br \/>\nLieu de travail\u00a0: Akwa, Douala, Cameroun<br \/>\nPour postuler\u00a0:<br \/>\nLes personnes int\u00e9ress\u00e9es par ce poste doivent faire parvenir leur curriculum vitae en tout<br \/>\ntemps \u00e0\u00a0vitalepluspharma@gmail.com.<\/p>\n<p>Nous attendons votre candidature au plus vite.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OFFRE D\u2019EMPOI Nous recrutons, Un Formateur \/ Technicien de Production en Industrie Cosm\u00e9tique H\/F Vitale Plus Cosmetics est une entreprise camerounaise, engag\u00e9e dans la production&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[27],"tags":[1508],"villes":[136],"contrats":[234],"diplomes":[162,212,159],"louma_meta":{"emploi_title":"Un Formateur \/ Technicien de Production en Industrie Cosm\u00e9tique H\/F","emplois_employeur":3046,"emplois_date_publication":"2020-11-16","emplois_heure_publication":"","emplois_date_cloture":"2020-12-16","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"vitalepluspharma@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/8528"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=8528"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/8528\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3031"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=8528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=8528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=8528"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=8528"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=8528"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=8528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}