{"id":8324,"date":"2020-11-06T02:07:47","date_gmt":"2020-11-06T01:07:47","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=8324"},"modified":"2020-11-06T02:07:47","modified_gmt":"2020-11-06T01:07:47","slug":"trade-marketing-manager","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/trade-marketing-manager\/","title":{"rendered":"Trade Marketing Manager"},"content":{"rendered":"<p>Trade Marketing Manager<\/p>\n<p>Soci\u00e9t\u00e9 industrielle de la place, sp\u00e9cialis\u00e9e dans les produits pour b\u00e2timents et travaux publics bas\u00e9e \u00e0 Yaound\u00e9, recherche pour les besoins de ses services un(e) Trade Marketing Manager.<\/p>\n<p>&nbsp;<\/p>\n<p>Profil et qualifications recherch\u00e9s :<\/p>\n<p>&nbsp;<\/p>\n<p>Etre \u00e2g\u00e9(e) de 26 ans minimum ;<\/p>\n<p>Bac+4\/5 dans une \u00e9cole de commerce en Marketing ou Vente ;<\/p>\n<p>Jouir d&rsquo;une exp\u00e9rience d&rsquo;au moins 3 ans \u00e0 un poste similaire ;<\/p>\n<p>Avoir une capacit\u00e9 d&rsquo;analyse et de synth\u00e8se de donn\u00e9es tr\u00e8s complexes ;<\/p>\n<p>Avoir un sens de l&rsquo;organisation et un esprit de m\u00e9thode ;<\/p>\n<p>Etre rigoureux (se), organis\u00e9(e), et avoir un solide sens du travail en \u00e9quipe ;<\/p>\n<p>Avoir une culture solide et pratique de la distribution ;<\/p>\n<p>Etre dot\u00e9(e) d&rsquo;un esprit de cr\u00e9ativit\u00e9, avoir une force de proposition et de persuasion ;<\/p>\n<p>Etre dot\u00e9(e) d&rsquo;un bon relationnel et d&rsquo;une capacit\u00e9 d&rsquo;\u00e9coute pouvant permettre de challenger les interlocuteurs.<\/p>\n<p>Missions principales:<\/p>\n<p>&nbsp;<\/p>\n<p>Sous la supervision du Responsable Marketing et Commercial, le (la) Trade Marketing Manager est charg\u00e9(e) de :<\/p>\n<p>&nbsp;<\/p>\n<p>L&rsquo;\u00e9laboration de la politique promotionnelle et des plans d&rsquo;action p\u00e9riodiques par partenaire de distribution;<\/p>\n<p>La conception et de la mise en place des op\u00e9rations de promotion et des \u00e9v\u00e9nements organis\u00e9s sur et \u00e0 proximit\u00e9 des lieux de vente ;<\/p>\n<p>Piloter les \u00e9tudes et analyses en rapport avec le march\u00e9 et le produit;<\/p>\n<p>Piloter toutes les op\u00e9rations du Trade marketing ;<\/p>\n<p>Suivre le d\u00e9roulement des actions, leur rentabilit\u00e9 et optimiser les r\u00e9sultats ;<\/p>\n<p>Assurer la veille concurrentielle ;<\/p>\n<p>Bien vouloir envoyer vos CV \u00e0 l&rsquo;adresse suivante : delphineoghsa@gmail.com<\/p>\n<p>&nbsp;<\/p>\n<p>Offre valable jusqu&rsquo;au 20 Novembre 2020.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Offre d&#8217;emploi une entreprise camerounaise est \u00e0 la recherche de candidature pour le poste Trade Marketing Manager<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[24],"tags":[],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Trade Marketing Manager","emplois_employeur":3046,"emplois_date_publication":"2020-11-06","emplois_heure_publication":"","emplois_date_cloture":"2020-12-06","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"Bien vouloir envoyer vos CV \u00e0 l'adresse suivante : delphineoghsa@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/8324"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=8324"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/8324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3031"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=8324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=8324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=8324"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=8324"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=8324"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=8324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}