{"id":8107,"date":"2020-10-29T04:05:05","date_gmt":"2020-10-29T03:05:05","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=8107"},"modified":"2020-10-29T04:05:05","modified_gmt":"2020-10-29T03:05:05","slug":"8107","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/8107\/","title":{"rendered":"OFFRE D&rsquo;EMPLOI -SECRETAIRE CAISSIERE"},"content":{"rendered":"<h2>SECRETAIRE CAISSIERE<\/h2>\n<div>\n<div class=\"addthis_toolbox addthis_default_style \">\n<div class=\"fb-like fb_iframe_widget\" data-layout=\"button_count\" data-share=\"false\" data-action=\"like\" data-width=\"90\" data-height=\"25\" data-font=\"arial\" data-href=\"http:\/\/emplois.groupe-cible.com\/job\/secretaire-caissiere\" data-send=\"false\"><\/div>\n<div class=\"tweet_iframe_widget\"><\/div>\n<p><a class=\"atc_s addthis_button_compact\">Partager<\/a><a class=\"addthis_button_expanded\" title=\"Plus d'options...\" href=\"http:\/\/emplois.groupe-cible.com\/job\/secretaire-caissiere#\" target=\"_blank\" rel=\"noopener noreferrer\">2<\/a><\/p>\n<div class=\"atclear\"><\/div>\n<\/div>\n<\/div>\n<h3><a href=\"http:\/\/emplois.groupe-cible.com\/job\/ciblerh.nukeboard.co\" target=\"_blank\" rel=\"noopener noreferrer\">Cible RH<\/a>\u00a0\u00a0\u00a0(Douala)<\/h3>\n<p>Publi\u00e9e : 28 octobre, 2020<\/p>\n<h5>Domaine de l&rsquo;offre :\u00a0<a href=\"http:\/\/emplois.groupe-cible.com\/category\/administration-jobs\">Administration\u00a0<\/a>\u00a0\u00a0\u00a0Lieu :\u00a0<a href=\"http:\/\/emplois.groupe-cible.com\/location\/douala-jobs\">Douala<\/a><\/h5>\n<p>Type de l&rsquo;offre : Full Time<\/p>\n<hr \/>\n<p><strong>R\u00e9f\u00e9rence<\/strong>\u00a0: SC-RH-027-10-20 _Type de contrat : CDI _ M\u00e9tier\/Sp\u00e9cialit\u00e9 : Administration, Localisation g\u00e9ographique : Douala ; Publication : 28-10-20<\/p>\n<p><strong>NOTRE\u00a0CLIENT<\/strong><\/p>\n<p>Entreprise sp\u00e9cialis\u00e9e dans l\u2019\u00e9nergie solaire<\/p>\n<p><strong>ACTIVITE(S) DU POSTE\u00a0<\/strong><\/p>\n<p><strong>Secr\u00e9tariat<\/strong><\/p>\n<p>\u2022 Saisir et g\u00e9rer les courriers (arriv\u00e9e et d\u00e9part)<\/p>\n<p>\u2022 Archiver et classer les documents (courriers, rapports, commandes, factures\u2026)<\/p>\n<p>\u2022 Recevoir et orienter les visiteurs<\/p>\n<p>\u2022 Assurer le standard t\u00e9l\u00e9phonique<\/p>\n<p>\u2022 Organiser les r\u00e9unions, les rendez-vous et les d\u00e9placements<\/p>\n<p>\u2022 Organiser le planning du Directeur<\/p>\n<p>\u2022 Repr\u00e9senter l\u2019entreprise aupr\u00e8s de tiers si n\u00e9cessaire (clients, fournisseurs, banques\u2026)<\/p>\n<p>\u2022 Assurer le suivi de tout dossier ou mission confi\u00e9e par le Directeur<\/p>\n<p><strong>Caisse et banque<\/strong><\/p>\n<p>\u2022 G\u00e9rer la caisse<\/p>\n<p>\u2022 Tenir les journaux de caisse et de banque<\/p>\n<p>\u2022 Encaisser et remettre en banque les r\u00e8glements des clients<\/p>\n<p>\u2022 G\u00e9rer les op\u00e9rations bancaires courantes (retraits, versements, remises, virements\u2026)<\/p>\n<p>\u2022 Retirer les extraits de comptes bancaires<\/p>\n<p><strong>Reporting<\/strong><\/p>\n<p>\u2022\u00a0 \u00a0 \u00a0 \u00a0R\u00e9diger et transmettre les comptes-rendus de r\u00e9unions<\/p>\n<p><strong>PROFIL DU POSTE :<\/strong><\/p>\n<p>Minimum BTS Comptabilit\u00e9 et\/ou Gestion Entreprises et des Administrations<\/p>\n<p>Minimum 2 ans d\u2019exp\u00e9rience \u00e0 un poste similaire<\/p>\n<p>Comp\u00e9tences techniques : bonnes capacit\u00e9s r\u00e9dactionnelles, maitrise de l\u2019outil informatique, pratique des techniques d\u2019accueil, connaissance des techniques de classement<\/p>\n<p>Comp\u00e9tences comportementales :\u00a0 sens de l\u2019organisation, rigueur, aisance relationnelle, confiance en soi<\/p>\n<p>&nbsp;<\/p>\n<p>Bien vouloir envoyer votre curriculum vitae (CV) d\u00e9taill\u00e9 via le lien suivant :<\/p>\n<p><strong>HYPERLINK \u00ab\u00a0http:\/\/www.emplois.groupe-cible.com<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>DATE LIMITE :\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Mardi 06 Novembre 2020 \u00e0 18h<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SECRETAIRE CAISSIERE Partager2 Cible RH\u00a0\u00a0\u00a0(Douala) Publi\u00e9e : 28 octobre, 2020 Domaine de l&rsquo;offre :\u00a0Administration\u00a0\u00a0\u00a0\u00a0Lieu :\u00a0Douala Type de l&rsquo;offre : Full Time R\u00e9f\u00e9rence\u00a0: SC-RH-027-10-20 _Type de&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[1411],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"OFFRE D'EMPLOI -SECRETAIRE CAISSIERE","emplois_employeur":2630,"emplois_date_publication":"2020-10-29","emplois_heure_publication":"","emplois_date_cloture":"2020-11-05","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"http:\/\/emplois.groupe-cible.com\/job\/secretaire-caissiere#.X5ovVYhKhdg"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/8107"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=8107"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/8107\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2631"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=8107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=8107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=8107"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=8107"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=8107"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=8107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}