{"id":7969,"date":"2020-10-23T04:28:34","date_gmt":"2020-10-23T02:28:34","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=7969"},"modified":"2020-10-23T04:28:34","modified_gmt":"2020-10-23T02:28:34","slug":"stage-dinsertion-professionnelle","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/stage-dinsertion-professionnelle\/","title":{"rendered":"Stage d&rsquo;insertion Professionnelle"},"content":{"rendered":"<div class=\"headline\">\n<h2>Stage d&rsquo;insertion Professionnelle\u00a0<span class=\"label label-light-green rounded\">Nouveau<\/span><\/h2>\n<\/div>\n<div class=\"col-11 margin-bottom-5 detail-job\">\n<table class=\"table\">\n<tbody>\n<tr>\n<td>Post\u00e9 : 15-10-2020<\/td>\n<td>Nom de l\u2019employeur : Entreprise de la place<\/td>\n<\/tr>\n<tr>\n<td>Lieu : Yaound\u00e9<\/td>\n<td>Vues : 558<\/td>\n<\/tr>\n<tr>\n<td>Type d&#8217;emploi : STAGE<\/td>\n<td>Postulants : 0<\/td>\n<\/tr>\n<tr>\n<td>Date expiration : 24-10-2020<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"text-justify margin-bottom-30\">\n<div>\n<div class=\"margin-bottom-5 text-center\"><ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-4034601610242774\" data-ad-slot=\"3650588849\" data-adsbygoogle-status=\"done\"><ins id=\"aswift_2_expand\"><ins id=\"aswift_2_anchor\"><\/ins><\/ins><\/ins><\/div>\n<\/div>\n<div class=\"job-description\">\n<p><strong>Offre de stage d&rsquo;insertion professionnelle<\/strong><\/p>\n<p><strong>Nous sommes\u00a0<\/strong>est une Soci\u00e9t\u00e9 de droit Camerounais bas\u00e9e \u00e0 Yaound\u00e9 et sp\u00e9cialis\u00e9e dans les prestations de services informatiques et le e-commerce (Shoppinglist.cm).<\/p>\n<p>Accompagner nos partenaires et leurs clients dans leurs op\u00e9rations de ventes et d\u2019achats en ligne, tel est notre motivation.<\/p>\n<p>Ainsi, nous recherchons pour les besoins de nos services des Stagiaires dans le domaine du Marketing et commercial. Les Stagiaires auront pour objectif le d\u00e9veloppement du portefeuille clients de l&rsquo;entreprise et d&rsquo;assister\u00a0 les dirigeants dans la gestion commerciale de la structure.<\/p>\n<p><strong>Nombre de postes:04<\/strong><\/p>\n<p><strong><u>Job Description:<\/u><\/strong><\/p>\n<ul>\n<li>Prospections commerciales cibl\u00e9es\u00a0;<\/li>\n<li>D\u00e9veloppement et \u00e9laboration des strat\u00e9gies commerciales\u00a0;<\/li>\n<li>Gestion des partenaires et des commandes clients\u00a0;<\/li>\n<li>Assurer la livraison de certaines commandes\u00a0;<\/li>\n<li>Assistance des Dirigeants dans les proc\u00e9dures de gestion administrative et financi\u00e8re.<\/li>\n<\/ul>\n<p><strong><u>Profil du Candidat:<\/u><\/strong><\/p>\n<ul>\n<li>Ag\u00e9 de 21 ans au moins<\/li>\n<li>Sens de la rigueur au travail, assiduit\u00e9, orient\u00e9 r\u00e9sultat<\/li>\n<li>Aimer les d\u00e9fis et fonctionner par objectif<\/li>\n<li>Honn\u00eatet\u00e9<\/li>\n<li>Dipl\u00f4me Bac +2 Minimum en marketing, commerce\/vente (les candidatures f\u00e9minines sont encourag\u00e9es ainsi que les profils commerciaux.<\/li>\n<\/ul>\n<p><strong>Lieu<\/strong>: Yaound\u00e9 et Douala (Cameroun)<\/p>\n<p><strong>Type de contrat<\/strong>: Stage professionnel (attestation de service garanti) avec possibilit\u00e9 d&#8217;embauche si concluant<\/p>\n<p>Les candidatures (CV + Lettre de motivation) doivent \u00eatre achemin\u00e9es \u00e0 l\u2019adresse suivante :\u00a0<strong><a href=\"mailto:weberkouhsi@gmail.com\">weberkouhsi@gmail.com<\/a><\/strong>\u00a0<strong>au plus tard le 25 Octobre 2020<\/strong>.<\/p>\n<p><strong>NB<\/strong>\u00a0: Aucune suite ne sera donn\u00e9e aux candidatures non conformes.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Stage d&rsquo;insertion Professionnelle\u00a0Nouveau Post\u00e9 : 15-10-2020 Nom de l\u2019employeur : Entreprise de la place Lieu : Yaound\u00e9 Vues : 558 Type d&#8217;emploi : STAGE Postulants&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[251,22],"tags":[1385],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Stage d'insertion Professionnelle","emplois_employeur":3046,"emplois_date_publication":"2020-10-23","emplois_heure_publication":"","emplois_date_cloture":"2020-10-25","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"weberkouhsi@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/7969"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=7969"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/7969\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3031"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=7969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=7969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=7969"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=7969"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=7969"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=7969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}