{"id":7966,"date":"2020-10-23T03:44:55","date_gmt":"2020-10-23T01:44:55","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=7966"},"modified":"2020-10-23T03:44:55","modified_gmt":"2020-10-23T01:44:55","slug":"technicien-infographiste","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/technicien-infographiste\/","title":{"rendered":"TECHNICIEN INFOGRAPHISTE"},"content":{"rendered":"<div class=\"headline\">\n<h2>TECHNICIEN INFOGRAPHISTE<\/h2>\n<\/div>\n<div class=\"col-11 margin-bottom-5 detail-job\">\n<table class=\"table\">\n<tbody>\n<tr>\n<td>Post\u00e9 : 19-10-2020<\/td>\n<td>Nom de l\u2019employeur : Entreprise de la place<\/td>\n<\/tr>\n<tr>\n<td>Lieu : Douala<\/td>\n<td>Vues : 276<\/td>\n<\/tr>\n<tr>\n<td>Type d&#8217;emploi : CDI<\/td>\n<td>Postulants : 0<\/td>\n<\/tr>\n<tr>\n<td>Date expiration : 07-11-2020<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"text-justify margin-bottom-30\">\n<div>\n<div class=\"margin-bottom-5 text-center\"><ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-4034601610242774\" data-ad-slot=\"3650588849\" data-adsbygoogle-status=\"done\"><ins id=\"aswift_2_expand\"><ins id=\"aswift_2_anchor\"><\/ins><\/ins><\/ins><\/div>\n<\/div>\n<div class=\"job-description\">\n<p><strong>OPPORTUNITE<\/strong><\/p>\n<p><strong>Titre du poste\u00a0:\u00a0<\/strong>TECHNICIEN INFOGRAPHISTE<\/p>\n<p><strong>Statut :<\/strong>\u00a0Agent de Ma\u00eetrise<\/p>\n<p><strong>Lieu du travail :\u00a0<\/strong>Douala, Yaound\u00e9, Bafoussam<\/p>\n<p><strong>Sexe :<\/strong>\u00a0Masculin, F\u00e9minin<\/p>\n<p><strong>Age\u00a0:<\/strong>\u00a025-35 ans<\/p>\n<p><strong>Dipl\u00f4me\u00a0Acad\u00e9mique Exig\u00e9\u00a0:<\/strong>\u00a0BTS en Infographie ou webdesign \/ BTS en communication visuelle ou industrie graphique \/ Licence professionnelle en infographie ou webdesign \/ Licence professionnelle en communication visuelle ou industrie graphique<\/p>\n<p><strong>Niveau Acad\u00e9mique Exig\u00e9\u00a0:\u00a0<\/strong>BACC + 2 \/ BACC + 3\u00a0;<\/p>\n<p><strong>BACCALAUREAT de Base :<\/strong>\u00a0Tous les BACCALAUREAT<\/p>\n<p><strong>Exp\u00e9riences Professionnelles\u00a0:\u00a0<\/strong>Avoir au minimum 5 ann\u00e9es d\u2019exp\u00e9riences professionnelles \u00e0 un poste similaire\u00a0(<strong>au sein d\u2019une soci\u00e9t\u00e9 organis\u00e9e de r\u00e9f\u00e9rence<\/strong>)<\/p>\n<p><strong>Informatique<\/strong><\/p>\n<ul>\n<li>Maitrise de Photoshop, illustrator, Adobe After Effects ;<\/li>\n<li>Ma\u00eetrise du Motion Design\u00a0;<\/li>\n<li>Maitrise de la PAO (Publication Assist\u00e9e par Ordinateur)\u00a0;<\/li>\n<li>Maitrise des logiciels professionnels de l\u2019audiovisuel\u00a0;<\/li>\n<li>Maitrise des logiciels Microsoft Office\u00a0(Word, Excel, PowerPoint, Outlook, etc\u2026)\u00a0;<\/li>\n<li>Maitrise de l\u2019outil internet\u00a0;<\/li>\n<li>Connaissance des syst\u00e8mes d\u2019exploitation\u00a0: windows 7, windows 10<\/li>\n<\/ul>\n<p><strong>Missions principales du poste<\/strong><\/p>\n<p>Le\u00a0technicien infographiste a pour mission d\u2019assurer la cr\u00e9ation et la r\u00e9alisation des supports de communication. Il imagine, pr\u00e9pare et r\u00e9alise des supports visuels dans le respect de la charte graphique de l\u2019entreprise. Il doit retoucher et transformer des images afin de transmettre un message clair et pr\u00e9cis.<\/p>\n<p><strong>Domaine de comp\u00e9tences<\/strong><\/p>\n<ul>\n<li>Cr\u00e9er des graphismes, dessins, maquettes, illustrations gr\u00e2ce \u00e0 la PAO\u00a0;<\/li>\n<li>Concevoir graphiquement les supports \u00e0 caract\u00e8res informatif et\/ou promotionnel dans le respect de la charte graphique de l\u2019entreprise ;<\/li>\n<li>Cr\u00e9er une communication visuelle avec des textes et des images\u00a0;<\/li>\n<li>Transformer des images pour transmettre un message clair et pr\u00e9cis\u00a0;<\/li>\n<li>Concevoir et r\u00e9aliser des documents publicitaires et marketing\u00a0;<\/li>\n<li>G\u00e9rer la biblioth\u00e8que \u00ab\u00a0image\u00a0\u00bb et \u00ab\u00a0conception graphique\u00a0\u00bb\u00a0;<\/li>\n<li>Maitriser les notions d\u2019audiovisuel et des codes visuels (typographie, couleurs, etc\u2026)\u00a0;<\/li>\n<li>Maitriser les techniques de communication\u00a0;<\/li>\n<li>Traiter des images et cr\u00e9er des visuels avec des outils graphiques\u00a0: Photoshop et Illustrator\u00a0;<\/li>\n<li>Cr\u00e9er des animations\u00a0;<\/li>\n<li>Maitriser la cr\u00e9ation d\u2019une charte graphique\u00a0;<\/li>\n<li>Concevoir et transmettre un message<\/li>\n<\/ul>\n<p><strong>Autres comp\u00e9tences<\/strong><\/p>\n<ul>\n<li>Notions de gestion et de marketing\u00a0;<\/li>\n<li>Savoir prendre des photos\/vid\u00e9os professionnelles est un plus\u00a0;<\/li>\n<li>Ma\u00eetrise des r\u00e9seaux sociaux et diff\u00e9rents types de contenus pouvant \u00eatre produits pour les r\u00e9seaux sociaux (stories, vid\u00e9os, images)\u00a0;<\/li>\n<li>Savoir administrer une messagerie<\/li>\n<\/ul>\n<p><strong>Contraintes du poste\u00a0<\/strong>:\u00a0Disponibilit\u00e9, flexibilit\u00e9, pro activit\u00e9, mobilit\u00e9, capacit\u00e9 \u00e0 travailler sous pression<\/p>\n<p><strong>Langue<\/strong><\/p>\n<ul>\n<li>Fran\u00e7ais \/ Anglais parl\u00e9 couramment et \u00e9crit<\/li>\n<li>Anglais \/ Fran\u00e7ais souhait\u00e9e<\/li>\n<li>Autres langues souhait\u00e9es<\/li>\n<\/ul>\n<p><strong>Comment Postuler?<\/strong><\/p>\n<p>Bien vouloir envoyer vos dossiers (<strong><em>CV<\/em><\/strong><em>,\u00a0<strong>lettre de motivation<\/strong>,\u00a0<strong>copie dipl\u00f4me<\/strong><\/em>)\u00a0<strong>en format pdf<\/strong>\u00a0<strong>au plus tard le samedi 07\/11\/2020 \u00e0 18h00<\/strong>\u00a0\u00e0 l\u2019adresse mail suivante\u00a0:\u00a0\u00a0\u00a0<strong><a href=\"mailto:recrutements2035@gmail.com\">recrutements2035@gmail.com<\/a><\/strong>\u00a0 \u00a0avec en\u00a0<strong>objet TECHNICIEN INFOGRAPHISTE.<\/strong><\/p>\n<p><strong><em>NB<\/em><\/strong><em>\u00a0: Seuls les candidats pr\u00e9s\u00e9lectionn\u00e9s et r\u00e9pondant strictement aux crit\u00e8res sus \u00e9voqu\u00e9s seront contact\u00e9s pour des entretiens.<\/em><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>TECHNICIEN INFOGRAPHISTE Post\u00e9 : 19-10-2020 Nom de l\u2019employeur : Entreprise de la place Lieu : Douala Vues : 276 Type d&#8217;emploi : CDI Postulants :&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[697],"tags":[1377],"villes":[135,136],"contrats":[234],"diplomes":[248,212],"louma_meta":{"emploi_title":"TECHNICIEN INFOGRAPHISTE","emplois_employeur":3046,"emplois_date_publication":"2020-10-23","emplois_heure_publication":"","emplois_date_cloture":"2020-11-23","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"recrutements2035@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/7966"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=7966"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/7966\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3031"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=7966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=7966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=7966"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=7966"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=7966"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=7966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}