{"id":7549,"date":"2020-10-08T04:32:19","date_gmt":"2020-10-08T02:32:19","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=7549"},"modified":"2020-10-08T04:32:19","modified_gmt":"2020-10-08T02:32:19","slug":"appel-a-candidature-directeur-customer-care","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/appel-a-candidature-directeur-customer-care\/","title":{"rendered":"Appel \u00e0 candidature : Directeur customer care"},"content":{"rendered":"<div class=\"post-header\">\n<div class=\"post-head\">\n<h1 class=\"post-title entry-title\">Appel \u00e0 candidature : Directeur customer care<\/h1>\n<\/div>\n<div class=\"post-meta\"><span class=\"post-author vcard\"><i class=\"fa fa-user\"><\/i>\u00a0<span class=\"fn\"><a class=\"g-profile\" title=\"Cameroon Desk\" href=\"https:\/\/www.blogger.com\/profile\/18407799637193377338\" rel=\"author\">Cameroon Desk\u00a0<\/a><\/span><\/span><span class=\"post-timestamp\"><i class=\"fa fa-calendar-o\"><\/i>\u00a0<a class=\"timestamp-link\" title=\"permanent link\" href=\"https:\/\/www.cameroondesks.com\/2020\/10\/appel-candidature-directeur-customer.html\" rel=\"bookmark\"><abbr class=\"published timeago\" title=\"15:19\">1 day ago<\/abbr><\/a>\u00a0<\/span><span class=\"label-head\"><i class=\"fa fa-folder-o\"><\/i>\u00a0<a href=\"https:\/\/www.cameroondesks.com\/search\/label\/jobs?&amp;max-results=6\" rel=\"tag\">jobs,<\/a>\u00a0<a href=\"https:\/\/www.cameroondesks.com\/search\/label\/offre%20d%27emploi?&amp;max-results=6\" rel=\"tag\">offre d&#8217;emploi,<\/a>\u00a0<a href=\"https:\/\/www.cameroondesks.com\/search\/label\/recrutement?&amp;max-results=6\" rel=\"tag\">recrutement,<\/a><\/span><\/div>\n<div><\/div>\n<div class=\"ads-posting\"><a name=\"ad-post-top\"><\/a><\/div>\n<div><\/div>\n<\/div>\n<article>\n<div id=\"post-body-4498408399991156187\" class=\"post-body entry-content\">\n<div>\n<table class=\"tr-caption-container\" cellspacing=\"0\" cellpadding=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td><a href=\"https:\/\/1.bp.blogspot.com\/-QdwVH4c0rjs\/XliQTp3BJEI\/AAAAAAAAEgE\/dAKqnKFBy_w05gCnPnBFcaAC5ZNBBH1qQCPcBGAYYCw\/s1600\/upowa.png\"><img decoding=\"async\" title=\"upowa\" src=\"https:\/\/1.bp.blogspot.com\/-QdwVH4c0rjs\/XliQTp3BJEI\/AAAAAAAAEgE\/dAKqnKFBy_w05gCnPnBFcaAC5ZNBBH1qQCPcBGAYYCw\/s1600\/upowa.png\" alt=\"upowa\" border=\"0\" data-original-height=\"159\" data-original-width=\"318\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td class=\"tr-caption\"><b>Appel \u00e0 candidature : Directeur customer care<\/b><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div><b>\u00a0<\/b><\/div>\n<div><b>DIRECTEUR CUSTOMER CARE<\/b><\/div>\n<div><b>Lieu :\u00a0<\/b>Yaound\u00e9<\/div>\n<div><b>Type d&#8217;emploi :<\/b>\u00a0CDI<\/div>\n<\/div>\n<p><b>Responsabilit\u00e9s du DCC<\/b><\/p>\n<ul>\n<li>Organise l\u2019activit\u00e9 d\u2019un site ax\u00e9 sur la relation client \u00e0 Distance<\/li>\n<li>Supervise l\u2019activit\u00e9 des \u00e9quipes dans le sens de l\u2019atteinte des objectifs qui lui sont fix\u00e9s.<\/li>\n<li>Veille \u00e0 la qualit\u00e9 des services et au maintien d\u2019un bon climat social entre les op\u00e9rateurs et les clients<b>.<\/b><\/li>\n<\/ul>\n<p><b>Missions<\/b><br \/>\n<b>a. Mise en \u0153uvre de la politique de la relation client<\/b><\/p>\n<ul>\n<li>Mettre en \u0153uvre les orientations m\u00e9tier en selon les objectifs quantitatifs et qualitatifs ;<\/li>\n<li>D\u00e9velopper les actions garantissant la qualit\u00e9 de service aux clients et leur satisfaction ;<\/li>\n<li>Assurer la responsabilit\u00e9 de l\u2019ensemble des risques op\u00e9rationnels<\/li>\n<\/ul>\n<p><b>b. Pilotage des \u00e9quipes du contact center<\/b><\/p>\n<ul>\n<li>D\u00e9finir et suivre les objectifs individuels\/collectifs, qualitatifs\/quantitatifs des op\u00e9rateurs.<\/li>\n<li>Organiser et superviser le travail des \u00e9quipes : encadrement (Responsable des Op\u00e9rations,\u00a0<a href=\"http:\/\/www.frederic-chartier.com\/teleprospection\/index.php?2017\/12\/30\/79-responsable-de-plateau-fiche-metier-descriptif-de-poste\">Chef d\u2019\u00e9quipe et op\u00e9rateurs) comp\u00e9tence\u00a0<\/a>(qualit\u00e9 des services, formation, planification, statistiques, informatique, gestion de la Relation Clients).<\/li>\n<li>Transmettre aux \u00e9quipes les d\u00e9cisions de la Direction, des Clients internes\/externes.<\/li>\n<li>Faire appliquer les process sp\u00e9cifiques d\u00e9finis avec les Clients internes\/externes.<\/li>\n<\/ul>\n<p><b>c. Management des \u00e9quipes du Centre de contacts<\/b><\/p>\n<ul>\n<li>Participer aux recrutements, int\u00e9grer et \u00e9valuer les collaborateurs.<\/li>\n<li>Mettre sur pied les m\u00e9thodes de travail visant \u00e0 accompagner le d\u00e9veloppement de leurs comp\u00e9tences.<\/li>\n<li>Assurer la gestion administrative (absences, formation) et les relations sociales.<\/li>\n<li>Planifier les ressources des \u00e9quipes en fonction du cahier des charges et des flux quotidiens d\u2019appels.<\/li>\n<li>Mettre sur pied une r\u00e9glementation sociale visant \u00e0 d\u00e9velopper une vraie exp\u00e9rience client.<\/li>\n<\/ul>\n<p><b>d. Reporting<\/b><\/p>\n<ul>\n<li>D\u00e9finir et suivre les indicateurs de performance : satisfaction des Clients, Chiffre d\u2019Affaires, climat social, respect des process.<\/li>\n<li>Suivre les indicateurs de productivit\u00e9 du traitement des appels t\u00e9l\u00e9phoniques : taux de prise d\u2019appels, de d\u00e9lai de r\u00e9ponse, de temps d\u2019attente, d\u2019abandons, de transformation\u2026<\/li>\n<li>Analyser les r\u00e9sultats de l\u2019activit\u00e9 du Call Center.<\/li>\n<\/ul>\n<p><b>e. Animation de la d\u00e9marche d\u2019am\u00e9lioration continue<\/b><\/p>\n<ul>\n<li>Veiller \u00e0 la qualit\u00e9 des entretiens avec les Clients.<\/li>\n<li>Identifier les diff\u00e9rents axes d\u2019am\u00e9lioration pour optimiser la rentabilit\u00e9 du Centre d\u2019Appels, contribuer aux \u00e9volutions de ses activit\u00e9s.<\/li>\n<li>D\u00e9finir les objectifs des enqu\u00eates de satisfaction : p\u00e9riodicit\u00e9, profils des cibles clients, cat\u00e9gories de produits\/services etc.<\/li>\n<li>Accompagner les \u00e9quipes dans la ma\u00eetrise des process, sur la base des enqu\u00eates et des indicateurs<\/li>\n<\/ul>\n<p><b>f. Service apr\u00e8s-vente<\/b><\/p>\n<ul>\n<li>S\u2019assurer que les plaintes client et les cas SAV sont bien collect\u00e9s, enregistr\u00e9s et trait\u00e9s dans les d\u00e9lais<\/li>\n<li>Assister les clients en ligne dans la r\u00e9solution des plaintes.<\/li>\n<li>G\u00e9rer la prise de rendez-vous pour l\u2019assistance d\u2019un technicien et \u00e9valuer par la suite la satisfaction client.<\/li>\n<li>Assister les clients en ligne dans l\u2019installation compl\u00e8te de leur kit solaire.<\/li>\n<\/ul>\n<p><b>Profil souhait\u00e9<\/b><br \/>\n<b>Etudes :<\/b>\u00a0BAC+5 minimum, \u00e9tudes de commerce\/communication vivement souhait\u00e9 ; Une exp\u00e9rience professionnelle en call center serait un plus<\/p>\n<p><b>Savoir-\u00eatre :\u00a0<\/b>Dynamique, rigoureux et autonome, patience, empathie, \u00e9coute, respect de la client\u00e8le<br \/>\n<b><br \/>\nLangue :\u00a0<\/b>Tr\u00e8s bonne capacit\u00e9 d\u2019expression orale, bonne ma\u00eetrise du fran\u00e7ais et l\u2019anglais. Parler une ou plusieurs langues locales du Cameroun est un atout.<\/p>\n<p><b>Comment postuler :<\/b><br \/>\nSi votre profil cadre avec la candidature, pri\u00e8re d\u2019envoyer votre CV \u00e0 l\u2019adresse suivante<\/p>\n<p><b><u>Date expiration : 20-10-2020<\/u><\/b><\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Appel \u00e0 candidature : Directeur customer care<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[1253],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Appel \u00e0 candidature : Directeur customer care","emplois_employeur":5832,"emplois_date_publication":"2020-10-08","emplois_heure_publication":"","emplois_date_cloture":"2020-10-20","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"recrutement@upowa.org"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/7549"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=7549"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/7549\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/5836"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=7549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=7549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=7549"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=7549"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=7549"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=7549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}