{"id":7480,"date":"2020-10-07T03:48:35","date_gmt":"2020-10-07T01:48:35","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=7480"},"modified":"2020-10-07T03:48:35","modified_gmt":"2020-10-07T01:48:35","slug":"directeurtrice-des-centres-commerciaux-douala","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/directeurtrice-des-centres-commerciaux-douala\/","title":{"rendered":"Directeur(Trice) Des Centres Commerciaux \u2013 Douala"},"content":{"rendered":"<h2 style=\"font-weight: 500\">Directeur(Trice) Des Centres Commerciaux \u2013 Douala<\/h2>\n<h5>Autres<\/h5>\n<p>Vacancy<\/p>\n<p style=\"font-weight: 400\">1<\/p>\n<p>Job Type<\/p>\n<p style=\"font-weight: 400\">Full Time<\/p>\n<p>Responsibilities<\/p>\n<p style=\"font-weight: 400\"><b><strong><em><u>Missions du poste\u00a0:<\/u><\/em><\/strong><\/b><\/p>\n<p style=\"font-weight: 400\">Rattach\u00e9(e) au Directeur G\u00e9n\u00e9ral, le(la) Directeur(trice) des Centres Commerciaux aura la responsabilit\u00e9 de l\u2019exploitation des centres commerciaux au Cameroun. Il(elle) doit veiller \u00e0 l\u2019optimisation de l\u2019exploitation et des revenus locatifs des espaces commerciaux, et accompagner le lancement de nouveaux projets.<\/p>\n<p style=\"font-weight: 400\">Dans ce cadre, le(la) Directeur(trice) des Centres Commerciaux sera en charge de :<\/p>\n<ul>\n<li style=\"font-weight: 400\"><b><strong>La gestion des baux commerciaux<\/strong><\/b><\/li>\n<\/ul>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Contr\u00f4ler les encaissements de loyer<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Suivre et g\u00e9rer les situations d\u2019impay\u00e9s<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Suivre et g\u00e9rer les contentieux locatifs avec les locataires et les services juridiques<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0N\u00e9gocier les renouvellements de bail \u00e0 l\u2019\u00e9ch\u00e9ance<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Etablir une relation de confiance et de performance mutuelle avec les exploitants locataires<\/p>\n<ul>\n<li style=\"font-weight: 400\"><b><strong>La gestion immobili\u00e8re du site<\/strong><\/b><\/li>\n<\/ul>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Mettre en place et g\u00e9rer les contrats de prestations de services de propret\u00e9, s\u00e9curit\u00e9 et maintenance des Centres Commerciaux<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0G\u00e9rer les budgets de charges, les refacturations et les redditions avec les locataires<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Etablir des benchmarks et proposer des solutions d\u2019optimisation des charges immobili\u00e8res<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Proposer des process d\u2019am\u00e9lioration de la gestion immobili\u00e8re<\/p>\n<ul>\n<li style=\"font-weight: 400\"><b><strong>La commercialisation des locaux aupr\u00e8s des enseignes<\/strong><\/b><\/li>\n<\/ul>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Commercialiser les espaces libres<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Commercialiser les nouveaux projets<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Maintenir une recherche et un relationnel permanent aupr\u00e8s des enseignes, franchis\u00e9s, nationaux et internationaux<\/p>\n<ul>\n<li style=\"font-weight: 400\"><b><strong>Le Marketing et la Communication<\/strong><\/b><\/li>\n<\/ul>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Elaborer le Plan d\u2019Action Marketing et communication<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Mettre en place et superviser les animations et \u00e9v\u00e8nements<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Elaborer la politique et les actions de marketing digital<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Etablir les bilans d\u2019actions marketing et orienter les actions correctives<\/p>\n<ul>\n<li style=\"font-weight: 400\"><b><strong>L\u2019Asset Management des Centres Commerciaux<\/strong><\/b><\/li>\n<\/ul>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Elaborer l\u2019ensemble des plans d\u2019actions\u00a0: commerciaux (baux), marketing, maintenance<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Synth\u00e9tiser les plans d\u2019actions sous forme de Business Plan<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Elaborer les budgets<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Elaborer le Plan Strat\u00e9gique<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Identifier les leviers de cr\u00e9ation de valeur immobili\u00e8re<\/p>\n<ul>\n<li style=\"font-weight: 400\">\u00a0<b><strong>Le lancement de nouveaux projets<\/strong><\/b><\/li>\n<\/ul>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Accompagner les \u00e9quipes expansion et travaux au cours de la conception des projets, et au cours de la r\u00e9alisation<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Planifier les actions d\u2019ouverture et de lancement des nouveaux Centres Commerciaux<\/p>\n<p>Educational Requirements<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Dipl\u00f4me d\u2019une \u00e9cole de commerce ou tout autre dipl\u00f4me \u00e9quivalent<\/p>\n<p>Experience Requirements<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Avoir au minimum 05 ans d\u2019exp\u00e9rience \u00e0 un poste similaire<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Avoir une bonne exp\u00e9rience de la grande distribution<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Une connaissance ou une exp\u00e9rience du retail organis\u00e9 (enseigne de distribution, enseigne de retail sp\u00e9cialis\u00e9, \u2026)<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Avoir une exp\u00e9rience de la gestion budg\u00e9taire, du contr\u00f4le de gestion et de la gestion financi\u00e8re<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0\u00catre parfaitement bilingue (fran\u00e7ais\/anglais)<\/p>\n<p>Additional Requirements<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Bonne condition physique<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Bonne ouverture d\u2019esprit<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Curiosit\u00e9<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Orientation r\u00e9sultats<\/p>\n<p style=\"font-weight: 400\">o\u00a0\u00a0\u00a0Orientation client<\/p>\n<p>Compensation And Other Benefits<\/p>\n<p style=\"font-weight: 400\">N\u00e9gociable<\/p>\n<p>Job Location<\/p>\n<p style=\"font-weight: 400\">Douala, Douala, Cameroon<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Directeur(Trice) Des Centres Commerciaux \u2013 Douala<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[1182],"tags":[1235],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Directeur(Trice) Des Centres Commerciaux \u2013 Douala","emplois_employeur":4816,"emplois_date_publication":"2020-10-07","emplois_heure_publication":"","emplois_date_cloture":"2020-10-25","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/mhd.hsd-melt.com\/public-search\/32"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/7480"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=7480"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/7480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4817"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=7480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=7480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=7480"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=7480"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=7480"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=7480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}