{"id":7046,"date":"2020-09-18T03:29:30","date_gmt":"2020-09-18T01:29:30","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=7046"},"modified":"2020-09-18T03:29:30","modified_gmt":"2020-09-18T01:29:30","slug":"une-charge-e-detudes-et-du-suivi-commercial-cesc","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/une-charge-e-detudes-et-du-suivi-commercial-cesc\/","title":{"rendered":"UN(E) CHARGE (E) D&rsquo;ETUDES ET DU SUIVI COMMERCIAL (CESC)"},"content":{"rendered":"<p>Une entreprise sp\u00e9cialis\u00e9e dans les TIC recrute pour les besoins de ses services en pr\u00e9-emploi au poste suivant :<\/p>\n<p><span class=\"bold\">UN(E) CHARGE (E) D&rsquo;ETUDES ET DU SUIVI COMMERCIAL (CESC)<\/span><\/p>\n<p><span class=\"bold\">Mission principale :\u00a0<\/span>Assurer les \u00e9tudes Marketing et le suivi Commercial.<\/p>\n<p>Sur le plan Etude de march\u00e9 \/ Veille strat\u00e9gique<\/p>\n<ul>\n<li>Elaboration et mise en \u0153uvre d&rsquo;un plan de veille concurrentielle ;<\/li>\n<li>Analyse des parts de march\u00e9 et du positionnement de l&rsquo;entreprise ;<\/li>\n<li>Mise en \u0153uvre et suivi de l&rsquo;impl\u00e9mentation du syst\u00e8me d&rsquo;information Marketing et Commercial ;<\/li>\n<li>R\u00e9aliser des \u00e9tudes de pr\u00e9sence dans l&rsquo;environnement de l&rsquo;entreprise.<\/li>\n<\/ul>\n<p>Sur le plan Suivi Commercial<\/p>\n<ul>\n<li>Soutenir et accompagner la Direction Commerciale et Marketing dans ses activit\u00e9s de supervision de la force de vente ; la mise en \u0153uvre des strat\u00e9gies et politiques commerciales d\u00e9finies par la Direction G\u00e9n\u00e9rale ;<\/li>\n<li>Analyser les \u00e9tats et reportings effectu\u00e9s par les \u00e9quipes commerciales ;<\/li>\n<li>Actualiser r\u00e9guli\u00e8rement la base de donn\u00e9es des prospects pour un meilleur ciblage lors des actions de prospection des commerciaux ;<\/li>\n<li>\u00c9laborer les argumentaires de vente par produit et service ;<\/li>\n<\/ul>\n<p>Sur le plan de la Gestion de la Force de Vente<\/p>\n<ul>\n<li>Participer aux r\u00e9unions commerciales avec les managers commerciaux ;<\/li>\n<li>Organiser chaque mois des s\u00e9ances de formation et de renforcement des capacit\u00e9s des commerciaux sur les solutions commercialis\u00e9s par l&rsquo;entreprise ;<\/li>\n<li>Organiser des s\u00e9minaires commerciaux tous les trimestres.<\/li>\n<\/ul>\n<p>Comp\u00e9tences th\u00e9oriques et techniques :<\/p>\n<ul>\n<li>Etre titulaire d&rsquo;un BAC + 5 en Gestion, option Marketing<\/li>\n<li>Bonne ma\u00eetrise de la suite Office ;<\/li>\n<li>Connaissances d&rsquo;utilisation des logiciels d&rsquo;analyse des donn\u00e9es (Sphinx, SPSS,\u2026) ;<\/li>\n<li>Justifier d&rsquo;au moins 2 ans d&rsquo;exp\u00e9rience \u00e0 ce poste ou \u00e0 un poste similaire ;<\/li>\n<li>Connaissance \u00e9ventuelle du secteur de T\u00e9l\u00e9communications.<\/li>\n<\/ul>\n<p>Comp\u00e9tences organisationnelles et sociales :<\/p>\n<ul>\n<li>Forte motivation et aptitude \u00e0 travailler sous pression ;<\/li>\n<li>Forte capacit\u00e9 d&rsquo;adaptation au stress;<\/li>\n<li>Rigueur et respect des d\u00e9lais ;<\/li>\n<li>Dynamisme et grande capacit\u00e9 d&rsquo;organisation ;<\/li>\n<li>Disponibilit\u00e9 et r\u00e9activit\u00e9 ;<\/li>\n<li>Bon relationnel et travail en \u00e9quipe<\/li>\n<\/ul>\n<p><span class=\"bold\">D\u00e9marche de candidature :<\/span><\/p>\n<p>Si vous \u00eates int\u00e9ress\u00e9(es), bien vouloir envoyer votre dossier de candidature (<em>CV + Lettre de motivation + pi\u00e8ces justificatives<\/em>) \u00e0 l&rsquo;adresse<span class=\"bold\">\u00a0<a href=\"mailto:rhrecruitment.tic@gmail.com\" target=\"_blank\" rel=\"noopener noreferrer\">rhrecruitment.tic@gmail.com<\/a>\u00a0au plus tard le 21 Septembre 2020 \u00e0 15h pr\u00e9cises<\/span>; avec en objet l&rsquo;intitul\u00e9 du poste. \u00ab\u00a0<span class=\"bold\">Charg\u00e9 d&rsquo;Etudes<\/span>\u00ab\u00a0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une entreprise sp\u00e9cialis\u00e9e dans les TIC recrute pour les besoins de ses services en pr\u00e9-emploi au poste suivant : UN(E) CHARGE (E) D&rsquo;ETUDES ET DU&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[3,251],"tags":[1091],"villes":[136],"contrats":[236,234],"diplomes":[162,212,159],"louma_meta":{"emploi_title":"UN(E) CHARGE (E) D'ETUDES ET DU SUIVI COMMERCIAL (CESC)","emplois_employeur":3046,"emplois_date_publication":"2020-09-18","emplois_heure_publication":"","emplois_date_cloture":"2020-10-18","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"rhrecruitment.tic@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/7046"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=7046"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/7046\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3031"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=7046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=7046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=7046"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=7046"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=7046"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=7046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}