{"id":7032,"date":"2020-09-18T02:51:25","date_gmt":"2020-09-18T00:51:25","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=7032"},"modified":"2020-09-18T02:51:25","modified_gmt":"2020-09-18T00:51:25","slug":"charge-du-developpement-de-la-force-de-vente","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/charge-du-developpement-de-la-force-de-vente\/","title":{"rendered":"Charg\u00e9 du d\u00e9veloppement de la force de vente"},"content":{"rendered":"<p>Intitul\u00e9 du poste\u00a0<strong>:<\/strong>\u00a0<strong>Charg\u00e9 du d\u00e9veloppement de la force de vente<\/strong><\/p>\n<p>Zone de publication\u00a0<strong>:\u00a0<\/strong>Interne\/Externe<\/p>\n<p>Lieu de Fonction<strong>\u00a0:<\/strong>Yaound<strong>\u00e9<\/strong><\/p>\n<p><strong>Mission principale\u00a0:Concevoir et mettre en \u0153uvre les programmes et outils destin\u00e9s \u00e0 renforcer l&rsquo;efficacit\u00e9 des \u00e9quipes commerciales sur le terrain.<\/strong><\/p>\n<p><strong>ACTIVITES DU POSTE<\/strong><\/p>\n<p>D\u00e9terminer les objectifs de la strat\u00e9gie de vente ;<\/p>\n<p>Organiser, animer et suivre l&rsquo;activit\u00e9 de l&rsquo;\u00e9quipe de vente et lui apporter un appui technique ;<\/p>\n<p>Elaborer et mettre en \u0153uvre la strat\u00e9gie de merchandising et du trade marketing par zone de vente ;<\/p>\n<p>D\u00e9velopper un portefeuille clients\/prospects ;<\/p>\n<p>Suivre le budget des actions commerciales ;<\/p>\n<p>Recueillir les recommandations des clients, de la direction des ventes, de la force de vente et les traduire en plans d&rsquo;actions commerciaux ;<\/p>\n<p>Suivre le march\u00e9 au plan national et international ;<\/p>\n<p>N\u00e9gocier les contrats commerciaux avec les centrales d&rsquo;achats (r\u00e9f\u00e9rencement, charte tarifaire, op\u00e9rations promotionnelles\u2026) ;<\/p>\n<p>Superviser les r\u00e9seaux de vente ou des circuits de distribution (agences commerciales, boutiques, GMS\u2026) ;<\/p>\n<p>Effectuer des reportings \u00e0 la hi\u00e9rarchie ;<\/p>\n<p>R\u00e9aliser les argumentaires commerciaux devant \u00eatre utilis\u00e9s par la force de vente.<\/p>\n<p><strong>QUALIFICATIONS ET EXPERIENCE REQUISES<\/strong><\/p>\n<p><strong>Niveau acad\u00e9mique : BACC+3 en commerce\/vente et n\u00e9gociation<\/strong><\/p>\n<p><strong>Exp\u00e9rience professionnelle : 02 ans minimum \u00e0 un poste similaire dans le secteur cosm\u00e9tique.<\/strong><\/p>\n<p><strong>\u00catre titulaire d&rsquo;un Permis de conduire cat\u00e9gorie B valide<\/strong><\/p>\n<p><strong>COMPETENCES REQUISES<\/strong><\/p>\n<p><strong>Savoirs<\/strong><\/p>\n<p>Excellente connaissance en gestion de la force de vente ;<\/p>\n<p>Excellente connaissance en gestion des portes feuilles ;<\/p>\n<p>Excellente connaissance en technique de prospection ;<\/p>\n<p>Bonne maitrise de la conduite d&rsquo;actions de n\u00e9gociations commerciales ;<\/p>\n<p>Excellente connaissance en management d&rsquo;\u00e9quipes commerciales ;<\/p>\n<p>Bonne analyse de l&rsquo;environnement concurrentiel du secteur de la cosm\u00e9tique ;<\/p>\n<p><strong>Savoir-Faire<\/strong><\/p>\n<p>Bonne connaissance en marketing op\u00e9rationnel ;<\/p>\n<p>Bonne connaissance des techniques de merchandising ;<\/p>\n<p>Connaissance en gestion comptable et administrative ;<\/p>\n<p>Techniques de vente ;<\/p>\n<p>Techniques de n\u00e9gociation et de fid\u00e9lisation des clients ;<\/p>\n<p>Connaissances des produits et\/ou services d&rsquo;une entreprise cosm\u00e9tique ;<\/p>\n<p>Bonne connaissance des circuits de distribution des produits cosm\u00e9tiques ;<\/p>\n<p>Maitrise d&rsquo;internet et des logiciels : EXCEL\u2026<\/p>\n<p>Techniques d&rsquo;expression fran\u00e7aise et anglaise.<\/p>\n<p><strong>Savoir-\u00catre<\/strong><\/p>\n<p>Grande capacit\u00e9 d&rsquo;\u00e9coute et de persuasion ;<\/p>\n<p>Excellente pr\u00e9sentation physique et bonne \u00e9locution ;<\/p>\n<p>Organis\u00e9(e), rigoureux(se), capable de g\u00e9rer les priorit\u00e9s et force de proposition ;<\/p>\n<p>Sens pouss\u00e9 de la n\u00e9gociation et dot\u00e9(e) de bonnes qualit\u00e9s relationnelles<\/p>\n<p><strong><em>D\u00e9p\u00f4t des candidatures :<\/em><em>\u00a0Envoyez votre lettre de motivation et votre curriculum vitae \u00e0 l&rsquo;adresse<\/em><em>\u00a0:\u00a0<\/em><a href=\"mailto:careers@laboratoiresbb.com\" target=\"_blank\" rel=\"noopener noreferrer\"><em>careers@laboratoiresbb.com<\/em><\/a>\u00a0<em>au plus tard le<\/em>\u00a0<em>Mercredi 23 Septembre 2020<\/em><em>\u00a0en pr\u00e9cisant en objet \u00ab\u00a0<\/em><em>candidature au poste de Charg\u00e9(e) du d\u00e9veloppement de la force de vente<\/em><em>\u00a0\u00bb Toute candidature re\u00e7ue par un canal autre que celui indiqu\u00e9 ne sera pas consid\u00e9r\u00e9e.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Intitul\u00e9 du poste\u00a0:\u00a0Charg\u00e9 du d\u00e9veloppement de la force de vente Zone de publication\u00a0:\u00a0Interne\/Externe Lieu de Fonction\u00a0:Yaound\u00e9 Mission principale\u00a0:Concevoir et mettre en \u0153uvre les programmes et&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[3,27],"tags":[1088],"villes":[136],"contrats":[234],"diplomes":[162,212,159],"louma_meta":{"emploi_title":"Charg\u00e9 du d\u00e9veloppement de la force de vente","emplois_employeur":3046,"emplois_date_publication":"2020-09-18","emplois_heure_publication":"","emplois_date_cloture":"2020-09-23","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"3","emploi_email":"careers@laboratoiresbb.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/7032"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=7032"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/7032\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3031"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=7032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=7032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=7032"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=7032"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=7032"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=7032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}