{"id":6758,"date":"2020-09-07T04:32:24","date_gmt":"2020-09-07T02:32:24","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=6758"},"modified":"2020-09-07T04:32:24","modified_gmt":"2020-09-07T02:32:24","slug":"kpmg-recrute-pour-le-bureau-de-douala-stagiaire-professionnel-saison-2020-2021-audit-advisory","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/kpmg-recrute-pour-le-bureau-de-douala-stagiaire-professionnel-saison-2020-2021-audit-advisory\/","title":{"rendered":"KPMG Recrute pour le bureau de Douala : Stagiaire Professionnel saison 2020-2021 (Audit &amp; Advisory)\u00a0"},"content":{"rendered":"<p>KPMG Recrute pour le bureau de Douala : Stagiaire Professionnel saison 2020-2021 (Audit &amp; Advisory)<\/p>\n<p>&nbsp;<\/p>\n<p>Notre cabinet \u00e9volue avec une\u00a0 culture d&rsquo;entreprise o\u00f9 la gestion des comp\u00e9tences est une r\u00e9alit\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p>Gr\u00e2ce \u00e0 la multiplicit\u00e9 des \u00e9changes g\u00e9n\u00e9r\u00e9s par nos missions et \u00e0 la pr\u00e9sence internationale de notre Cabinet, nous vous donnons les moyens de vous \u00e9panouir pleinement.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Dans le cadre du d\u00e9veloppement de ses activit\u00e9s, KPMG recherche des stagiaires professionnels aux profils suivants:<\/p>\n<p>&nbsp;<\/p>\n<p>Profils recherch\u00e9s:<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c2g\u00e9 entre 20 et 26 ans; Ayant un niveau Bac+5; Bilingue, Excellent niveau en fran\u00e7ais et en anglais;<\/p>\n<p>&nbsp;<\/p>\n<p>\u00catre parmi les 05 meilleurs dipl\u00f4m\u00e9s d&rsquo;un des \u00e9tablissements cot\u00e9 de la r\u00e9gion3;<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; Avoir envie de b\u00e2tir une carri\u00e8re en cabinet.<\/p>\n<p>&nbsp;<\/p>\n<p>Dossier de candidature \u00e0 envoyer par email: cV \u00e0jour (pr\u00e9cisant la date de naissance et les r\u00e9f\u00e9rences du candidat);<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; Le relev\u011b de note ou autres documents officiels soutenant le classement indiqu\u00e9;<\/p>\n<p>&nbsp;<\/p>\n<p>Tout autre document jug\u00e9 n\u00e9cessaire;<\/p>\n<p>&nbsp;<\/p>\n<p>Bien marquer en objet du mail la r\u00e9f\u00e9rence inscrite ci-dessous. Seuls les candidats retenus pour les prochaines \u00e9tapes seront contact\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<p>Veuillez postuler avant le 07\/09\/2020 Email : cm-contact@kpmg.cm R\u00e9f\u00e9rence : KPMG AC_SP_202008 kpmg.com\/socialmedia in www: https:\/\/home.kpmg.com\/cm\/fr\/home.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>KPMG Recrute pour le bureau de Douala : Stagiaire Professionnel saison 2020-2021 (Audit &amp; Advisory) &nbsp; Notre cabinet \u00e9volue avec une\u00a0 culture d&rsquo;entreprise o\u00f9 la&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[1009],"villes":[135,136],"contrats":[152],"diplomes":[162,212,159],"louma_meta":{"emploi_title":"KPMG Recrute pour le bureau de Douala : Stagiaire Professionnel saison 2020-2021 (Audit & Advisory)\u00a0","emplois_employeur":6401,"emplois_date_publication":"2020-09-07","emplois_heure_publication":"","emplois_date_cloture":"2020-09-07","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"Email : cm-contact@kpmg.cm"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/6758"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=6758"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/6758\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/6402"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=6758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=6758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=6758"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=6758"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=6758"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=6758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}