{"id":6681,"date":"2020-09-03T13:25:03","date_gmt":"2020-09-03T11:25:03","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=6681"},"modified":"2020-09-03T13:25:03","modified_gmt":"2020-09-03T11:25:03","slug":"offre-demploi-manager-audit-comptable-financier-kpmg","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/offre-demploi-manager-audit-comptable-financier-kpmg\/","title":{"rendered":"Offre d&#8217;emploi : Manager Audit Comptable\/Financier-KPMG"},"content":{"rendered":"<p>KPMG Recrutement &#8211; Manager Audit Comptable &amp; Financier Bureau du Cameroun Le monde \u00e9conomique et financier \u00e9volue, le m\u00e9tier d&rsquo;Auditeur \u00e9galement, Nos cients nous sollicitent de plus en plus pour des interventions \u00e0 forte valeur ajout\u00e9e, pour lesquelles, plus que jamais, nous agissons en tant que partenaire privil\u00e9gi\u0117. Rejoindre KPMG, c&rsquo;est d\u00e9velopper une expertise rEconnue, gogner rapidement en responsabilit\u00e9s, booster votre carri\u00e8re et vous r\u00e9aliser dans un environnement propice. Nous recherchons unte):<\/p>\n<p>Manager Audit Comptable\/Financier Rattach\u00e9(e) a la Business Unit Audit GRANDS COMPTES de KPMG Afrique Centrale, bureau du Cameroun, vous r\u00e9alisez des missions \u00e0 forte valeur ajout\u00e9e en \u00e9tablissant une relation de confiance et en assurant un soutien continu \u00e0 nos cdients.<\/p>\n<p>&nbsp;<\/p>\n<p>Vous interviendrez principalement sur des missions d&rsquo;audit aupr\u00e8s d&rsquo;une client\u0117le diversifi\u00e9e, dans un environnement national mais aussi international Vous serez responsable des missions suivantes:<\/p>\n<p>\u2022 Audit l\u00e9gal et contractuel sur un portefeuille client de secteur financier (Etablissements de cr\u00e9dits et institutions financi\u00e8res);<\/p>\n<p>\u2022 Encadrement et coordination des \u00e9quipes d&rsquo;audit (gestion planning, encourager, donner des consignes claires, valoriser les succ\u00e8s de l&rsquo;\u00e9quipe et f&rsquo;inciter \u00e0 une constante am\u00e9lioration);<\/p>\n<p>\u2022 Etre garant du niveau de valeur ajout\u00e9e apport\u00e9e par F\u00e9quipe aux clients;<\/p>\n<p>\u2022 Actions de d\u00e9veloppement commercial; Profil:<\/p>\n<p>\u2022 Vous \u00eates un expert comptable dipl\u00f4m\u00e9 (e) avec une majeure en finance\/comptabilit\u00e9 bancaire:<\/p>\n<p>\u2022 Vous disposez d&rsquo;une exp\u00e9rience d&rsquo;au moins 5 ans au sein d&rsquo;un cabinet d&rsquo;audit ou dans une fonction comparable aupr\u00e8s d&rsquo;une banque;<\/p>\n<p>\u2022 Vous avez une exp\u00e9rience r\u00e9ussie du management d&rsquo;\u00e9quipe, vous vous exprimez couramment en fran\u00e7ais et en anglais, et vous maitrisez les normes comptables internationales (IFRS):<\/p>\n<p>\u2022 Vous avez une parfaite connaissance de l&rsquo;environnement r\u00e9glementaire local (CEMAC) et international du secteur bancaire \u2022<\/p>\n<p>Enfin, vous \u00eates dynamique, entreprenantie). dot\u00e9le) d&rsquo;un fort esprit d&rsquo;analyse, et de capac\u012bt\u00e9s de d\u00e9veloppement commercial et, vous souhaitez \u00e9largir vos comp\u00e9tences dans un environnement stimulant \u00e0 la pointe des nouvelles technologies en mati\u00e8re daudit.<\/p>\n<p>Dossier de candidature \u00e0 envoyer par email: CV d\u00e9taill\u00e9 \u00e0 jour des r\u00e9f\u00e9rences du candidat et tout autre document jug\u00e9 n\u00e9cessaire; Bien marquer en objet du mail la ref\u00e9rence inscrite d-dessous. Veuillez postuler avant le 15 Septembre 2020.<\/p>\n<p>Seuls les candidats retenus pour les prochaines \u00e9tapes seront contact\u00e9s. Email : cm-contact@kpmg.cm R\u00e9f\u00e9rence : KPMG AC MA 202008 www: https:\/\/home.kpmg\/cm\/tr\/home.html kpmg.com\/socialmedia in f Oa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>KPMG Recrutement &#8211; Manager Audit Comptable &amp; Financier Bureau du Cameroun Le monde \u00e9conomique et financier \u00e9volue, le m\u00e9tier d&rsquo;Auditeur \u00e9galement, Nos cients nous sollicitent&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[23],"tags":[986],"villes":[136],"contrats":[236,234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Offre d'emploi : Manager Audit Comptable\/Financier-KPMG","emplois_employeur":6401,"emplois_date_publication":"2020-09-03","emplois_heure_publication":"","emplois_date_cloture":"2020-10-04","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"cm-contact@kpmg.cm"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/6681"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=6681"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/6681\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/6402"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=6681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=6681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=6681"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=6681"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=6681"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=6681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}