{"id":6283,"date":"2020-08-24T03:23:20","date_gmt":"2020-08-24T01:23:20","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=6283"},"modified":"2020-08-24T03:23:20","modified_gmt":"2020-08-24T01:23:20","slug":"offre-demploi-superviseure-mobilisation-communutaire","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/offre-demploi-superviseure-mobilisation-communutaire\/","title":{"rendered":"Offre d\u00b4emploi :\u00a0Superviseur(e) MOBILISATION COMMUNUTAIRE"},"content":{"rendered":"<div>\n<div class=\"media\">\n<div class=\"media-body\">\n<h3 class=\"media-heading\">Offre d\u00b4emploi :\u00a0Superviseur(e) MOBILISATION COMMUNUTAIRE<\/h3>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row-fluid\">\n<div class=\"span3\">\n<div class=\"infosentreprise\">\n<h3 class=\"instruction\">Infos cl\u00e9s<\/h3>\n<ul>\n<li><b>Type de contrat :<\/b>\u00a0A n\u00e9gocier<\/li>\n<li><b>Domaine d&rsquo;activit\u00e9 :<\/b>\u00a0Non sp\u00e9cifi\u00e9<\/li>\n<li><b>Lieu de travail :<\/b>\u00a0Kouss\u00e9ri<\/li>\n<li><b>Exp\u00e9rience :<\/b>\u00a0D\u00e9butant<\/li>\n<li><b>Niveau d&rsquo;\u00e9tude minimum :<\/b>\u00a0Licence<\/li>\n<li><b>Salaire<\/b>\u00a0: \u00e0 n\u00e9gocier<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"span6\">\n<div class=\"bloclecture\">\n<h3 class=\"instruction\">l&rsquo;offre<\/h3>\n<h4>Profil souhait\u00e9<\/h4>\n<div>\n<p>Une personne, homme ou femme ayant entre 25 et 45 ans avec comme niveau d\u00b4\u00e9tude Licence ni plus ni moins parlant et \u00e9crivant fran\u00e7ais<\/p>\n<\/div>\n<h4>Description du profil<\/h4>\n<div>\n<div>Presentation de l\u00b4entreprise<\/div>\n<div>\n<p>La Croix-Rouge fran\u00e7aise (CRf) et la Croix-Rouge Camerounaise (CRC) sont des associations humanitaires, auxiliaires des pouvoirs publics, qui apportent aide et assistance aux personnes vuln\u00e9rables.<\/p>\n<p>Depuis 2010, la Croix-Rouge fran\u00e7aise (CRf) est pr\u00e9sente au Cameroun et intervient dans les domaines de la sant\u00e9, de la nutrition et de la s\u00e9curit\u00e9 alimentaire et moyens d\u2019existence (SAME) dans les r\u00e9gions de l\u2019Est et de l\u2019Extr\u00eame-Nord.<\/p>\n<p><strong>Contexte du recrutement<br \/>\n<\/strong><\/p>\n<p>Remplacement d\u2019un staff en cong\u00e9 (arr\u00eat m\u00e9dical).<\/p>\n<p>Fait partie de l\u2019\u00e9quipe de Batouri.<\/p>\n<p>PRESENTATION DU POSTE:<\/p>\n<p><strong>Objectif \/ R\u00e9sum\u00e9 du poste<\/strong><\/p>\n<p>Sous la responsabilit\u00e9 du Chef de projet PSP, l\u2019adjointe cheffe de projet psychosocial(e), participe \u00e0 la mise en \u0153uvre du projet \u00ab\u00a0I Y\u00e9k\u00e9 Oko\u00a0\u00bb, qui vise \u00e0 contribuer au d\u00e9veloppement durable et \u00e9quilibr\u00e9 des territoires de la Kadey et de la Mamb\u00e9r\u00e9-Kade\u00ef.<\/p>\n<p>Plus sp\u00e9cifiquement, il intervient sur les activit\u00e9s li\u00e9es \u00e0 la composante coh\u00e9sion sociale, dont l\u2019objectif est de \u00ab\u00a0<em>contribuer au renforcement des m\u00e9canismes communautaires de gestion des ressources, de m\u00e9diation et d\u00b4acc\u00e8s aux services de base\u00a0<\/em>\u00bb. Il\/Elle collabore \u00e9troitement avec les \u00e9quipes de la Croix-Rouge (Camerounaise et Fran\u00e7aise) de Batouri ainsi qu\u2019avec les \u00e9quipes des partenaires du consortium et les services sociaux de base. Il\/Elle doit apporter un support technique au personnel du projet et un soutien psychosocial aux b\u00e9n\u00e9ficiaires du projet via les volontaires.<\/p>\n<p><strong>Responsabilit\u00e9s<\/strong><\/p>\n<ol>\n<li>Planification, mise en \u0153uvre et encadrement des activit\u00e9s mobilisation communautaire et psychosociales\u00a0;<\/li>\n<li>Suivi-\u00e9valuation des activit\u00e9s de la mobilisation communautaire et psychosociales du projet\u00a0;<\/li>\n<li>Communication interne et externe des activit\u00e9s du projet\u00a0;<\/li>\n<li>Gestion de l\u2019\u00e9quipe de volontaires sur les activit\u00e9s du projet en lien avec les activit\u00e9s su consortium\u00a0;<\/li>\n<li>Redevabilit\u00e9 et capitalisation des activit\u00e9s de la mobilisation communautaire et psychosociales\u00a0;<\/li>\n<li>Repr\u00e9sentation de l\u2019organisation aupr\u00e8s des partenaires.<\/li>\n<\/ol>\n<p><strong>Description des t\u00e2ches<\/strong><\/p>\n<p><strong>Planification, mise en \u0153uvre et encadrement des activit\u00e9s mobilisation communautaire et psychosociales<\/strong><\/p>\n<ul>\n<li>Fait des propositions quant \u00e0 l\u2019organisation des activit\u00e9s psychosociales et mobilisations communautaires (m\u00e9thodologie d\u2019intervention, \u00e9tudes pr\u00e9alables, etc.)\u00a0;<\/li>\n<li>Planifie les activit\u00e9s psychosociales du projet et les organise avec son \u00e9quipe\u00a0de travail ;<\/li>\n<li>Identifie les besoins de sensibilisation pour la population et les b\u00e9n\u00e9ficiaires, propose et organise les groupes de parole, des entretiens individuels sur des th\u00e9matiques en lien avec le soutien psychosocial ;<\/li>\n<li>Met en place les activit\u00e9s psychosociales en coordination avec l\u2019ensemble des activit\u00e9s du projet\u00a0;<\/li>\n<li>S\u2019assure que les activit\u00e9s individuel et collectif sont men\u00e9es conform\u00e9ment au planning ;<\/li>\n<li>Contribue \u00e0 la bonne organisation des activit\u00e9s du projet dans les villages cibl\u00e9s avec les autres acteurs : composantes du Mouvement, acteurs humanitaires et autorit\u00e9s locales\u00a0;<\/li>\n<li>Proc\u00e8de \u00e0 un \u00e9tat des lieux initial sur les l\u2019existence et le fonctionnement des centres d\u2019\u00e9coutes et des structures locales intervenant dans la prise en charge psychologique dans la zone d\u2019intervention ; des structures locales intervenant dans la mobilisation communautaire<\/li>\n<li>Contribue au renforcement des capacit\u00e9s du personnel social des centres d\u2019\u00e9coute des communes, des relais communautaires et autres acteurs (comme leaders communautaires)\u00a0;<\/li>\n<li>Organise les sessions de formation des volontaires pour am\u00e9liorer ou renforcer leurs interventions dans le domaine psychosocial\u00a0et d\u2019animation communautaire via diff\u00e9rents groupes (club de m\u00e8re et de p\u00e8re, club d\u2019\u00e9coute, OSBC)<\/li>\n<li>Appuie le chef de projet et son adjointe dans l\u2019\u00e9laboration des diff\u00e9rents modules de formation psychosociale du personnel du projet et des partenaires, en lien avec le responsable du bureau PSP au si\u00e8ge, selon les protocoles en vigueur au Cameroun et \u00e0 la Croix-Rouge\u00a0;<\/li>\n<li>Propose des actions ou des am\u00e9liorations visant \u00e0 maintenir ou renforcer la qualit\u00e9 du projet en ad\u00e9quation avec l\u2019\u00e9volution \u00e9ventuelle des besoins\u00a0;<\/li>\n<\/ul>\n<p><strong>Suivi-\u00e9valuation et renforcement des capacit\u00e9s<\/strong><\/p>\n<ul>\n<li>Participe \u00e0 la r\u00e9alisation des enqu\u00eates CAP et diagnostic communautaire participatif\u00a0;<\/li>\n<li>Participe \u00e0 la r\u00e9alisation des \u00e9valuations rapides et des strat\u00e9gies d\u2019intervention\u00a0en cas de crise ;<\/li>\n<li>Fait des propositions quant \u00e0 la d\u00e9finition des outils de suivi des activit\u00e9s dont il\/elle est responsable\u00a0;<\/li>\n<li>R\u00e9alise des visites de terrain sur les sites des activit\u00e9s psychosociales en cours de r\u00e9alisation selon un chronogramme d\u00e9fini ; chaque visite donnera lieu \u00e0 la r\u00e9daction d\u2019un rapport ;<\/li>\n<li>Assure une \u00e9valuation continue des activit\u00e9s dont il est responsable et fait des propositions pour l\u2019orientation et le d\u00e9veloppement \u00e9ventuel des activit\u00e9s en cours\u00a0;<\/li>\n<li>Assure l\u2019analyse des donn\u00e9es suivies en continu dans le projet\u00a0;<\/li>\n<li>Assure la collecte des informations aupr\u00e8s des diff\u00e9rents intervenants dans le secteur communautaire, social et psychosocial (relations avec les partenaires, participation aux r\u00e9unions th\u00e9matiques organis\u00e9es par les agences comp\u00e9tentes au niveau local, \u2026)\u00a0;<\/li>\n<\/ul>\n<p><strong>Reporting et capitalisation des activit\u00e9s de mobilisation communautaires et psychosociales<\/strong><\/p>\n<ul>\n<li>Appui le chef de projet et le charg\u00e9 de suivi-\u00e9valuation dans le reporting\u00a0des activit\u00e9s dont il a la responsabilit\u00e9\u00a0;<\/li>\n<li>Participe \u00e0 la validation technique des rapports externes\u00a0;<\/li>\n<li>Supervise la collecte de donn\u00e9es et assure l\u2019uniformisation et l\u2019actualisation des bases de donn\u00e9es des activit\u00e9s dont il est responsable\u00a0;<\/li>\n<li>S\u2019assure de la capitalisation des formations et des activit\u00e9s de mobilisation communautaires et de soutien psychosocial mise en place au cours du projet\u00a0;<\/li>\n<\/ul>\n<p><strong>Gestion des \u00e9quipes<\/strong><\/p>\n<ul>\n<li>Participe au processus d\u2019identification des volontaires\u00a0;<\/li>\n<li>Identifie les dysfonctionnements et doit \u00eatre \u00e0 l\u2019\u00e9coute des besoins des liens hi\u00e9rarchiques et des volontaires dans les districts d\u2019intervention de fa\u00e7on \u00e0 proposer des solutions ad\u00e9quates aux probl\u00e8mes rencontr\u00e9s avec leur collaboration et participation\u00a0;<\/li>\n<li>Organise des r\u00e9unions avec les acteurs locaux.<\/li>\n<\/ul>\n<p><strong>Communication\u00a0interne et externe sur les activit\u00e9s du projet<\/strong><\/p>\n<ul>\n<li>Participe activement aux r\u00e9unions de coordination internes \u00e0 l\u2019\u00e9quipe du projet\u00a0;<\/li>\n<li>Accompagne les CRC et la CRf dans son d\u00e9veloppement organisationnel et op\u00e9rationnel<\/li>\n<li>Collabore avec les autres partenaires du consortium pour l\u2019harmonisation des outils et pour une action int\u00e9gr\u00e9e\u00a0;<\/li>\n<li>Informe sa hi\u00e9rarchie de toute difficult\u00e9 ou incompr\u00e9hension avec des partenaires et les b\u00e9n\u00e9ficiaires qui puisse influencer les activit\u00e9s du projet\u00a0;<\/li>\n<li>Assure \u00e0 son niveau une bonne communication avec les agents des services techniques avec lesquels il\/elle est amen\u00e9 \u00e0 travailler. Il\/Elle devra avoir une bonne collaboration avec les agents sociaux des centres d\u2019\u00e9coutes des communes et la Direction R\u00e9gionale des Affaires Sociales (DRAS)\u00a0;<\/li>\n<li>Assure une communication fluide, entretient le lien avec les autorit\u00e9s locales et les b\u00e9n\u00e9ficiaires du projet et s\u2019assure de leur bonne compr\u00e9hension des informations qui leur sont transmises\u00a0;<\/li>\n<li>D\u00e9veloppe et maintient un r\u00e9seau de contacts locaux (partenaires, experts, etc.)\u00a0;<\/li>\n<li>Diffuse les informations aupr\u00e8s des diff\u00e9rents intervenants concern\u00e9s par le projet\u00a0;<\/li>\n<li>Participe aux r\u00e9unions de concertation technique avec les partenaires.<\/li>\n<\/ul>\n<p><strong>Repr\u00e9sentation de l\u2019organisation aupr\u00e8s des partenaires<\/strong><\/p>\n<ul>\n<li>Se fait le porte-parole du projet aupr\u00e8s des autorit\u00e9s locales sur le terrain et aupr\u00e8s de la population, notamment en expliquant les activit\u00e9s et les objectifs du projet \u2013 dans le respect des principes du mouvement CR\u00a0;<\/li>\n<li>Repr\u00e9sente l\u2019organisation aupr\u00e8s des b\u00e9n\u00e9ficiaires\u00a0;<\/li>\n<li>Pr\u00e9sente le projet et assure le lien avec les diff\u00e9rents partenaires locaux\u00a0;<\/li>\n<li>Assure de bonnes relations de travail et de partenariat avec les personnels du mouvement Croix-Rouge, du Minist\u00e8re des Affaires Sociales (MINAS) ou MINPROFF et des autres acteurs humanitaires.<\/li>\n<\/ul>\n<p>De plus, il peut \u00eatre demand\u00e9 occasionnellement \u00e0 l\u2019employ\u00e9(e) d\u2019accomplir d\u2019autres t\u00e2ches li\u00e9es \u00e0 sa fonction mais qui ne sont pas explicitement mentionn\u00e9es dans cette description de poste.<\/p>\n<p>PROFIL:<\/p>\n<p><strong><u>Localisation du Poste\u00a0:\u00a0<\/u>Ce poste est ouvert aux personnes ayant le profil requis et r\u00e9sidant \u00e0 Kouss\u00e9ri\u00a0; il n\u2019est donc pas soumis \u00e0 d\u00e9localisation. Le candidat retenu \u00e0 l\u2019issue du processus de recrutement ne pourra par cons\u00e9quent pas pr\u00e9tendre au statut de salari\u00e9 d\u00e9localis\u00e9.<\/strong><\/p>\n<p><strong>Age \/ Genre\u00a0:\u00a0<\/strong>Non sp\u00e9cifi\u00e9\u00a0<strong>\u00a0: les candidatures f\u00e9minines sont encourag\u00e9es<\/strong><\/p>\n<p><strong>Profil recherch\u00e9\u00a0<\/strong>\u00a0: De formation Licence ou \u00e9quivalent en psychologie, en science sociologique, ou en criminologie option psychosocial.<\/p>\n<p><strong>Exp\u00e9riences et comp\u00e9tences indispensables\u00a0:<\/strong><\/p>\n<ul>\n<li>Avoir une exp\u00e9rience d\u2019au moins 2 ans en mati\u00e8re de planification, coordination et suivi\/\u00e9valuation de projet et programme similaire.<\/li>\n<li>Avoir une excellente connaissance des probl\u00e9matiques du psychosocial et de la gestion des espaces d\u2019\u00e9coute.<\/li>\n<li>Avoir une excellence connaissance dans la mobilisation communautaire<\/li>\n<li>Avoir des capacit\u00e9s d\u2019analyse et de synth\u00e8se.<\/li>\n<li>Avoir l\u2019esprit d\u2019initiative pour promouvoir les r\u00e9seaux et identifier les opportunit\u00e9s.<\/li>\n<li>Avoir un tr\u00e8s bon relationnel (interne et externe).<\/li>\n<li>Avoir l\u2019esprit d\u2019\u00e9quipe, de partage de connaissances, d\u2019apprentissage continu.<\/li>\n<li>Etre dynamique et diplomate.<\/li>\n<li>Ma\u00eetrise du pack Office (Word, Excel, Power Point), Internet<\/li>\n<li>Respecter les principes du Mouvement international de la Croix-Rouge et du Croissant Rouge\u00a0: humanit\u00e9, neutralit\u00e9, unit\u00e9, universalit\u00e9, impartialit\u00e9, volontariat, ind\u00e9pendance.<\/li>\n<li>Faire preuve d\u2019une bonne r\u00e9sistance physique, les distances \u00e0 parcourir en voiture \u00e9tant grandes et les conditions relativement difficiles lors des visites fr\u00e9quentes de supervision sur le terrain.<\/li>\n<li>Conduite de la moto \u00e0 des distances \u00e9loign\u00e9es de son lieu de base de travail, pour des actions terrain.<\/li>\n<\/ul>\n<p><strong>Comp\u00e9tences et aptitudes appr\u00e9ci\u00e9es\u00a0:<\/strong><\/p>\n<ul>\n<li>Aptitude \u00e0 travailler sous pression<\/li>\n<li>Bonnes qualit\u00e9s p\u00e9dagogiques<\/li>\n<li>La connaissance du Mouvement Croix-Rouge\/Croissant-Rouge au travers d\u2019une exp\u00e9rience pr\u00e9alable est un atout.<\/li>\n<li>La connaissance des probl\u00e9matiques sanitaires du Cameroun est un atout.<\/li>\n<li>Parfaite ma\u00eetrise de la langue fran\u00e7aise.<\/li>\n<li>La connaissance du Fulfulde, du Kako et du Gbaya est un atout.<\/li>\n<\/ul>\n<div>PROCESSUS DE RECRUTEMENT:<\/div>\n<div>\n<p><strong>Les dossiers de candidatures devront contenir<\/strong><\/p>\n<ul>\n<li>Un Curriculum Vitae actualis\u00e9\u00a0;<\/li>\n<li>Une lettre de motivation\u00a0;<\/li>\n<li>Une photocopie du dipl\u00f4me\/\u00e9quivalent\u00a0requis\u00a0;<\/li>\n<li>Une photocopie de la carte d\u2019identit\u00e9\u00a0nationale\u00a0;<\/li>\n<li>Deux r\u00e9f\u00e9rences pouvant \u00eatre contact\u00e9es\u00a0;<\/li>\n<\/ul>\n<p>Le dossier de candidature peut \u00eatre d\u00e9pos\u00e9,\u00a0<strong>sous plis ferm\u00e9s qui reprend l\u2019intitul\u00e9 du poste et la localisation,\u00a0<\/strong>aux adresses suivantes :<\/p>\n<ul>\n<li>Maroua : Sous-D\u00e9l\u00e9gation de la Croix-Rouge fran\u00e7aise et \u00eatre remis aux gardiens au bureau situ\u00e9s au quartier Pitoar\u00e9, \u00e0 c\u00f4t\u00e9 de la DRSP (d\u00e9l\u00e9gation R\u00e9gionale de la Sant\u00e9 Publique), b\u00e2timent C4\/IRD\/CRF\u00a0;<\/li>\n<li>Yaound\u00e9\u00a0: D\u00e9l\u00e9gation Croix-Rouge fran\u00e7aise 2005 rue Henri Dunant BP 631 YAOUNDE\u00a0;<\/li>\n<li>Kouss\u00e9ri\u00a0: Croix-Rouge fran\u00e7aise, quartier R\u00e9sidentiel \u00e0 500m des bureaux du CICR<\/li>\n<li>Batouri\u00a0: Ancien bureau de Premier Urgence, Quartier Sambo II face STBK<\/li>\n<li><strong>Ou\u00a0<\/strong>envoy\u00e9 \u00e0 l\u2019adresse\u00a0:\u00a0<u><strong>recruitcrfyaounde@gmail.com<\/strong><\/u><\/li>\n<\/ul>\n<p>Les dossiers devront \u00eatre adress\u00e9s\u00a0\u00e0\u00a0<strong>M. le Chef de Sous-D\u00e9l\u00e9gation de la Croix-Rouge fran\u00e7aise.<\/strong><\/p>\n<p>Au vu, du nombre de dossiers que nous recevons, nous sommes dans l\u2019incapacit\u00e9 de r\u00e9pondre individuellement \u00e0 chacun.\u00a0 Donc si sous 10 jours vous n\u2019avez pas de nouvelles de notre part, veuillez consid\u00e9rer que votre candidature n\u2019a pas \u00e9t\u00e9 retenue. Les candidats pr\u00e9s\u00e9lectionn\u00e9s sur dossier seront convoqu\u00e9s eux pour un test \u00e9crit dans les locaux de la CRF. Les dossiers non s\u00e9lectionn\u00e9s ne seront pas retourn\u00e9s aux candidats.<\/p>\n<p><strong>Date limite de r\u00e9ception des candidatures:<\/strong><strong>28 Ao\u00fbt 2020<\/strong><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<h4>Principales t\u00e2ches<\/h4>\n<div>\n<p>Planification, mise en \u0153uvre et encadrement des activit\u00e9s mobilisation communautaire et psychosociales<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Offre d\u00b4emploi :\u00a0Superviseur(e) MOBILISATION COMMUNUTAIRE &nbsp; Infos cl\u00e9s Type de contrat :\u00a0A n\u00e9gocier Domaine d&rsquo;activit\u00e9 :\u00a0Non sp\u00e9cifi\u00e9 Lieu de travail :\u00a0Kouss\u00e9ri Exp\u00e9rience :\u00a0D\u00e9butant Niveau d&rsquo;\u00e9tude&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[436],"tags":[884],"villes":[141],"contrats":[234],"diplomes":[162,212,159],"louma_meta":{"emploi_title":"Offre d\u00b4emploi :\u00a0Superviseur(e) MOBILISATION COMMUNUTAIRE","emplois_employeur":3172,"emplois_date_publication":"2020-08-24","emplois_heure_publication":"","emplois_date_cloture":"2020-08-28","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"recruitcrfyaounde@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/6283"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=6283"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/6283\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2000"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=6283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=6283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=6283"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=6283"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=6283"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=6283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}