{"id":6143,"date":"2020-08-19T04:59:40","date_gmt":"2020-08-19T02:59:40","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=6143"},"modified":"2020-08-19T04:59:40","modified_gmt":"2020-08-19T02:59:40","slug":"offre-demploi-electricien-automobile","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/offre-demploi-electricien-automobile\/","title":{"rendered":"Offre d\u00b4emploi :\u00a0\u00c9lectricien Automobile"},"content":{"rendered":"<div>\n<div class=\"media\">\n<div class=\"media-body\">\n<h3 class=\"media-heading\">Offre d\u00b4emploi :\u00a0\u00c9lectricien Automobile<\/h3>\n<p>Offre d\u00b4emploi n\u00b0 6768 publi\u00e9e le Lundi 17 Ao\u00fbt 2020 encore valable pour 28 jours. Postulation en ligne non autoris\u00e9e, si vous \u00eates interess\u00e9 par cette offre, prennez contact directement avec le recruteur.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row-fluid\">\n<div class=\"span3\">\n<div class=\"infosentreprise\">\n<h3 class=\"instruction\">Infos cl\u00e9s<\/h3>\n<ul>\n<li><b>Type de contrat :<\/b>\u00a0CDD<\/li>\n<li><b>Domaine d&rsquo;activit\u00e9 :<\/b>\u00a0Non sp\u00e9cifi\u00e9<\/li>\n<li><b>Lieu de travail :<\/b>\u00a0Douala<\/li>\n<li><b>Exp\u00e9rience :<\/b>\u00a0D\u00e9butant<\/li>\n<li><b>Niveau d&rsquo;\u00e9tude minimum :<\/b>\u00a0BTS (Brevet des techniciens sup\u00e9rieurs)<\/li>\n<li><b>Salaire<\/b>\u00a0: \u00e0 n\u00e9gocier<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"span6\">\n<div class=\"bloclecture\">\n<h3 class=\"instruction\">l&rsquo;offre<\/h3>\n<h4>Profil souhait\u00e9<\/h4>\n<div>\n<p>Une personne, homme ou femme ayant entre 25 et 40 ans avec comme niveau d\u00b4\u00e9tude BTS (Brevet des techniciens sup\u00e9rieurs) ni plus ni moins parlant et \u00e9crivant fran\u00e7ais<\/p>\n<\/div>\n<h4>Description du profil<\/h4>\n<div>\n<div class=\"job-description\">\n<p><strong>OPPORTUNITE<\/strong><\/p>\n<p>Une soci\u00e9t\u00e9 de la place situ\u00e9e dans la zone industrielle exercant dans le domaine de la foresterie recherche pour les besoins de son activit\u00e9 un\u00a0<strong>Electricien- Automobile<\/strong>.<\/p>\n<p><strong>PROFIL DU POSTE<\/strong><\/p>\n<ul>\n<li>il doit etre de sexe masculin de pr\u00e9f\u00e9rence et ag\u00e9 entre 25 et 40 ans .<\/li>\n<li>Titulaire d\u00b4un BTS en Electricit\u00e9 &#8211; Automobile et\/ou une formation professionnelle obtenue dans une \u00e9cole appropri\u00e9e ou un centre de formation, il\u00a0doit avoir \u00e0 son actif\u00a0 03 ans d\u00b4exp\u00e9rience professionnelle minimum\u00a0 acquis dans une entreprise ou un at\u00e9lier de d\u00e9pannage \/ r\u00e9paration.<\/li>\n<\/ul>\n<p><u><strong>Qualifications r\u00e9quises:<\/strong><\/u><\/p>\n<p>Plac\u00e9 sous la supervision du chef m\u00e9canicien , l\u00b4\u00e9lectricien automobile devra\u00a0\u00a0\u00eatre capable :<\/p>\n<ul>\n<li>De lire des sch\u00e9mas \u00e9lectriques et \u00e9lectroniques ;<\/li>\n<li>D\u00b4assurer le cablage \u00e9l\u00e9ctrique des automobiles et poids lourds particuli\u00e8rement les camions de marque ACTROSS;<\/li>\n<li>D\u00b4avoir une bonne capacit\u00e9 manuelle de d\u00e9tection, de pr\u00e9cision dans les activit\u00e9s de r\u00e9paration et d\u00b4\u00e9ssai des v\u00e9hicules dans un d\u00e9lai imparti en fonction de la panne ;<\/li>\n<li>D\u00b4organiser\u00a0 une t\u00e2che et de travailler en \u00e9quipe ;<\/li>\n<li>De r\u00e9parer et v\u00e9rifier les syst\u00e8mes \u00e9l\u00e9ctriques et \u00e9lectroniques des v\u00e9hicules \u00e0 l\u00b4instar des batteries , alternateurs , climatiseurs , direction assist\u00e9e , alarmes , vitres etc..<\/li>\n<li>De r\u00e9diger un rapport d\u00b4activit\u00e9 dans un d\u00e9lai bien d\u00e9fini ;<\/li>\n<\/ul>\n<p>Les dossiers de candidature doivent etre compos\u00e9s d\u00b4un\u00a0CV, d\u00b4une lettre de motivation et de la photocopie de la carte nationale d\u00b4identit\u00e9\u00a0 \u00e0 jour\u00a0\u00e0 l\u00b4adresse suivante :\u00a0<a href=\"mailto:servicesbois@yahoo.com\"><strong>servicesbois@yahoo.com<\/strong><\/a><\/p>\n<p><strong>D\u00e9lai de d\u00e9pot de\u00a0 candidature: 15 Septembre 2020<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Offre d\u00b4emploi :\u00a0\u00c9lectricien Automobile Offre d\u00b4emploi n\u00b0 6768 publi\u00e9e le Lundi 17 Ao\u00fbt 2020 encore valable pour 28 jours. Postulation en ligne non autoris\u00e9e, si&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[408],"tags":[852],"villes":[136],"contrats":[236,234],"diplomes":[248],"louma_meta":{"emploi_title":"Offre d\u00b4emploi :\u00a0\u00c9lectricien Automobile","emplois_employeur":3046,"emplois_date_publication":"2020-08-19","emplois_heure_publication":"","emplois_date_cloture":"2020-09-19","emplois_heure_cloture":"","emplois_experience_min":"2","emplois_experience_max":"3","emploi_email":"servicesbois@yahoo.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/6143"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=6143"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/6143\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3031"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=6143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=6143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=6143"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=6143"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=6143"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=6143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}