{"id":5906,"date":"2020-08-12T10:51:06","date_gmt":"2020-08-12T08:51:06","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=5906"},"modified":"2020-08-12T10:51:06","modified_gmt":"2020-08-12T08:51:06","slug":"offre-demploi-lentreprise-mapris-recrute-plusieurs-profils","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/offre-demploi-lentreprise-mapris-recrute-plusieurs-profils\/","title":{"rendered":"Offre d&#8217;emploi : l&rsquo;entreprise MAPRIS recrute plusieurs profils"},"content":{"rendered":"<p>L&rsquo;entreprise MAPRIS, dans le cadre de ses activit\u00e9s recrute des professionnels. NOUS RECRUTONS<\/p>\n<p>\u2022 1 Technicien sup\u00e9rieur en ma\u00e7onnerie PRISE EN CHARGE D&rsquo;INFRASTRUCTURES IMMOBILI\u00c8RES REFECTIONS &#8211; R\u00c9PARATIONS FINITIONS<\/p>\n<p>\u2022 Des techniciens sup\u00e9rieurs en rev\u00eatements murs, sols et plafonds<\/p>\n<p>\u2022 1 Technicien sup\u00e9rieur en peinture et \u00e9tanch\u00e9it\u00e9<\/p>\n<p>\u2022 1 Technicien sup\u00e9rieur en menuiserie et \u00e9b\u00e9nisterie<\/p>\n<p>PROFIL ID\u00c9AL: BTS, moins de 33 ans, mobile et dynamique, aptitude \u00e0 s&rsquo;exprimer et \u00e0 r\u00e9diger.<\/p>\n<p>MODALIT\u00c9S PRATIQUES :<\/p>\n<p>Envoyez votre curriculum vitae (CV) et une lettre de motivation en pr\u00e9cisant en objet le domaine d&rsquo;activit\u00e9 vis\u00e9 \u00e0 l&rsquo;adresse suivante: mapris.assistance@gmail.com<\/p>\n<p>&#8211; Disponibilit\u00e9 de rigueur<\/p>\n<p>&#8211; Lieu : Yaound\u00e9<\/p>\n<p>&#8211; Date limite : 25 Ao\u00fbt 2020 (+237) 690 313 574 mapris.assistance@gmail.com y @MAPRIS ASSIST f Mapris Assistance MAPRIS MA PRIS L&rsquo;AS SISTAN CE QUI VOUS CONVIENT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;entreprise MAPRIS, dans le cadre de ses activit\u00e9s recrute des professionnels. NOUS RECRUTONS \u2022 1 Technicien sup\u00e9rieur en ma\u00e7onnerie PRISE EN CHARGE D&rsquo;INFRASTRUCTURES IMMOBILI\u00c8RES REFECTIONS&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[3],"tags":[784],"villes":[],"contrats":[236,234],"diplomes":[163,162,248,160,212],"louma_meta":{"emploi_title":"Offre d'emploi : l'entreprise MAPRIS recrute plusieurs profils","emplois_employeur":3046,"emplois_date_publication":"2020-08-12","emplois_heure_publication":"","emplois_date_cloture":"2020-08-25","emplois_heure_cloture":"","emplois_experience_min":"2","emplois_experience_max":"3","emploi_email":"mapris.assistance@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/5906"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=5906"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/5906\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3031"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=5906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=5906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=5906"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=5906"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=5906"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=5906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}