{"id":56249,"date":"2026-01-13T11:18:49","date_gmt":"2026-01-13T10:18:49","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=56249"},"modified":"2026-01-13T11:18:50","modified_gmt":"2026-01-13T10:18:50","slug":"charge-de-relation-clientele-pme-pmi","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2026\/charge-de-relation-clientele-pme-pmi\/","title":{"rendered":"Charg\u00e9 de Relation Client\u00e8le PME \/ PMI"},"content":{"rendered":"<p>DIRECTION DU RETAIL BANKING<br \/>\n\u00b7<br \/>\nCharg\u00e9 de Relation Client\u00e8le PME \/ PMI<br \/>\nProspection client\u00e8le<br \/>\nEntretien et d\u00e9veloppement du portefeuille client\u00e8le<br \/>\n\u00b7<br \/>\nSuivi de la relation client\u00e8le<br \/>\n\u2022<br \/>\nEtude et Analyse des demandes de financement<br \/>\n\u00b7<br \/>\nVente des produits et services bancaires<br \/>\nGestion administrative des dossiers des clients<br \/>\nEncadrement des \u00e9quipes junior<br \/>\nReporting des activit\u00e9s<br \/>\nRespect des proc\u00e9dures en mati\u00e8re de LAB-LFT<br \/>\nSuivi de portefeuille<br \/>\nRecouvrement pr\u00e9contentieux<br \/>\nExp\u00e9rience souhait\u00e9e :<br \/>\nMinimum 3 ans d&rsquo;exp\u00e9rience au poste de Charg\u00e9 de Relation Client\u00e8le Entreprises et\/ou au poste d&rsquo;analyste financier ou analyste cr\u00e9dit.<br \/>\nNiveau d&rsquo;\u00e9tude :<br \/>\nBac +4\/5 en Gestion\/ Banque\/ Finance\/ Action commerciale ou Analyse Financi\u00e8re Formation bancaire: ITB, BBS ou \u00e9quivalent.<br \/>\nQualit\u00e9s recherch\u00e9es :<br \/>\nVous faites preuve de rigueur, d&rsquo;adaptation, de grande capacit\u00e9 r\u00e9dactionnelle,<br \/>\nde sang-froid, d&rsquo;\u00e9coute, d&rsquo;int\u00e9grit\u00e9 et \u00eates force de proposition.<br \/>\n\u2022<br \/>\nVous \u00eates dot\u00e9 d&rsquo;un bon sens de l&rsquo;organisation.<br \/>\n\u00b7<br \/>\nVous avez de grandes qualit\u00e9s relationnelles et humaines, de r\u00e9elles capacit\u00e9s<br \/>\nd&rsquo;analyse et vous \u00eates r\u00e9actif \u00e0 mettre en place des actions.<br \/>\nVous avez le sens de la n\u00e9gociation ainsi que l&rsquo;esprit d&rsquo;initiative.<br \/>\nVous \u00eates orient\u00e9 performance.<br \/>\nLa maitrise de l&rsquo;anglais professionnel et de l&rsquo;outil informatique sont indispensables.<br \/>\nLa bonne maitrise du logiciel Amplitude est indispensable.<br \/>\nPermis de conduire, cat\u00e9gorie B.<br \/>\nR\u00e9f\/N\u00b0001\/01\/2026.BGFIBank Cameroun<\/p>\n<p>COMMENT POSTULER ?<br \/>\nEnvoyez vos candidatures \u00e0 l&rsquo;adresse : recrutement.bgfibankcameroun@bgfi.com Date limite 16\/01\/2026<br \/>\nBGFIBank<br \/>\nVotre partenaire pour l&rsquo;avenir<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via recrutement.bgfibankcameroun@bgfi.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[3636,23,1139],"tags":[],"villes":[135],"contrats":[148],"diplomes":[159],"louma_meta":{"emploi_title":"Charg\u00e9 de Relation Client\u00e8le PME \/ PMI","emplois_employeur":11226,"emplois_date_publication":"2026-01-13","emplois_heure_publication":"11:18","emplois_date_cloture":"2026-01-16","emplois_heure_cloture":"17:00","emplois_experience_min":"3","emplois_experience_max":"","emploi_email":"recrutement.bgfibankcameroun@bgfi.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/56249"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=56249"}],"version-history":[{"count":1,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/56249\/revisions"}],"predecessor-version":[{"id":56250,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/56249\/revisions\/56250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/11227"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=56249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=56249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=56249"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=56249"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=56249"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=56249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}