{"id":55170,"date":"2025-09-19T13:10:40","date_gmt":"2025-09-19T11:10:40","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=55170"},"modified":"2025-09-19T13:10:43","modified_gmt":"2025-09-19T11:10:43","slug":"une-stagiaire-chef-de-publicite-publix-media","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2025\/une-stagiaire-chef-de-publicite-publix-media\/","title":{"rendered":"Un(e) Stagiaire Chef de Publicit\u00e9 &#8211; PUBLIX MEDIA"},"content":{"rendered":"<p>Nous recherchons un(e) stagiaire pour le poste de Chef de Publicit\u00e9 pour rejoindre notre \u00e9quipe dynamique. Vous travaillerez aux c\u00f4t\u00e9s de nos sp\u00e9cialistes de la publicit\u00e9 pour d\u00e9velopper et mettre en \u0153uvre des campagnes publicitaires efficaces.<\/p>\n<p>Responsabilit\u00e9s<br \/>\n&#8211; Assister les chefs de publicit\u00e9 dans la cr\u00e9ation et la mise en \u0153uvre de campagnes publicitaires.<br \/>\n&#8211; R\u00e9aliser des recherches et analyses de march\u00e9.<br \/>\n&#8211; Collaborer avec les \u00e9quipes cr\u00e9atives pour d\u00e9velopper des contenus publicitaires.<\/p>\n<p>Profil<br \/>\n&#8211; \u00c9tudiant(e) en marketing, publicit\u00e9 ou domaine connexe.<br \/>\n&#8211; Connaissances en marketing et publicit\u00e9.<br \/>\n&#8211; Bonnes comp\u00e9tences en communication et en travail d&rsquo;\u00e9quipe.<\/p>\n<p>Dur\u00e9e du stage<br \/>\n&#8211; 3 \u00e0 6 mois, selon disponibilit\u00e9s.<\/p>\n<p>Avantages<br \/>\n&#8211; Exp\u00e9rience pratique dans le domaine de la publicit\u00e9.<br \/>\n&#8211; Opportunit\u00e9s de d\u00e9veloppement professionnel.<\/p>\n<p>COMMENT POSTULER :<br \/>\nEnvoyez votre CV et une lettre de motivation \u00e0 adresse e-mail: publixmedia3@gmail.com Nous nous r\u00e9jouissons de recevoir votre candidature<\/p>\n<p>Date limite de r\u00e9ception des candidatures : 19 Septembre 2025<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via publixmedia3@gmail.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[25,24],"tags":[],"villes":[135],"contrats":[152],"diplomes":[212],"louma_meta":{"emploi_title":"Un(e) Stagiaire Chef de Publicit\u00e9 - PUBLIX MEDIA","emplois_employeur":3046,"emplois_date_publication":"2025-09-19","emplois_heure_publication":"12:10","emplois_date_cloture":"2025-09-19","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"publixmedia3@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/55170"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=55170"}],"version-history":[{"count":1,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/55170\/revisions"}],"predecessor-version":[{"id":55171,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/55170\/revisions\/55171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=55170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=55170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=55170"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=55170"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=55170"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=55170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}