{"id":53944,"date":"2025-07-22T11:59:00","date_gmt":"2025-07-22T09:59:00","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=53944"},"modified":"2025-07-22T11:59:05","modified_gmt":"2025-07-22T09:59:05","slug":"expert-en-communication-h-f-pour-un-projet","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2025\/expert-en-communication-h-f-pour-un-projet\/","title":{"rendered":"\u00a0EXPERT EN COMMUNICATION (H\/F) POUR UN PROJET"},"content":{"rendered":"<p>Association Camerounaise pour le Marketing Social<br \/>\nAVIS D&rsquo;APPEL A CANDIDATURES POUR LE RECRUTEMENT D&rsquo;UN (01) EXPERT EN COMMUNICATION (H\/F) POUR UN PROJET AU SEIN DE L&rsquo;ACMS<br \/>\nL&rsquo;ACMS en bref !<br \/>\nL&rsquo;Association Camerounaise pour le Marketing Social (ACMS) est une organisation non gouvernementale de droit Camerounais qui a pour mission principale d&rsquo;am\u00e9liorer de mani\u00e8re durable et mesurable la situation sociale de la population camerounaise et de promouvoir la sant\u00e9. Ainsi, ACMS travaille en coop\u00e9ration avec le gouvernement et ses partenaires des secteurs public et priv\u00e9 pour offrir des programmes de sant\u00e9 de haute qualit\u00e9, atteignant toutes les populations dans le besoin. Depuis plus de vingt-cinq ans, ACMS offre \u00e0 la population camerounaise des interventions de sant\u00e9 publique compl\u00e8tes et fond\u00e9es sur des preuves, notamment des programmes dans la sant\u00e9 de la reproduction, le paludisme et la pr\u00e9vention du VIH entre autres.<br \/>\nRejoignez-nous !<br \/>\nACMS est \u00e0 la recherche des candidats pour occuper le poste d&rsquo;Expert en Communication (H\/F) dans le cadre d&rsquo;un projet au sein de l&rsquo;ACMS.<br \/>\nQui recrutons-nous?<br \/>\nL&rsquo;Expert en Communication aura la responsabilit\u00e9 d&rsquo;apporter un appui \u00e0 l&rsquo;\u00e9quipe des Programmes.<br \/>\nFonctions essentielles :<br \/>\n-Identifier les comportements cibles et les obstacles au changement;<br \/>\n-\u00c9valuer les facteurs qui influencent les comportements et les strat\u00e9gies de changement existantes;<br \/>\n-Effectuer une analyse des besoins et des contextes des communaut\u00e9s ou groupes cibles;<br \/>\n-Diriger le d\u00e9veloppement d&rsquo;une strat\u00e9gie de communication et de changement social et comportemental;<br \/>\n&#8211; Appuyer les objectifs du projet gr\u00e2ce \u00e0 la strat\u00e9gie de changement social et comportemental (SBC), en particulier en ce qui concerne les syst\u00e8mes alimentaires et la nutrition, ainsi que l&rsquo;agriculture, le genre, la gouvernance et l&rsquo;engagement communautaire;<br \/>\nACMS est un employeur garantissant l&rsquo;\u00e9galit\u00e9 des chances et encourage les candidatures f\u00e9minines.<br \/>\nInformations cl\u00e9s sur le poste :<br \/>\nType de contrat : Permanent,<br \/>\nNiveau du poste: 11\u00e8me cat\u00e9gorie, du secteur tertiaire Il de la Convention Collective Nationale du Commerce<br \/>\nLieu de travail : Yaound\u00e9<br \/>\nType de poste: Senior<br \/>\nDate de prise de fonction : Ao\u00fbt 2025<br \/>\nLa Directrice<\/p>\n<p>COMMENT POSTULER :<br \/>\nVotre dossier de candidature :<br \/>\nLes dossiers complets seront envoy\u00e9s uniquement \u00e0 l&rsquo;adresse suivante : CM_recrutement@acms-cmr.org<br \/>\nNotre politique d&#8217;emploi<br \/>\nL&rsquo;ACMS est un employeur qui souscrit au principe de l&rsquo;\u00e9galit\u00e9 des chances et encourage les candidatures qualifi\u00e9es des personnes de tous les sexes.<br \/>\nSeuls les candidats pr\u00e9s\u00e9lectionn\u00e9s seront contact\u00e9s.<br \/>\nL&rsquo;ACMS se r\u00e9serve le droit de proc\u00e9der \u00e0 un recrutement \u00e0 un niveau inf\u00e9rieur ou sur la base d&rsquo;un profil de poste modifi\u00e9.<br \/>\nLe candidat retenu devra passer une v\u00e9rification des ant\u00e9c\u00e9dents.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via CM_recrutement@acms-cmr.org<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[25],"tags":[],"villes":[136],"contrats":[236],"diplomes":[212,159],"louma_meta":{"emploi_title":" EXPERT EN COMMUNICATION (H\/F) POUR UN PROJET","emplois_employeur":3436,"emplois_date_publication":"2025-07-22","emplois_heure_publication":"10:58","emplois_date_cloture":"2025-07-25","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"CM_recrutement@acms-cmr.org"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/53944"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=53944"}],"version-history":[{"count":1,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/53944\/revisions"}],"predecessor-version":[{"id":53945,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/53944\/revisions\/53945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3437"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=53944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=53944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=53944"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=53944"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=53944"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=53944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}