{"id":5392,"date":"2020-07-29T04:31:11","date_gmt":"2020-07-29T02:31:11","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=5392"},"modified":"2020-07-29T04:31:11","modified_gmt":"2020-07-29T02:31:11","slug":"avis-de-recrutement-responsable-administratif-et-financier-raf-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/avis-de-recrutement-responsable-administratif-et-financier-raf-2\/","title":{"rendered":"Avis de recrutement : Responsable Administratif et Financier &#8211; RAF"},"content":{"rendered":"<p>R\u00c9PUBLIQUE DU CAMEROU \u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0REPUBLIC OF CAMEROON<\/p>\n<p>PAIX \u2013 TRAVAIL &#8211; PATRIE \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0PEACE \u2013 WORK &#8211; FATHERLAND<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212; \u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<table width=\"670\">\n<tbody>\n<tr>\n<td width=\"670\">AVIS DE RECRUTEMENT N\u00b0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \/GROUPEMENT\/2020\u00a0 DU<\/p>\n<p>POUR LE RECRUTEMENT RESPONSABLE ADMINISTRATIF ET FINANCIER DU GROUPEMENT<\/p>\n<p>MEGASOFT\/SNTPartners,\/GES<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Le Groupement MEGASOFT\/SNTPartners\/GLOBAL INGENEERING SOLUTIONS est adjudicataire du march\u00e9 de mise en \u0153uvre d\u2019un Observatoire Urbain, de la r\u00e9alisation de l\u2019Adressage et de l\u2019actualisation de la base de donn\u00e9es des imp\u00f4ts et des recettes municipales dans les villes de Brazzaville et de Pointe Noire ;march\u00e9 lanc\u00e9 par le\u00a0 Minist\u00e8re de l\u2019Am\u00e9nagement, de l\u2019Equipement du Territoire, des Grands Travaux\/Cellule d\u2019Ex\u00e9cution du Projet de D\u00e9veloppement Urbain et de Restructuration des Quartiers Pr\u00e9caires(DURQuaP) sur financement Banque Mondiale..<\/p>\n<p>A ce titre, il lance le pr\u00e9sent AVIS de RECRUTEMENT pour le recrutement d\u2019un Responsable Administratif et Financier pour l\u2019appuyer dans la mise en \u0153uvre de ce march\u00e9. Les Termes de R\u00e9f\u00e9rence du poste se d\u00e9clinent comme suit :<\/p>\n<p>Titre du poste : Responsable Administratif et Financier\u2013 RAF<\/p>\n<ol>\n<li>Fonctions et attributions<\/li>\n<\/ol>\n<p>Plac\u00e9 sous la responsabilit\u00e9 des Cabinets MEGASOFT et SNTPartners et sous le contr\u00f4le du Cabiner GLOBAL INGINEERING SOLUTIONS, le Responsable Administratif et Financier assure le fonctionnement administratif et la gestion financi\u00e8re et comptable du march\u00e9 ; notamment :<\/p>\n<ul>\n<li>l\u2019assistance \u00e0 ces derniers pour la gestion administrative, financi\u00e8re et comptable dans le cadre de ce march\u00e9<\/li>\n<li>le suivi des op\u00e9rations de mise \u00e0 disposition des fonds le suivi et la tenue des comptes ;<\/li>\n<li>l\u2019organisation et le suivi de l\u2019audit des comptes du march\u00e9<\/li>\n<li>le respect des proc\u00e9dures de d\u00e9caissement ;<\/li>\n<li>l\u2019archivage et la mise \u00e0 la disposition des auditeurs des pi\u00e8ces justificatives ;<\/li>\n<li>la tenue de la comptabilit\u00e9 mati\u00e8res du march\u00e9;<\/li>\n<li>le suivi rigoureux des proc\u00e9dures financi\u00e8res et Comptables adopt\u00e9es par le Groupement\n<ul>\n<li>Pr\u00e9paration des Projets de budget<\/li>\n<\/ul>\n<\/li>\n<li>Il s\u2019agira d\u2019\u00e9laborer un Projet de budget sur la base des \u00e9l\u00e9ments adopt\u00e9s par le Groupement\n<ul>\n<li>Suivi de la tenue des comptes et du contr\u00f4le interne de gestion<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Il s\u2019agira d\u2019effectuer un suivi quotidien, mensuel du budget du march\u00e9, avec la production des fiches d\u2019engagements quotidiens et des tableaux de bord \u00e0 consulter avant toute op\u00e9ration. Ceci permettra de r\u00e9aliser un contr\u00f4le permanent des op\u00e9rations\u00a0 financi\u00e8res.<\/p>\n<ul>\n<li>Suivi administratif et du personnel<\/li>\n<\/ul>\n<p>Il s\u2019agira de suivre d\u2019une part l\u2019entretien des \u00e9quipements et du mat\u00e9riel, les d\u00e9penses de consommation de carburant et d\u2019entretien des v\u00e9hicules, les formalit\u00e9s administratives relatives aux assurances des \u00e9quipements, la gestion des stocks de mati\u00e8res et fournitures, la gestion administrative des immobilisations et d\u2019autre part de suivre administrativement le personnel affect\u00e9 au march\u00e9 par la mise en place et de la tenue du fichier et des dossiers individuels du personnel, du suivi de la discipline du personnel, de la pr\u00e9paration des \u00e9l\u00e9ments de paie,<\/p>\n<ol start=\"2\">\n<li>Qualifications requises :<\/li>\n<\/ol>\n<ul>\n<li>avoir un dipl\u00f4me sup\u00e9rieur en Sciences de Gestion, (Comptabilit\u00e9, Gestion, Finance, Gestion des projets, Gestion de paie) (minimum Bac+4) ;<\/li>\n<li>Avoir un minimum de 3 (Trois) ann\u00e9es d\u2019exp\u00e9riences professionnelles dans les Finances parmi lesquelles de trois (2) ann\u00e9es d\u2019exp\u00e9rience professionnelles dans le domaine de la comptabilit\u00e9 et de gestion<\/li>\n<li>Avoir une bonne connaissance des proc\u00e9dures de financement de projets<\/li>\n<li>Avoir une connaissance de l\u2019outil informatique, et des logiciels courants (Word ; Excel ; Power point ; Email ; et autres outils de communication ; la connaissance d\u2019un logiciel de Gestion, suivi et \u00e9valuation est un atout)<\/li>\n<\/ul>\n<p>;<\/p>\n<ul>\n<li>Avoir une aptitude \u00e0 organiser son travail et \u00e0 travailler en \u00e9quipe ;<\/li>\n<li>Disposer d&rsquo;une bonne int\u00e9grit\u00e9 professionnelle ;<\/li>\n<li>Maitriser une des deux langues officielles et avoir une bonne connaissance de l\u2019autre.<\/li>\n<li>La connaissance des proc\u00e9dures des bailleurs (Banque Mondiale Banque Africaine de D\u00e9veloppement ,etc\u2026)est un atout.<\/li>\n<\/ul>\n<p>A cet effet, le Groupement, invite les consultants individuels \u00e0 pr\u00e9senter leur candidature en vue de fournir les services d\u00e9crits ci-dessus. Les candidats devront fournir des informations sur leur qualification et leur exp\u00e9rience afin de justifier leur exp\u00e9rience \u00e0 mener \u00e0 bien la mission propos\u00e9e (documents, r\u00e9f\u00e9rences dans les responsabilit\u00e9s similaires, exp\u00e9rience dans les missions du m\u00eame type, etc).<\/p>\n<p>3- Lieu et Dur\u00e9e du contrat<\/p>\n<p>Le contrat est un CDD de 12 mois Le lieu de service est Yaound\u00e9<\/p>\n<p>4-Dossier de Candidature<\/p>\n<p>Le dossier de candidature comprend :<\/p>\n<ul>\n<li>une demande adress\u00e9e \u00e0\u00a0<u>snt.ges.hr@gmail.com<\/u><\/li>\n<li>une lettre de motivation<\/li>\n<li>un Curriculum Vitae d\u00e9taill\u00e9 faisant \u00e9tat de la formation et de l\u2019exp\u00e9rience professionnelle \u00e0 jour et sign\u00e9 et (iii) copies des dipl\u00f4mes et copies des r\u00e9f\u00e9rences dans les responsabilit\u00e9s similaires.<\/li>\n<\/ul>\n<p>Pour toutes informations compl\u00e9mentaires, contacter :<\/p>\n<p><u>mega.snt.ges.hr@gmail.com<\/u>\u00a0699570903 ou 697494736<\/p>\n<p>Les dossiers complets doivent \u00eatre adress\u00e9s au Groupement MEGASOFT\/SNTPartners\/GES et envoy\u00e9 par courrier \u00e9lectronique \u00e0 l\u2019adresse email :\u00a0 mega.snt.ges.hr@gmail.com \u00a0au plus tard le 30 juillet 2020 \u00e0 12 heures pr\u00e9cises, portant la mention \u00ab AVIS DE RECRUTEMENT D\u2019UN RESPONSABLE ADMINISTRATIF ET FINANCIER POUR LA GESTION DU MARCHE DE MISE EN PLACE D\u2019UN OBSERVATOIRE URBAIN, DE LA REALISATION DE L\u2019ADRESSAGE ET DE L\u2019ACTUALISATION DE LA BASE DES DONNEES DES IMPOTS ET DES RECETTES MUNICIPALES DES VILLES DE BRAZZAVILLE ET DE POINTE NOIRE\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>YAOUNDE, LE\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026..<\/p>\n<p>Pour le Groupement,<\/p>\n<p>Ibrahim MOUKOUOP NGUENA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00c9PUBLIQUE DU CAMEROU \u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0REPUBLIC OF CAMEROON PAIX \u2013 TRAVAIL &#8211; PATRIE \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0PEACE \u2013 WORK &#8211;&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21,23],"tags":[637],"villes":[136],"contrats":[234],"diplomes":[162,212,159],"louma_meta":{"emploi_title":"Responsable Administratif et Financier","emplois_employeur":3875,"emplois_date_publication":"2020-07-29","emplois_heure_publication":"","emplois_date_cloture":"2020-07-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"mega.snt.ges.hr@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/5392"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=5392"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/5392\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3876"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=5392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=5392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=5392"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=5392"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=5392"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=5392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}