{"id":53860,"date":"2025-07-12T18:35:32","date_gmt":"2025-07-12T18:35:32","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2025\/blanchisseur-2\/"},"modified":"2025-07-12T21:06:46","modified_gmt":"2025-07-12T19:06:46","slug":"blanchisseur-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2025\/blanchisseur-2\/","title":{"rendered":"Blanchisseur"},"content":{"rendered":"<p>Nous avons besoin d&rsquo;un&nbsp;<strong>Blanchisseur<\/strong>&nbsp;ma&icirc;trisant le lavage en machine et le repassage professionnel.<\/p>\n<h3>Profil recherch&eacute; pour le poste : Blanchisseur Professionnel &#8211; Yaound&eacute;<\/h3>\n<ul>\n<li>Maitrise des tissus,&nbsp;<\/li>\n<li>maitrise des techniques de lavage en machine<\/li>\n<li>maitrise du repassage<\/li>\n<\/ul>\n<p><strong>Salaire :<\/strong><\/p>\n<ul>\n<li>100&nbsp;000&nbsp;FCFA&nbsp;\/ mois&nbsp;<\/li>\n<\/ul>\n<p>comment postuler?<\/p>\n<p>contacter nous sur whatsapp en indiquant que c&rsquo;est pour le poste de blanchisseur au 674706297<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous avons besoin d&rsquo;un&nbsp;Blanchisseur&nbsp;ma&icirc;trisant le lavage en machine et le repassage professionnel. Profil recherch&eacute; pour le poste : Blanchisseur Professionnel &#8211; Yaound&eacute; Maitrise des tissus,&nbsp;&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"open","template":"","categories":[3],"tags":[],"villes":[136],"contrats":[150],"diplomes":[156],"louma_meta":{"emploi_title":"Blanchisseur ","emplois_employeur":3046,"emplois_date_publication":"2025-07-12","emplois_heure_publication":"","emplois_date_cloture":"2025-08-10","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"wa.me\/message\/LXOOERAADPK3E1"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/53860"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=53860"}],"version-history":[{"count":1,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/53860\/revisions"}],"predecessor-version":[{"id":53884,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/53860\/revisions\/53884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=53860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=53860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=53860"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=53860"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=53860"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=53860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}