{"id":5307,"date":"2020-07-28T02:25:07","date_gmt":"2020-07-28T00:25:07","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=5307"},"modified":"2020-07-28T02:25:07","modified_gmt":"2020-07-28T00:25:07","slug":"chef-des-programmes-hop-responsable-des-politiques-de-programme-p4-pam","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/chef-des-programmes-hop-responsable-des-politiques-de-programme-p4-pam\/","title":{"rendered":"Chef des programmes (HoP) \/ Responsable des politiques de programme P4-PAM"},"content":{"rendered":"<table id=\"cF8FE42table\">\n<tbody>\n<tr>\n<td>\n<h2><span><span class=\"goog-text-highlight\">Chef des programmes (HoP) \/ Responsable des politiques de programme P4, Yaound\u00e9, Cameroun<\/span><\/span><\/h2>\n<\/td>\n<td class=\"pull-right\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"row\">\n<div>\n<div>\n<ul id=\"cats\" class=\"list-group\">\n<li class=\"list-group-item dropdown-toggle\"><span>Organisation:\u00a0<\/span><span>Programme alimentaire mondial des Nations Unies (PAM)<\/span><\/li>\n<li class=\"list-group-item dropdown-toggle\"><span>Pays:\u00a0<\/span><span>Cameroun<\/span><\/li>\n<li class=\"list-group-item dropdown-toggle\">City:\u00a0Yaound\u00e9, Cameroon<\/li>\n<li id=\"officeli\" class=\"list-group-item dropdown-toggle\">Office:\u00a0WFP Yaound\u00e9, Cameroon<\/li>\n<\/ul>\n<div class=\"container ag\"><\/div>\n<div id=\"doclinks\"><\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div id=\"job1595875051214\" class=\"job1595875051214\">\n<div>\n<div class=\"t1595875051214\">\n<p><strong><span>Le PAM recherche des candidats de la plus haute int\u00e9grit\u00e9 et du plus grand professionnalisme qui partagent nos principes humanitaires.<\/span><\/strong><\/p>\n<p><strong><span>La s\u00e9lection du personnel se fait sur une base concurrentielle et nous nous engageons \u00e0 promouvoir la diversit\u00e9 et l&rsquo;\u00e9quilibre entre les sexes.<\/span><\/strong><\/p>\n<p><span>\u00cates-vous un gestionnaire de programme int\u00e9ress\u00e9 \u00e0 d\u00e9velopper davantage votre exp\u00e9rience professionnelle tout en contribuant \u00e0 mettre fin \u00e0 la faim dans le monde?\u00a0Souhaitez-vous rejoindre le Programme alimentaire mondial des Nations Unies (PAM), une organisation tr\u00e8s r\u00e9put\u00e9e qui apporte des changements positifs dans la vie des personnes touch\u00e9es par des difficult\u00e9s?\u00a0Souhaitez-vous rejoindre une organisation mondiale qui investit dans son personnel?<\/span><\/p>\n<p><span>Si votre r\u00e9ponse est oui, alors c&rsquo;est une excellente opportunit\u00e9 pour vous de devenir membre \u00e0 part enti\u00e8re d&rsquo;une \u00e9quipe diversifi\u00e9e et passionn\u00e9e qui travaille sur des projets vari\u00e9s et internationaux contribuant directement \u00e0 l&rsquo;assistance aux b\u00e9n\u00e9ficiaires.<\/span><\/p>\n<p><strong><span>\u00c0 propos du PAM<\/span><\/strong><\/p>\n<p><span>Le PAM est la plus grande agence humanitaire au monde qui lutte contre la faim dans le monde.\u00a0Notre mission est d&rsquo;aider le monde \u00e0 atteindre la Faim Z\u00e9ro au cours de nos vies.\u00a0Avec plus de 18 000 coll\u00e8gues dans le monde, le PAM s&rsquo;efforce de garantir qu&rsquo;aucun enfant ne se couche le ventre vide et que les plus pauvres et les plus vuln\u00e9rables, en particulier les femmes et les enfants, ainsi que les personnes touch\u00e9es par les catastrophes, puissent acc\u00e9der aux aliments nutritifs dont ils ont besoin.<\/span><\/p>\n<p><strong><span>Pourquoi devriez-vous rejoindre le PAM?<\/span><\/strong><\/p>\n<ul>\n<li><span>Chaque ann\u00e9e, le PAM aide plus de 86 millions de personnes dans 83 pays.\u00a0Votre travail aura un impact positif sur la vie des personnes les plus vuln\u00e9rables du monde<\/span><\/li>\n<li><span>La mani\u00e8re dont le PAM sert les personnes affam\u00e9es et affect\u00e9es &#8211; y compris les femmes, les groupes minoritaires, les enfants et les personnes \u00e2g\u00e9es &#8211; est vraiment importante pour leur s\u00e9curit\u00e9 et leur dignit\u00e9<\/span><\/li>\n<li><span>Vous rejoindrez une \u00e9quipe diversifi\u00e9e de professionnels et aurez la chance d&rsquo;\u00e9changer votre exp\u00e9rience et votre expertise avec vos coll\u00e8gues<\/span><\/li>\n<li><span>Le PAM investit dans la formation et le d\u00e9veloppement de ses employ\u00e9s gr\u00e2ce \u00e0 une gamme de programmes de formation, d&rsquo;accr\u00e9ditation, de mentorat et d&rsquo;autres programmes ainsi que des possibilit\u00e9s de mobilit\u00e9 interne<\/span><\/li>\n<li><span>Notre \u00e9quipe se d\u00e9veloppe \u00e0 l&rsquo;international et le moment choisi pour nous rejoindre ne peut \u00eatre meilleur!<\/span><\/li>\n<li><span>Nous proposons un package de r\u00e9mun\u00e9ration attractif (veuillez vous r\u00e9f\u00e9rer \u00e0 la section Termes et Conditions)<\/span><\/li>\n<\/ul>\n<p><strong><span>PAM Cameroun<\/span><\/strong><\/p>\n<p><span>Le PAM est l&rsquo;un des principaux acteurs humanitaires et de d\u00e9veloppement au Cameroun.\u00a0Le plan strat\u00e9gique de pays du PAM couvre la p\u00e9riode 2018-2021 et se concentre sur les r\u00e9sultats strat\u00e9giques suivants: Les populations vuln\u00e9rables touch\u00e9es par les catastrophes et les d\u00e9placements prolong\u00e9s, et les communaut\u00e9s en situation d&rsquo;ins\u00e9curit\u00e9 alimentaire chronique ont un acc\u00e8s s\u00fbr \u00e0 une alimentation ad\u00e9quate et nutritive et augmentent leur r\u00e9silience aux chocs , les enfants \u00e2g\u00e9s de 6 \u00e0 59 mois et les femmes et hommes vuln\u00e9rables dans les districts prioritaires en situation d&rsquo;ins\u00e9curit\u00e9 alimentaire ont r\u00e9duit les taux de malnutrition, les petits exploitants en situation d&rsquo;ins\u00e9curit\u00e9 alimentaire ont augment\u00e9 leurs revenus de mani\u00e8re durable pour am\u00e9liorer leur autosuffisance et leurs moyens de subsistance et am\u00e9liorer leur productivit\u00e9, en soutenant les capacit\u00e9s nationales en mati\u00e8re de protection sociale et la pr\u00e9paration aux catastrophes.<\/span><\/p>\n<p><strong><span>Le r\u00f4le<\/span><\/strong><\/p>\n<p><span>Le PAM Cameroun est \u00e0 la recherche d&rsquo;un chef de programme (HoP) \/ Administrateur des politiques de programme au niveau P4 pour \u00e9laborer, g\u00e9rer et mettre en \u0153uvre les programmes et politiques du PAM afin de relever certains des d\u00e9fis critiques auxquels sont confront\u00e9es les personnes vuln\u00e9rables, y compris les r\u00e9fugi\u00e9s et les personnes d\u00e9plac\u00e9es \u00e0 l&rsquo;int\u00e9rieur du pays. pays.\u00a0Le HoP sera responsable d&rsquo;une \u00e9quipe diversifi\u00e9e d&rsquo;environ 20 professionnels nationaux et internationaux travaillant dans divers domaines programmatiques tels que les interventions d&rsquo;urgence (en nature et en esp\u00e8ces), la nutrition, les moyens de subsistance et le renforcement de la r\u00e9silience, et les repas scolaires.\u00a0L&rsquo;op\u00e9ration du PAM au Cameroun est actuellement en pleine expansion et s&rsquo;adapte pour r\u00e9pondre aux besoins imm\u00e9diats croissants r\u00e9sultant de la crise du COVID-19.<\/span><\/p>\n<p><span>Le titulaire du poste rel\u00e8vera directement du directeur de pays adjoint et travaillera en \u00e9troite collaboration avec les chefs d&rsquo;autres unit\u00e9s (par exemple, cha\u00eene d&rsquo;approvisionnement, gestion des ressources, finances, partenariats et rapports) pour s&rsquo;assurer que les programmes du PAM sont int\u00e9gr\u00e9s de mani\u00e8re coh\u00e9rente dans le programme Paix-Humanitaire- Lien de d\u00e9veloppement.<\/span><\/p>\n<p><span>Le HoP assurera la liaison avec le Bureau r\u00e9gional et le si\u00e8ge pour suivre les orientations du programme et mettre en \u0153uvre les derniers enseignements tir\u00e9s des activit\u00e9s programmatiques au Cameroun ainsi que les nouvelles initiatives potentielles.<\/span><\/p>\n<p><strong><span>Principales responsabilit\u00e9s<\/span><\/strong><\/p>\n<ul>\n<li><span>Diriger et inspirer une \u00e9quipe d&rsquo;une vingtaine de professionnels diversifi\u00e9s, d\u00e9finir et suivre les priorit\u00e9s, g\u00e9rer les performances et offrir des conseils et des opportunit\u00e9s de carri\u00e8re et de d\u00e9veloppement professionnel<\/span><\/li>\n<li><span>Formuler des plans de programme du PAM conformes \u00e0 la fois \u00e0 la strat\u00e9gie organisationnelle et aux r\u00e9alit\u00e9s pratiques de l&rsquo;intervention sur le terrain au Cameroun;<\/span><\/li>\n<li><span>Fournir des conseils et un appui aux bureaux ext\u00e9rieurs ex\u00e9cutant un portefeuille complexe de programmes afin de lever les ambigu\u00eft\u00e9s et de garantir que les politiques et les programmes sont conformes aux politiques du PAM,<\/span><\/li>\n<li><span>Faire preuve de leadership dans la mobilisation de l&rsquo;expertise technique sur un large \u00e9ventail de programmes et de questions de politique, y compris l&rsquo;\u00e9valuation, l&rsquo;analyse, le choix des objectifs, les activit\u00e9s, les modalit\u00e9s de transfert et les produits alimentaires appropri\u00e9s.\u00a0Faciliter le d\u00e9ploiement et le test d&rsquo;approches innovantes et d\u00e9velopper des strat\u00e9gies pour soutenir les efforts du gouvernement pour r\u00e9duire la faim et la malnutrition.<\/span><\/li>\n<li><span>Aider les principales parties prenantes du gouvernement et d&rsquo;autres partenaires \u00e0 identifier les priorit\u00e9s et les besoins en mati\u00e8re d&rsquo;aide alimentaire du pays et de sa population.\u00a0Fournir un soutien et une expertise technique pour la planification, le d\u00e9veloppement et la mise en \u0153uvre de programmes visant \u00e0 renforcer l&rsquo;appropriation par le gouvernement et la communaut\u00e9 et l&rsquo;efficacit\u00e9 de la s\u00e9curit\u00e9 alimentaire et de la nutrition aux niveaux national et infranational.<\/span><\/li>\n<li><span>D\u00e9velopper et maintenir les partenariats strat\u00e9giques \u00e9tablis pour identifier les opportunit\u00e9s d&rsquo;initiatives de collaboration qui am\u00e9liorent les programmes d&rsquo;assistance et soutiennent le travail de plaidoyer<\/span><\/li>\n<li><span>Renforcer le statut de chef de file du PAM dans diff\u00e9rents forums sur des sujets li\u00e9s \u00e0 la s\u00e9curit\u00e9 alimentaire, \u00e0 la nutrition, aux moyens de subsistance, \u00e0 la r\u00e9silience, \u00e0 l&rsquo;engagement dans les contextes humanitaire, de transition et de d\u00e9veloppement et \u00e0 d&rsquo;autres questions connexes gr\u00e2ce \u00e0 une participation directe, des s\u00e9ances d&rsquo;information, des produits d&rsquo;information et d&rsquo;autres mat\u00e9riels.<\/span><\/li>\n<li><span>Contribuer \u00e0 la conception et aux efforts de mobilisation des ressources, y compris l&rsquo;\u00e9laboration et la r\u00e9daction des propositions de projets et de leurs budgets;<\/span><\/li>\n<li><span>Assurer le leadership pour \u00e9tablir des syst\u00e8mes de surveillance solides et coordonner la collecte de donn\u00e9es, en veillant \u00e0 ce que des normes de qualit\u00e9 rigoureuses soient maintenues;<\/span><\/li>\n<li><span>G\u00e9rer ou superviser la pr\u00e9paration et la diffusion en temps opportun de rapports analytiques, de publications et d&rsquo;une vari\u00e9t\u00e9 de produits d&rsquo;information ou de propositions \u00e0 usage interne ou externe;<\/span><\/li>\n<li><span>Assurer la meilleure utilisation des ressources financi\u00e8res allou\u00e9es pour atteindre les objectifs fix\u00e9s dans le cadre d&rsquo;un budget important.<\/span><\/li>\n<li><span>Prendre la responsabilit\u00e9 d&rsquo;incorporer les perspectives de genre et de protection dans tous les domaines de travail, afin d&rsquo;assurer une participation \u00e9gale des femmes et des hommes.<\/span><\/li>\n<li>\n<div class=\"md-chip md-chip-raised md-chip-hover\"><\/div>\n<\/li>\n<\/ul>\n<ul>\n<li><span>Contribuer \u00e0 la pr\u00e9paration aux situations d&rsquo;urgence des bureaux de pays, c&rsquo;est-\u00e0-dire \u00e0 l&rsquo;alerte pr\u00e9coce, \u00e0 l&rsquo;analyse des risques et \u00e0 la planification d&rsquo;urgence afin de r\u00e9pondre aux crises et aux besoins humanitaires.<\/span><\/li>\n<li><span>Autre au besoin<\/span><\/li>\n<\/ul>\n<p><strong><span>Au propos de vous<\/span><\/strong><\/p>\n<ul>\n<li><span>Vous avez la passion d&rsquo;am\u00e9liorer la vie de millions de personnes vivant dans la pauvret\u00e9 et la faim;<\/span><\/li>\n<li><span>Vous avez une solide exp\u00e9rience dans la gestion d&rsquo;\u00e9quipes et de programmes dans des contextes humanitaires et de d\u00e9veloppement complexes, vous vous tenez au courant des derniers d\u00e9veloppements politiques sur un \u00e9ventail de questions humanitaires, y compris le lien entre l&rsquo;action humanitaire et le d\u00e9veloppement;<\/span><\/li>\n<li><span>Vous \u00eates tr\u00e8s adaptatif et capable de communiquer efficacement avec des publics diversifi\u00e9s qui pourraient ne pas partager les m\u00eames connaissances techniques;<\/span><\/li>\n<li><span>Vous pouvez prioriser et trouver un \u00e9quilibre entre les objectifs id\u00e9aux et les exigences op\u00e9rationnelles, et traduire les objectifs de genre et de protection en r\u00e9sultats tangibles sur le terrain<\/span><\/li>\n<\/ul>\n<p><strong><span>Qualifications et exigences cl\u00e9s<\/span><\/strong><\/p>\n<ul>\n<li><span>Dipl\u00f4me universitaire sup\u00e9rieur en affaires internationales, \u00e9conomie, nutrition \/ sant\u00e9, agriculture, sciences de l&rsquo;environnement, sciences sociales ou autre domaine pertinent pour l&rsquo;aide au d\u00e9veloppement international.<\/span><\/li>\n<li><span>Au moins huit ans d&rsquo;exp\u00e9rience professionnelle dans le domaine de l&rsquo;aide humanitaire et \/ ou des travaux de d\u00e9veloppement, dans des organisations internationales gouvernementales ou non gouvernementales.<\/span><\/li>\n<li><span>Solide connaissance et exp\u00e9rience des processus de planification strat\u00e9gique des pays;<\/span><\/li>\n<li><span>Exp\u00e9rience av\u00e9r\u00e9e de la coordination et du travail interinstitutions en r\u00e9ponse aux crises;<\/span><\/li>\n<li><span>Comp\u00e9tences \u00e9prouv\u00e9es en communication et capacit\u00e9 \u00e0 communiquer et \u00e0 adapter le style de communication \u00e0 diff\u00e9rents publics.<\/span><\/li>\n<\/ul>\n<p><strong><span>Additionnel \/ Nice ont des exigences:<\/span><\/strong><\/p>\n<ul>\n<li><span>Exp\u00e9rience de travail ant\u00e9rieure dans une agence des Nations Unies sur le terrain ou au niveau national;<\/span><\/li>\n<li><span>Exp\u00e9rience dans le renforcement des capacit\u00e9s du travail gouvernemental<\/span><\/li>\n<li><span>Connaissance de l&rsquo;\u00e9tablissement de relations avec les parties prenantes et capacit\u00e9 \u00e0 impliquer diff\u00e9rentes parties prenantes,<\/span><\/li>\n<li><span>Connaissance et exp\u00e9rience de la coordination interinstitutions dans les situations humanitaires<\/span><\/li>\n<li><span>Une exp\u00e9rience ant\u00e9rieure en Afrique de l&rsquo;Ouest et centrale, y compris une connaissance de la dynamique politique de la r\u00e9gion est un atout.<\/span><\/li>\n<li><span>Exp\u00e9rience dans diff\u00e9rentes approches de programme, y compris la gestion des op\u00e9rations d&rsquo;intervention d&rsquo;urgence en utilisant diff\u00e9rentes modalit\u00e9s de transfert;<\/span><\/li>\n<li><span>A collabor\u00e9 avec des agences gouvernementales pour identifier les besoins et mettre en \u0153uvre des programmes d&rsquo;assistance alimentaire;<\/span><\/li>\n<li><span>A dirig\u00e9 une \u00e9quipe lors de discussions strat\u00e9giques.<\/span><\/li>\n<\/ul>\n<p><strong><span>Langue<\/span><\/strong><span>\u00a0:<\/span><\/p>\n<ul>\n<li><span>Ma\u00eetrise (niveau C) du fran\u00e7ais et de l&rsquo;anglais.<\/span><\/li>\n<li><span>Connaissance interm\u00e9diaire (niveau B) d&rsquo;une deuxi\u00e8me langue officielle de l&rsquo;ONU: arabe, chinois, fran\u00e7ais, russe, espagnol et \/ ou langue de travail du PAM, portugais<\/span><\/li>\n<\/ul>\n<p><strong><span>DATE DE CL\u00d4TURE<\/span><\/strong><span>\u00a0:\u00a0<\/span><strong><span>27 ao\u00fbt 2020<\/span><\/strong><\/p>\n<p><strong><span>Num\u00e9ro VA: 123483<\/span><\/strong><\/p>\n<p><strong><span>Termes et conditions<\/span><\/strong><\/p>\n<p><span>La mobilit\u00e9 est, et continue d&rsquo;\u00eatre, une exigence contractuelle fondamentale au PAM.\u00a0Le candidat s\u00e9lectionn\u00e9 sera employ\u00e9 sous contrat \u00e0 dur\u00e9e d\u00e9termin\u00e9e avec une p\u00e9riode probatoire d&rsquo;un an.<\/span><\/p>\n<p><span>Le PAM offre une r\u00e9mun\u00e9ration et des avantages sociaux attrayants, notamment un salaire de base, un ajustement de poste, un droit \u00e0 la r\u00e9installation, des indemnit\u00e9s de d\u00e9placement et d&rsquo;exp\u00e9dition, 30 jours de cong\u00e9 annuel, un cong\u00e9 dans les foyers, une allocation pour frais d&rsquo;\u00e9tudes pour les enfants \u00e0 charge, un r\u00e9gime de retraite et une assurance m\u00e9dicale.\u00a0Pour plus de d\u00e9tails, veuillez visiter icsc.un.org.<\/span><\/p>\n<p><span>Les candidates qualifi\u00e9es et les candidates qualifi\u00e9es des pays en d\u00e9veloppement sont particuli\u00e8rement encourag\u00e9es \u00e0 postuler<\/span><\/p>\n<p><span>Le PAM a une tol\u00e9rance z\u00e9ro pour la discrimination et ne fait pas de discrimination sur la base du statut VIH \/ sida<\/span><\/p>\n<p><span>Aucune nomination au titre de quelque type de contrat que ce soit ne sera propos\u00e9e aux membres du Comit\u00e9 consultatif des Nations Unies pour les questions administratives et budg\u00e9taires (CCQAB), de la Commission de la fonction publique internationale (CFPI), du Comit\u00e9 financier de la FAO, du Commissaire aux comptes du PAM, du Comit\u00e9 d&rsquo;audit du PAM, du Corps commun d&rsquo;inspection ( CCI) et d\u2019autres organes similaires au sein du syst\u00e8me des Nations Unies ayant des responsabilit\u00e9s de supervision du PAM, tant pendant leur service que dans les trois ans suivant la cessation de ce service.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Chef des programmes (HoP) \/ Responsable des politiques de programme P4, Yaound\u00e9, Cameroun Organisation:\u00a0Programme alimentaire mondial des Nations Unies (PAM) Pays:\u00a0Cameroun City:\u00a0Yaound\u00e9, Cameroon Office:\u00a0WFP Yaound\u00e9,&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[436],"tags":[128,616,7],"villes":[],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Chef des programmes (HoP) \/ Responsable des politiques de programme P4-PAM","emplois_employeur":2947,"emplois_date_publication":"2020-07-28","emplois_heure_publication":"","emplois_date_cloture":"2020-08-28","emplois_heure_cloture":"","emplois_experience_min":"2","emplois_experience_max":"4","emploi_email":"https:\/\/career5.successfactors.eu\/career?_s.crb=yY0OSJsIwAgV3li72DgSvu8%252b29RoJivOiWu7CUUwyyo%253d"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/5307"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=5307"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/5307\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2948"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=5307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=5307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=5307"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=5307"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=5307"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=5307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}