{"id":5288,"date":"2020-07-27T05:28:54","date_gmt":"2020-07-27T03:28:54","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=5288"},"modified":"2020-07-27T05:30:33","modified_gmt":"2020-07-27T03:30:33","slug":"avis-de-recrutement-huit-08-travailleurs-sociaux","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/avis-de-recrutement-huit-08-travailleurs-sociaux\/","title":{"rendered":"Avis de recrutement : huit (08) Travailleurs Sociaux"},"content":{"rendered":"<p><strong>AVIS DE RECRUTEMENT DE TRAVAILLEURS SOCIAUX (TS)<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Date de publication du\u00a0poste<\/strong>\u00a0<strong>:\u00a0<\/strong>24 Juillet 2020<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>L\u2019ONG Children\u2019s Life in Rural Area (CLiRA) recrute\u00a0<strong>huit (08)<\/strong>\u00a0Travailleurs Sociaux exp\u00e9riment\u00e9s et hautement qualifi\u00e9s afin\u00a0d\u2019assurer\u00a0la mise en \u0153uvre des activit\u00e9s relatives \u00e0 la promotion de l\u2019Education Inclusive, dans les localit\u00e9s cibl\u00e9es par le projet.<\/p>\n<p>A propos de CLiRA<\/p>\n<p>Children\u2019s Life in Rural Area (CLiRA) est une Organisation Internationale non Gouvernementale ivoirienne, qui intervient dans les domaines de la protection de l\u2019enfance, des droits de la femme, de la sant\u00e9, du d\u00e9veloppement communautaire et de la pr\u00e9vention et la gestion de conflits. CLiRA est pr\u00e9sente en C\u00f4te d\u2019Ivoire, en R\u00e9publique Centrafricaine et au Cameroun.<\/p>\n<p><strong>A propos de CLiRA au Cameroun<\/strong><\/p>\n<p>Pr\u00e9sente de 2017 au Cameroun, CLiRA a collabor\u00e9 avec plusieurs partenaires strat\u00e9giques sur la mise en \u0153uvre de projets et de programmes divers en faveur des populations en g\u00e9n\u00e9ral et des enfants en particulier, dans les R\u00e9gions du Nord et de l\u2019Extr\u00eame-Nord.<\/p>\n<p>Avec son partenaire technique et financier UNICEF, CLiRA s\u2019engage dans un nouveau projet dans trois (03) D\u00e9partements de l\u2019extr\u00eame nord au profit des enfants exclus du syst\u00e8me \u00e9ducatif \u00a0pour des raisons socioculturelles et religieuses. C\u2019est dans ce cadre que CLiRA lance le pr\u00e9sent appel \u00e0 candidature pour le recrutement de huit (8) Travailleurs Sociaux (TS).<\/p>\n<p><strong>Des<\/strong>cription du post<strong>e<\/strong><\/p>\n<p>Le Travailleur Social est charg\u00e9 de la mise en \u0153uvre des interventions relatives \u00e0 la promotion de l\u2019Education Inclusive.<\/p>\n<p>Sous la responsabilit\u00e9 hi\u00e9rarchique du Coordonnateur de Projet, il\/elle r\u00e9alisera les t\u00e2ches \u00e0 lui confi\u00e9es.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Missions et Responsabilit\u00e9s<\/strong><\/p>\n<ul>\n<li>Mettre en \u0153uvre des activit\u00e9s programmatiques,<\/li>\n<li>Organiser la mise en place et\/ou la redynamiser les structures communautaires de protection,<\/li>\n<li>Organiser des s\u00e9ances de sensibilisation dans les \u00e9tablissements scolaires sur l\u2019\u00e9ducation inclusive, le genre, les droits humains et la parentalit\u00e9 positive,<\/li>\n<li>Appuyer l\u2019organisation de journ\u00e9es culturelles \u00ab Child protection \u00bb et \u00e0 la JEA 2021 dans les \u00e9tablissements scolaires partenaires,<\/li>\n<li>Identifier et organiser des groupes de parole au profit des maitres coraniques sur l&rsquo;\u00e9ducation inclusive et la protection des enfants,<\/li>\n<li>Identifier et former les structures communautaires (APE, AME) et les autorit\u00e9s locales sur l\u2019\u00e9ducation inclusive et la protection des enfants,<\/li>\n<li>Mettre en place\/redynamiser et former les RECOPE, les clubs d\u2019adolescents sur l\u2019\u00e9ducation inclusive et la protection des enfants,<\/li>\n<li>Assurer la promotion de l\u2019\u00e9ducation inclusive, du genre, des droits humains et de la parentalit\u00e9 positive,<\/li>\n<li>Organiser les s\u00e9ances d\u2019information grand public et de dialogues interg\u00e9n\u00e9rationnels sur l\u2019\u00e9ducation inclusive, le genre, les droits humains et la parentalit\u00e9 positive,<\/li>\n<li>Assister les enfants identifi\u00e9s \u00e0 risque de d\u00e9scolarisation, d\u00e9scolaris\u00e9s ou de mariage (\u00e2ge, sexe, handicap, orphelin),<\/li>\n<li>Former les points focaux \u00ab \u00e9ducation inclusive \u00bb et leurs responsables hi\u00e9rarchiques sur la protection, l&rsquo;\u00e9ducation inclusive, le genre, les droits humains et la parentalit\u00e9 positive,<\/li>\n<li>Identifier et suivre les d\u2019enfants victimes d\u2019in\u00e9galit\u00e9s en particulier les filles (\u00e0 risque\/victimes de mariage d\u2019enfant) et les enfants vivant avec handicap,<\/li>\n<li>Toutes autres t\u00e2ches demand\u00e9es par les responsables entrant dans les interventions de CLIRA sur le terrain.<\/li>\n<\/ul>\n<p><strong>Qualifications requises<u>\u00a0:<\/u><\/strong><\/p>\n<ul>\n<li>Ma\u00eetrise des normes sociales d\u00e9favorables aux enfants les emp\u00eachant de b\u00e9n\u00e9ficier de l\u2019\u00e9ducation formelle,<\/li>\n<li>Maitrise des approches, strat\u00e9gies et\/ou m\u00e9thodes d\u2019intervention communautaire et de Protection de l\u2019Enfance,<\/li>\n<li>Techniques de communication interpersonnelle (animation de groupes, focus group, \u00e9missions radiophoniques, counseling, etc.),<\/li>\n<li>Collecte, traitement et analyse sommaires et transmission des donn\u00e9es,<\/li>\n<li>Facilit\u00e9 de travail avec les enfants et empathie avec les enfants d\u00e9favoris\u00e9s.<\/li>\n<\/ul>\n<p><strong>Exigences du poste<\/strong><\/p>\n<ol>\n<li><strong>Education<\/strong><\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ul>\n<li>Avoir un dipl\u00f4me BAC+3 au moins en Sciences sociales de pr\u00e9f\u00e9rence ou dans d\u2019autres domaines des sciences sociales comme le droit, la sociologie, la psychologie.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ol start=\"2\">\n<li><strong>Exp\u00e9riences<\/strong><\/li>\n<\/ol>\n<p><strong>\u00a0<\/strong><\/p>\n<ul>\n<li>Avoir une exp\u00e9rience d&rsquo;au moins deux (02) ans\u00a0dans un poste similaire<br \/>\nau sein d&rsquo;une ONG Internationale ou Nationale reconnue ou dans le domaine de la Protection de l\u2019enfant,<\/li>\n<li>Justifier d\u2019une bonne \u00e9valuation en termes de respect des valeurs et des principes humanitaires.<\/li>\n<li>La connaissance de la r\u00e9gion de l\u2019Extr\u00eame-Nord est un atout.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"3\">\n<li><strong>Langues<\/strong><\/li>\n<\/ol>\n<p><strong>\u00a0<\/strong><\/p>\n<ul>\n<li>Parler et \u00e9crire dans un fran\u00e7ais courant<\/li>\n<li>Parler au moins une des langues locales des zones d\u2019intervention du projet (Mandara, kotoko, Kanuri et Arabe) est un atout.<\/li>\n<\/ul>\n<p><strong>Connaissances<\/strong><\/p>\n<ul>\n<li>Bonne capacit\u00e9 en r\u00e9daction de synth\u00e8ses et de rapport<\/li>\n<li>Bonne connaissance informatique de Pack Windows (Word, Excel, Power point, au moins) et utilisation internet et des r\u00e9seaux sociaux (WhatsApp, Messenger, etc.)<\/li>\n<li>Bonne capacit\u00e9 organisationnelle et travail en \u00e9quipe<\/li>\n<li>Connaissance des langues locales arabe, Mandara, Kotoko, Arabe Shoa et Fulfulde est un atout.<\/li>\n<\/ul>\n<p>Comp\u00e9tences<\/p>\n<ul>\n<li>Planification d&rsquo;activit\u00e9s,<\/li>\n<li>Bon esprit d&rsquo;\u00e9quipe et de gestion des conflits,<\/li>\n<li>Flexibilit\u00e9,<\/li>\n<li>Excellentes capacit\u00e9s d&rsquo;analyse et de synth\u00e8se,<\/li>\n<li>Esprit d\u2019initiative et innovation,<\/li>\n<li>Rigueur dans le travail et la gestion du temps,<\/li>\n<li>Respect des valeurs et exigences de CLIRA.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong><em>les candidatures f\u00e9minines sont encourag\u00e9es<\/em><\/strong><\/li>\n<li><strong><em>la d\u00e9tention d&rsquo;un permis de conduire de v\u00e9hicules de deux ou \u00e0 quatre roues est un atout.<\/em><\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Comment postuler<\/strong><\/p>\n<p>Les candidats int\u00e9ress\u00e9s sont invit\u00e9s \u00e0\u00a0<strong>postuler<\/strong>\u00a0en joignant\u00a0:\u00a0Lettre de Motivation adress\u00e9e au Chef de Mission de CLiRA Cameroun, Curriculum Vitae d\u00e9taill\u00e9, Photocopie du dipl\u00f4me requis et\u00a0 les Photocopies des documents justifiant l&rsquo;exp\u00e9rience (certificat de travail, attestation de stage, attestation d&#8217;emplois)\u00a0\u00e0 l\u2019adresse suivante\u00a0:\u00a0<a href=\"mailto:info@clira.org\"><strong>info@clira.org<\/strong><\/a>\u00a0avec en objet du message :<\/p>\n<p><strong>\u00ab\u00a0Travailleur Social &#8211; CLiRA \u2013 Extr\u00eame-Nord &#8211; Cameroun\u00bb.<\/strong><\/p>\n<p>Le CV doit mentionner le nom, le poste et les coordonn\u00e9es\u00a0<strong>d&rsquo;au moins deux r\u00e9f\u00e9rences<\/strong>, y compris le responsable hi\u00e9rarchique lors de votre dernier emploi.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Seulement les candidats short-list\u00e9s seront contact\u00e9s pour<\/strong>\u00a0<strong>le Test \u00e9crit et seuls les candidats retenus au test \u00e9cris participeront \u00e0 l\u2019entretien final<\/strong><strong>.<\/strong><\/p>\n<p><strong>Date limite d\u00e9p\u00f4t\u00a0:\u00a0<\/strong>vendredi 07 Ao\u00fbt 2020\u00a0\u00e0 17 h 00, GMT.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AVIS DE RECRUTEMENT DE TRAVAILLEURS SOCIAUX (TS) &nbsp; Date de publication du\u00a0poste\u00a0:\u00a024 Juillet 2020 \u00a0 L\u2019ONG Children\u2019s Life in Rural Area (CLiRA) recrute\u00a0huit (08)\u00a0Travailleurs Sociaux&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[436],"tags":[612],"villes":[136],"contrats":[234],"diplomes":[163,162,212],"louma_meta":{"emploi_title":"Avis de recrutement : huit (08) Travailleurs Sociaux","emplois_employeur":5289,"emplois_date_publication":"2020-07-27","emplois_heure_publication":"","emplois_date_cloture":"2020-08-07","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"info@clira.org"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/5288"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=5288"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/5288\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/5293"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=5288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=5288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=5288"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=5288"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=5288"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=5288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}