{"id":52723,"date":"2025-04-14T12:54:34","date_gmt":"2025-04-14T10:54:34","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=52723"},"modified":"2025-04-14T12:54:35","modified_gmt":"2025-04-14T10:54:35","slug":"02-stagiaires-en-statistique","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2025\/02-stagiaires-en-statistique\/","title":{"rendered":"02 Stagiaires en Statistique"},"content":{"rendered":"\n<p>Appel \u00e0 candidature : Stagiaire en statistique ou math\u00e9matiques appliqu\u00e9es \u00e0 la sante<br>M.A. SANTE [Meilleur Acc\u00e8s aux Soins de Sant\u00e9] est une ONG camerounaise bas\u00e9e \u00e0 Yaound\u00e9, cr\u00e9\u00e9e en 2006 avec pour objectif de contribuer \u00e0 l\u2019am\u00e9lioration de l\u2019acc\u00e8s aux soins de sant\u00e9 au Cameroun par la recherche, la formation en sant\u00e9 ainsi que la mise en \u0153uvre d\u2019interventions sanitaires. Ses activit\u00e9s sont organis\u00e9es \u00e0 partir de son si\u00e8ge \u00e0 Yaound\u00e9 et de ses sites d\u00e9centralis\u00e9s.<\/p>\n\n\n\n<p>Dans le cadre de son programme de renforcement des capacit\u00e9s en recherche, M.A. SANTE recherche deux (02) jeunes motiv\u00e9s pour faire carri\u00e8re comme statisticien dans le domaine de la recherche en sant\u00e9. &nbsp;<\/p>\n\n\n\n<p>Les candidats int\u00e9ress\u00e9s et s\u00e9lectionn\u00e9s vont b\u00e9n\u00e9ficier d\u2019un stage d\u2019une dur\u00e9e de 06 mois renouvelable une fois pour se familiariser aux activit\u00e9s de recherche afin d\u2019\u00eatre \u00e9valu\u00e9 pour un \u00e9ventuel recrutement. Le stage va porter sur :<\/p>\n\n\n\n<p>L\u2019exposition aux s\u00e9minaires et cours en ligne pay\u00e9s dans les domaines de statistique en sant\u00e9 et du modeling.<br>La formation sur les logiciels d\u2019analyse des donn\u00e9es<br>La r\u00e9daction des volets statistiques des protocoles d\u2019enqu\u00eate, d\u2019\u00e9tudes longitudinales, d\u2019\u00e9tudes observationnelles analytique de type cas t\u00e9moins et cohorte, d\u2019essais clinique et d\u2019essais de terrain et, de revue syst\u00e9matique.<br>Le pr\u00e9-test des protocoles et outils de collecte des donn\u00e9es.<br>Le suivi de la collecte des donn\u00e9es.<br>Le traitement des donn\u00e9s.<br>L\u2019analyse des donn\u00e9es d\u2019enqu\u00eate, d\u2019\u00e9tudes longitudinales, d\u2019\u00e9tudes observationnelles analytique de type cas t\u00e9moins et cohorte, d\u2019essais clinique.<br>Lieu du Stage :&nbsp; Bureau central de M.A. SANTE \u00e0 Yaound\u00e9<\/p>\n\n\n\n<p><strong>Eligibilit\u00e9<\/strong><\/p>\n\n\n\n<p>-\u00catre titulaire d\u2019une licence en Statistique ou en Math\u00e9matiques Appliqu\u00e9es ;<\/p>\n\n\n\n<p>\u2013 Avoir obtenu sa licence il y\u2019a moins de deux ans.<\/p>\n\n\n\n<p><strong>Composition du dossier<\/strong><\/p>\n\n\n\n<p>\u2013 Curriculum vitae de deux pages maximums (avec publication).<\/p>\n\n\n\n<p>\u2013 Tout document justifiant de ses qualifications.<\/p>\n\n\n\n<p>\u2013 Lettre de motivation de moins de 300 mots, adress\u00e9e au directeur scientifique de M.A. SANTE.<\/p>\n\n\n\n<p>\u2013 Copie du dipl\u00f4me ou de l\u2019attestation de r\u00e9ussite.<\/p>\n\n\n\n<p>\u2013 Photocopie de la carte d\u2019identit\u00e9 nationale.<\/p>\n\n\n\n<p>Pour les dossiers soumis par courrier \u00e9lectronique, les documents doivent \u00eatre envoy\u00e9s en format PDF dans un seul fichier (Nom Pr\u00e9nom.pdf).<\/p>\n\n\n\n<p><strong>COMMENT POSTULER :<\/strong><\/p>\n\n\n\n<p>Les candidatures doivent \u00eatre d\u00e9pos\u00e9es&nbsp;au plus tard le 30\/04\/2025 \u00e0 17 heures&nbsp;au si\u00e8ge de l\u2019Association : Yaound\u00e9, quartier Biyem-Assi Lac, en face du Centre Educatif Tyrannus ; ou envoy\u00e9es \u00e0 l\u2019adresse suivante : secretariat@masante-cam.org avec copie \u00e0 cmmassante@gmail.com et jateudj@yahoo.fr.<\/p>\n\n\n\n<p><em>Les candidatures re\u00e7ues apr\u00e8s la date limite ou ne remplissant pas toutes les conditions ne seront pas prises en consid\u00e9ration.<\/em><\/p>\n\n\n\n<p>Seuls les candidats pr\u00e9s\u00e9lectionn\u00e9s seront contact\u00e9s pour des auditions.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via secretariat@masante-cam.org avec copie \u00e0 cmmassante@gmail.com et jateudj@yahoo.fr<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[2986],"tags":[],"villes":[136],"contrats":[236],"diplomes":[212],"louma_meta":{"emploi_title":"","emplois_employeur":19762,"emplois_date_publication":"2025-04-14","emplois_heure_publication":"11:54","emplois_date_cloture":"2025-04-30","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"secretariat@masante-cam.org avec copie \u00e0 cmmassante@gmail.com et jateudj@yahoo.fr"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/52723"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=52723"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/52723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/19763"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=52723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=52723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=52723"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=52723"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=52723"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=52723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}