{"id":52721,"date":"2025-04-14T12:07:26","date_gmt":"2025-04-14T10:07:26","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=52721"},"modified":"2025-04-14T12:07:29","modified_gmt":"2025-04-14T10:07:29","slug":"stagiaire-academique-en-ressources-humaines","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2025\/stagiaire-academique-en-ressources-humaines\/","title":{"rendered":"Stagiaire Acad\u00e9mique en Ressources Humaines"},"content":{"rendered":"\n<p><strong>LE CENTRE DE FORMATION PROFESSIONNELLE GULF FROID INDUSTRIEL<\/strong> est une \u00e9cole dont le si\u00e8ge est \u00e0 Douala. Nous formons les jeunes pour un avenir meilleur et des patrons de demain. CFPGFI est pr\u00e9sent\u00e9 dans plusieurs zone&nbsp;: Deido (Carrefour, 3 morts face Eglise J\u00e9rusalem&nbsp;; Village (borne 10).<\/p>\n\n\n\n<ol style=\"list-style-type:upper-roman\">\n<li>Poste&nbsp;: recherche d\u2019un(e) stagiaire acad\u00e9mique en ressources humaines.<\/li>\n<\/ol>\n\n\n\n<ol>\n<li>ATOUTS<\/li>\n\n\n\n<li>\u00catre une personne dynamique&nbsp;; organis\u00e9e avec de bonnes capacit\u00e9s<\/li>\n\n\n\n<li>Connaissances des bases des outils informatiques<\/li>\n\n\n\n<li>Comp\u00e9tences en communication<\/li>\n\n\n\n<li>Organis\u00e9e avec de bonnes capacit\u00e9s<\/li>\n<\/ol>\n\n\n\n<p>Valide jusqu\u2019au 30\/05\/2025<\/p>\n\n\n\n<p>Type de contrat CDI<\/p>\n\n\n\n<p>Lieu de travail&nbsp;<\/p>\n\n\n\n<ul>\n<li>Deido (carrefour 03 morts face Eglise J\u00e9rusalem)<\/li>\n<\/ul>\n\n\n\n<p>Les d\u00e9p\u00f4ts de candidatures se font uniquement sur ce num\u00e9ro 696 343 512<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LE CENTRE DE FORMATION PROFESSIONNELLE GULF FROID INDUSTRIEL est une \u00e9cole dont le si\u00e8ge est \u00e0 Douala. Nous formons les jeunes pour un avenir meilleur&#8230;<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[20],"tags":[],"villes":[135],"contrats":[152],"diplomes":[248,212],"louma_meta":{"emploi_title":"Stagiaire Acad\u00e9mique en Ressources Humaines","emplois_employeur":3046,"emplois_date_publication":"2025-04-14","emplois_heure_publication":"11:07","emplois_date_cloture":"2025-05-30","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":""},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/52721"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=52721"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/52721\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=52721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=52721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=52721"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=52721"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=52721"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=52721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}