{"id":52290,"date":"2025-03-17T10:48:55","date_gmt":"2025-03-17T09:48:55","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=52290"},"modified":"2025-03-17T10:49:00","modified_gmt":"2025-03-17T09:49:00","slug":"18-femmes-pour-showroom-sur-mesure-sm","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2025\/18-femmes-pour-showroom-sur-mesure-sm\/","title":{"rendered":"18 FEMMES pour SHOWROOM Sur Mesure (SM)"},"content":{"rendered":"\n<p>SM, la Marque des Leaders, marque de mode Africaine haut de gamme, recrute des femmes \u00e9l\u00e9gantes,<br>passionn\u00e9es par la mode et dot\u00e9es d&rsquo;un excellent sens du contact pour rejoindre son \u00e9quipe dans son showroom.<br>\u00a0Nous recherchons : \u00a0<br>\u00a0Mannequins (02) \u00a0<br>\u00a0Conseill\u00e8res en Image (02) \u00a0<br>\u00a0H\u00f4tesses d\u2019Accueil Premium (06) \u00a0<br>\u00a0Personal Shoppers (04) \u00a0<br>\u00a0Animatrices de D\u00e9monstration Produit (02) \u00a0<br>\u00a0Coordinatrices d\u2019\u00c9v\u00e9nements (02) \u00a0<br><strong>\u00a0Profil recherch\u00e9 : \u00a0<\/strong><br>Passionn\u00e9e par la mode et les tendances. \u00a0<br>\u00a0Excellente pr\u00e9sentation et sens du contact. \u00a0<br>\u00a0Capacit\u00e9 \u00e0 s&rsquo;exprimer avec aisance et \u00e9l\u00e9gance. \u00a0<br>\u00a0Esprit d&rsquo;\u00e9quipe et dynamisme. \u00a0<br>Ma\u00eetrise des r\u00e9seaux sociaux (un plus). \u00a0<br>\u00a0Pour rejoindre l&rsquo;\u00e9quipe de Sur Mesure (SM), remplissez ce formulaire\u00a0\u00a0<a href=\"https:\/\/forms.gle\/JQjPe9LkU9jsBD1g8\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/forms.gle\/JQjPe9LkU9jsBD1g8<\/a>\u00a0<br>\u00a0Apr\u00e8s votre inscription, notre \u00e9quipe vous contactera. \u00a0<br>Devenez l\u2019ic\u00f4ne de l\u2019\u00e9l\u00e9gance Africaine avec SM !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via https:\/\/forms.gle\/JQjPe9LkU9jsBD1g8\u00a0<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[28],"tags":[],"villes":[136],"contrats":[148],"diplomes":[278],"louma_meta":{"emploi_title":"18 FEMMES pour SHOWROOM Sur Mesure (SM)","emplois_employeur":3046,"emplois_date_publication":"2025-03-17","emplois_heure_publication":"10:48","emplois_date_cloture":"2025-03-25","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"https:\/\/forms.gle\/JQjPe9LkU9jsBD1g8\u00a0"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/52290"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=52290"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/52290\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=52290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=52290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=52290"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=52290"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=52290"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=52290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}