{"id":52003,"date":"2025-02-25T10:46:02","date_gmt":"2025-02-25T09:46:02","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=52003"},"modified":"2025-02-25T10:46:04","modified_gmt":"2025-02-25T09:46:04","slug":"commercial-87","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2025\/commercial-87\/","title":{"rendered":"COMMERCIAL"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Nombre de postes : 1<\/h2>\n\n\n\n<p><strong>Type de contrat <\/strong>: Temps plein, CDI<\/p>\n\n\n\n<p><strong>Lieu de travail <\/strong>: Yaound\u00e9, Cameroun<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">\u00c0 propos d&rsquo;AlShadows Group<\/h1>\n\n\n\n<p>AlShadows Group est une entreprise technologique innovante bas\u00e9e \u00e0 Yaound\u00e9, sp\u00e9cialis\u00e9e dans le d\u00e9veloppement de solutions num\u00e9riques, la gestion de projets, la maintenance informatique et le marketing digital. Dans le cadre de notre croissance et de notre strat\u00e9gie de communication et commercialisation, nous recherchons un <strong>COMMERCIAL <\/strong>ambitieuxet motiv\u00e9 pour rentabiliser notre portefeuille et augmenter nos parts de march\u00e9.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Missions principales<\/h1>\n\n\n\n<p>En tant que Commercial(e), vous serez le moteur de notre croissance en d\u00e9veloppant et fid\u00e9lisant un portefeuille de clients. Vos principales responsabilit\u00e9s seront de :<\/p>\n\n\n\n<ul>\n<li>Prospecter de nouveaux clients et identifier leurs besoins.<\/li>\n\n\n\n<li>Pr\u00e9senter et promouvoir nos solutions technologiques.<\/li>\n\n\n\n<li>N\u00e9gocier et conclure des contrats.<\/li>\n\n\n\n<li>Assurer le suivi et la satisfaction des clients.<\/li>\n\n\n\n<li>Atteindre et d\u00e9passer les objectifs de vente.<\/li>\n\n\n\n<li>Effectuer une veille concurrentielle et identifier les opportunit\u00e9s de march\u00e9.<\/li>\n\n\n\n<li>Proposer des ajustements cr\u00e9atifs pour am\u00e9liorer l\u2019efficacit\u00e9 des campagnes et la pr\u00e9sence digitale de l\u2019entreprise.<\/li>\n<\/ul>\n\n\n\n<h1 class=\"wp-block-heading\">Profil recherch\u00e9<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">Qualifications et comp\u00e9tences requises :<\/h2>\n\n\n\n<ul>\n<li>Bac +2 minimum en commerce ou \u00e9quivalent.<\/li>\n\n\n\n<li>Exp\u00e9rience d\u2019au moins 2 ans dans un poste similaire, id\u00e9alement dans le secteur des technologies ou de services.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Qualit\u00e9s personnelles :<\/h2>\n\n\n\n<ul>\n<li>Vous \u00eates un(e) excellent(e) communicant(e) et n\u00e9gociateur(trice).<\/li>\n\n\n\n<li>Vous \u00eates autonome, organis\u00e9(e) et orient\u00e9(e) r\u00e9sultats.<\/li>\n\n\n\n<li>Bonnes comp\u00e9tences relationnelles et capacit\u00e9 \u00e0 travailler en \u00e9quipe.<\/li>\n\n\n\n<li>Capacit\u00e9 \u00e0 \u00e9voluer dans un environnement dynamique et en constante \u00e9volution.<\/li>\n<\/ul>\n\n\n\n<h1 class=\"wp-block-heading\">Pourquoi rejoindre AlShadows Group ?<\/h1>\n\n\n\n<ul>\n<li>Un environnement de travail stimulant et innovant.<\/li>\n\n\n\n<li>Une r\u00e9mun\u00e9ration attractive et \u00e9volutive (fixe + variable).<\/li>\n\n\n\n<li>Des opportunit\u00e9s de d\u00e9veloppement professionnel.<\/li>\n\n\n\n<li>Une \u00e9quipe dynamique et soud\u00e9e.<\/li>\n<\/ul>\n\n\n\n<h1 class=\"wp-block-heading\">Comment postuler ?<\/h1>\n\n\n\n<p>Si vous \u00eates int\u00e9ress\u00e9(e) par ce poste, veuillez envoyer votre CV et une lettre de motivation \u00e0 l&rsquo;adresse suivante : <a href=\"mailto:recrutement@alshadows.com\">recrutement@alshadows.com<\/a> avec l&rsquo;objet &nbsp;<strong>\u00ab&nbsp;commercial\/votre nom&nbsp;\u00bb.<\/strong><\/p>\n\n\n\n<p><strong>D\u00e9lai&nbsp;de recevabilit\u00e9&nbsp;: 05 mars 2025<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via recrutement@alshadows.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[251],"tags":[],"villes":[136],"contrats":[234,148],"diplomes":[248],"louma_meta":{"emploi_title":"","emplois_employeur":3892,"emplois_date_publication":"2025-02-25","emplois_heure_publication":"10:45","emplois_date_cloture":"2025-03-05","emplois_heure_cloture":"17:00","emplois_experience_min":"2","emplois_experience_max":"","emploi_email":"recrutement@alshadows.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/52003"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=52003"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/52003\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3901"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=52003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=52003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=52003"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=52003"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=52003"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=52003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}