{"id":51915,"date":"2025-02-19T12:30:10","date_gmt":"2025-02-19T11:30:10","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=51915"},"modified":"2025-02-19T12:30:12","modified_gmt":"2025-02-19T11:30:12","slug":"ingenieur-commercial-projets","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2025\/ingenieur-commercial-projets\/","title":{"rendered":"Ing\u00e9nieur Commercial &amp; Projets"},"content":{"rendered":"\n<p>Missions principales D\u00e9veloppement commercial<br>Prospecter de nouveaux clients et march\u00e9s<br>Identifier les besoins des clients et proposer des solutions techniques<br>N\u00e9gocier et conclure des opportunit\u00e9s de vente<br>D\u00e9velopper et fid\u00e9liser un portefeuille de clients<br>Expertise technique<br>Assurer une veille concurrentielle<br>Collaborer avec le Service Technique pour assurer la faisabilit\u00e9 des projets<br>Gestion de projets<br>Piloter les projets de vente, de la prospection \u00e0 la livraison<br>Assurer le suivi des projets et la satisfaction des clients<br>Reporting et analyse<br>Effectuer un reporting r\u00e9gulier de l&rsquo;activit\u00e9 commerciale<br>Effectuer un reporting r\u00e9gulier des projets en cours<br>Effectuer un reporting r\u00e9gulier de la veille technologique et concurrentielle<br>Analyser les r\u00e9sultats et proposer des axes d&rsquo;am\u00e9lioration<br>Participer \u00e0 l&rsquo;\u00e9laboration de la strat\u00e9gie commerciale<br><strong>Formation et\u00a0exp\u00e9rience<\/strong><br>Exp\u00e9rience: 1 &#8211; 2 ans d&rsquo;exp\u00e9rience \u00e0 un poste similaire<br>Une exp\u00e9rience commerciale serait un atout<br>Piloter en \u00e9troite collaboration avec le Service Technique la conception des<br>solutions techniques sur mesure et l&rsquo;\u00e9laboration des cahiers de charges<br>Assurer une veille technologique pour proposer les solutions \u00e0 jour et innovantes<\/p>\n\n\n\n<p>Gr\u00e2ce \u00e0 vos connaissances et comp\u00e9tences techniques, vous proposerez des solutions<br>techniques r\u00e9pondant aux attentes des clients. Vous assurerez la mise en \u0153uvre des<br>solutions en mode projet et leur suivi commercial<br>Concevoir et r\u00e9diger les pr\u00e9sentations des offres commerciales dans le cadre<br>des appels d&rsquo;offres et consultations<br>Ma\u00eetriser les produits et services de l&rsquo;entreprise pour conseiller au mieux les<br>clients<br>Ma\u00eetriser les r\u00e8gles et normes techniques de conception, mise en \u0153uvre et<br>maintenance des solutions techniques propos\u00e9es<br>Coordonner les actions des diff\u00e9rents intervenants (\u00e9quipe technique, logistique,<br>commercial, finances)<br>Dipl\u00f4me d&rsquo;ing\u00e9nieur avec une sp\u00e9cialisation technique (formation in\u00e9g\u00e9nieur<br>g\u00e9n\u00e9ralaiste, g\u00e9nie industriel, \u00e9lectrom\u00e9canique, \u00e9lectronique, informatique<br>industrielle,\u2026)<\/p>\n\n\n\n<p>Comp\u00e9tences<br>techniques<br>Capacit\u00e9 \u00e0 conna\u00eetre et comprendre les produits et solutions de l&rsquo;entreprise<br>Capacit\u00e9 \u00e0 comprendre, analyser et traduire les besoins techniques des clients<br>Aptitude \u00e0 conduire les projets en mode projet<br>Capacit\u00e9 \u00e0 conna\u00eetre et ma\u00eetriser les techniques de vente<br>Capacit\u00e9 manag\u00e9riale: aptitude \u00e0 g\u00e9rer une \u00e9quipe projet<br>Niveau de langue anglaise: Moyen<br>Qualit\u00e9s personelles Int\u00e8gre, discret et loyal<br>Excellent relationnel<br>Aisance communicationnelle<br>Sens de l&rsquo;\u00e9coute et du service client<br>Autonomie et rigueur<br>M\u00e9thodique et aisance organisationnelle<br>Esprit d&rsquo;\u00e9quipe et capacit\u00e9 \u00e0 travailler en mode projet<br>Capacit\u00e9 \u00e0 travailler sous pression<br>Go\u00fbt pour les challenges et la culture du r\u00e9sultat<br>Mobilit\u00e9 g\u00e9ographique Sur le territoire national et \u00e0 l&rsquo;\u00e9tranger<br>Un passeport \u00e0 jour est indispensable pour ce poste<br>Outils de travail Poste de travail \u00e9quip\u00e9 d&rsquo;un laptop configur\u00e9 pour les besoins du poste<br>T\u00e9l\u00e9phone de fonction + cr\u00e9dit de communication<br>Mat\u00e9riel bureautique<br>R\u00e9mun\u00e9ration et<br>avantages Salaire fixe + variable attractif<br>Pr\u00e9voyance sociale CNPS<br>Acc\u00e8s \u00e0 la m\u00e9d\u00e9cine de travail<br>Formation continue<\/p>\n\n\n\n<p><strong>COMMENT POSTULER :<\/strong><br>Pour postuler Envoyer CV et lettre de motivation \u00e0 l&rsquo;adresse glcinter@gmail.com<br>Date limite de<br>soumission Le 28 f\u00e9vrier 2025<br>Capacit\u00e9 \u00e0 comprendre et restituer les normes et r\u00e9f\u00e9rentiels applicables pour la<br>conception et la mise en \u0153uvre des solutions techniques<br>Aptitude \u00e0 r\u00e9diger des offres de service, des offres techniques et commerciales<br>pertinentes<br>Aisance avec les outils informatiques : Pack MS Office (Excel, PPT, Word), MS<br>Project, AUTOCAD, logiciels ou applications de gestion<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via glcinter@gmail.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[251,1833],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Ing\u00e9nieur Commercial & Projets","emplois_employeur":51909,"emplois_date_publication":"2025-02-19","emplois_heure_publication":"12:30","emplois_date_cloture":"2025-02-28","emplois_heure_cloture":"17:00","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"glcinter@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/51915"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=51915"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/51915\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/51910"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=51915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=51915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=51915"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=51915"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=51915"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=51915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}