{"id":50183,"date":"2024-11-12T21:16:43","date_gmt":"2024-11-12T21:16:43","guid":{"rendered":""},"modified":"2024-11-12T22:21:46","modified_gmt":"2024-11-12T21:21:46","slug":"assistant-community-manager-3","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/assistant-community-manager-3\/","title":{"rendered":"Assistant Community Manager"},"content":{"rendered":"<p class=\"MsoNormal\"><strong>Assistant Community Manager chez Smartketplus<\/strong><\/p>\n<p class=\"MsoNormal\">&nbsp;<\/p>\n<p class=\"MsoNormal\"><strong>Description :<\/strong><\/p>\n<p class=\"MsoNormal\">Smartketplus, une entreprise sp&eacute;cialis&eacute;e dans la commercialisation de machines alimentaires, recherche un(e) Stagiaire Assistant Community Manager passionn&eacute;(e) et cr&eacute;atif(ve) pour rejoindre notre &eacute;quipe.<\/p>\n<p class=\"MsoNormal\">&nbsp;<\/p>\n<p class=\"MsoNormal\"><strong>Missions \/ Responsabilit&eacute;s \/ Activit&eacute;s :<\/strong><\/p>\n<p class=\"MsoNormal\">&nbsp;<\/p>\n<p class=\"MsoNormal\">Animer et d&eacute;velopper les r&eacute;seaux sociaux de l&rsquo;entreprise en publiant des contenus attractifs et engageants.<\/p>\n<p class=\"MsoNormal\">Interagir activement avec la communaut&eacute;, r&eacute;pondre aux questions et commentaires, et fid&eacute;liser la client&egrave;le en ligne.<\/p>\n<p class=\"MsoNormal\">Collaborer avec l&rsquo;&eacute;quipe pour cr&eacute;er des campagnes marketing innovantes et contribuer &agrave; la visibilit&eacute; de l&rsquo;entreprise.<\/p>\n<p class=\"MsoNormal\">G&eacute;rer la r&eacute;putation en ligne de l&rsquo;entreprise et veiller &agrave; une image de marque coh&eacute;rente et positive.<\/p>\n<p class=\"MsoNormal\">Analyser les performances des campagnes et proposer des strat&eacute;gies pour am&eacute;liorer la notori&eacute;t&eacute; de l&rsquo;entreprise.<\/p>\n<p class=\"MsoNormal\"><strong>Comp&eacute;tences \/ Exigences \/ Qualit&eacute;s :<\/strong><\/p>\n<p class=\"MsoNormal\">&nbsp;<\/p>\n<p class=\"MsoNormal\"><strong>Exp&eacute;rience :<\/strong> Id&eacute;alement un(e) d&eacute;butant(e) venant d&rsquo;obtenir un dipl&ocirc;me en marketing, communication ou dans un domaine connexe, avec une passion pour le community management.<\/p>\n<p class=\"MsoNormal\"><strong>Langues :<\/strong> Ma&icirc;trise du fran&ccedil;ais et de l&rsquo;anglais (un plus pour la candidature).<\/p>\n<p class=\"MsoNormal\"><strong>Comp&eacute;tences cl&eacute;s :<\/strong> Solide ma&icirc;trise des r&eacute;seaux sociaux (Instagram, Facebook, TikTok, etc.), excellent sens de la communication, cr&eacute;ativit&eacute;, et capacit&eacute; &agrave; engager une communaut&eacute; en ligne.<\/p>\n<p class=\"MsoNormal\"><strong>Vos Avantages :<\/strong><\/p>\n<p class=\"MsoNormal\">&nbsp;<\/p>\n<p class=\"MsoNormal\">Un environnement de travail motivant au sein d&rsquo;une &eacute;quipe dynamique et cr&eacute;ative.<\/p>\n<p class=\"MsoNormal\">Des opportunit&eacute;s d&rsquo;&eacute;volution et de formation continue dans un secteur en pleine croissance.<\/p>\n<p class=\"MsoNormal\"><strong>Documents de candidature :<\/strong><\/p>\n<p class=\"MsoNormal\">Curriculum Vitae<\/p>\n<p class=\"MsoNormal\">recrutement@smartketplus.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Assistant Community Manager chez Smartketplus &nbsp; Description : Smartketplus, une entreprise sp&eacute;cialis&eacute;e dans la commercialisation de machines alimentaires, recherche un(e) Stagiaire Assistant Community Manager passionn&eacute;(e)&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"open","template":"","categories":[1773],"tags":[],"villes":[135],"contrats":[148],"diplomes":[248],"louma_meta":{"emploi_title":"Assistant Community Manager ","emplois_employeur":47019,"emplois_date_publication":"2024-11-12","emplois_heure_publication":"","emplois_date_cloture":"2024-11-30","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"recrutement@smartketplus.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/50183"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=50183"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/50183\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/47020"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=50183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=50183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=50183"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=50183"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=50183"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=50183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}