{"id":50076,"date":"2024-11-04T10:55:30","date_gmt":"2024-11-04T09:55:30","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=50076"},"modified":"2024-11-04T10:55:32","modified_gmt":"2024-11-04T09:55:32","slug":"coursier-4","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/coursier-4\/","title":{"rendered":"COURSIER"},"content":{"rendered":"\n<p>Description du poste : Nous recherchons un coursier exp\u00e9riment\u00e9 pour intervenir dans diff\u00e9rentes zones de douala.<\/p>\n\n\n\n<p>Vos principales responsabilit\u00e9s incluront :<\/p>\n\n\n\n<ul>\n<li>Livraison de commandes : Assurer que les livraisons soient effectu\u00e9es dans les d\u00e9lais, en garantissant que la marchandise arrivent en parfait \u00e9tat chez les clients.<\/li>\n\n\n\n<li>Achat divers : Effectuer les achats n\u00e9cessaires ,tout type de produits requis pour le bon fonctionnement de l&rsquo;activit\u00e9.<\/li>\n\n\n\n<li>Entretien du mat\u00e9riel : Prendre en charge l&rsquo;entretien courant du mat\u00e9riel pour assurer sa durabilit\u00e9 et son bon fonctionnement.<\/li>\n\n\n\n<li>Qualit\u00e9 de service : Veiller \u00e0 offrir une qualit\u00e9 de service irr\u00e9prochable, notamment en assurant un bon rapport envers les clients.<\/li>\n\n\n\n<li>Comparaison des prix : R\u00e9aliser des \u00e9tudes comparatives des prix des mati\u00e8res premi\u00e8res pour garantir des achats au meilleur co\u00fbt.<\/li>\n<\/ul>\n\n\n\n<p>Profil recherch\u00e9 :<\/p>\n\n\n\n<ul>\n<li>Ponctualit\u00e9 : \u00eates toujours \u00e0 l&rsquo;heure.<\/li>\n\n\n\n<li>Dynamisme : r\u00e9actif et motiv\u00e9 par les d\u00e9fis.<\/li>\n\n\n\n<li>Sens de l&rsquo;orientation : Vous avez une excellente connaissance de la ville de Douala.<\/li>\n\n\n\n<li>Organisation : Vous \u00eates capable de vous organiser de tel en sorte de respecter les temps de livraison.<br>\u2022 Savoir conduire une moto Horaires de travail:<br>Lundi -vendredi : 8h -17h<br>Samedi: 8h -14h<\/li>\n<\/ul>\n\n\n\n<p>Poste bas\u00e9 \u00e0 DOUALA!!! Vivre \u00e0 bonamoussadi et alentours..<br>Cliquez sur le lien pour \u00e9crire au recruteur +237695798519<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via +237695798519<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[1182],"tags":[],"villes":[135],"contrats":[148],"diplomes":[162],"louma_meta":{"emploi_title":"COURSIER ","emplois_employeur":3046,"emplois_date_publication":"2024-11-04","emplois_heure_publication":"09:55","emplois_date_cloture":"2024-11-18","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"+237695798519"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/50076"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=50076"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/50076\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=50076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=50076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=50076"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=50076"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=50076"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=50076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}