{"id":50033,"date":"2024-10-31T19:38:02","date_gmt":"2024-10-31T18:38:02","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=50033"},"modified":"2024-10-31T19:38:06","modified_gmt":"2024-10-31T18:38:06","slug":"charge-daffaires-corporate-finance","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/charge-daffaires-corporate-finance\/","title":{"rendered":"Charg\u00e9 d\u2019Affaires Corporate Finance"},"content":{"rendered":"\n<p>Charg\u00e9 d\u2019Affaires Corporate Finance<\/p>\n\n\n\n<p>MISSIONS<\/p>\n\n\n\n<p>Int\u00e9gr\u00e9(e) au sein de la Pr\u00e9sidence de la Holding, le Charg\u00e9 d\u2019Affaires Corporate Finance prendra part :<\/p>\n\n\n\n<p>&#8211; A <a><\/a>l\u2019\u00e9laboration de : pitchs, notes de synth\u00e8se, teasers, m\u00e9morandums et management presentations<\/p>\n\n\n\n<p>&#8211; A la mod\u00e9lisation des op\u00e9rations d\u2019ing\u00e9nierie financi\u00e8re et de management de projet<\/p>\n\n\n\n<p>&#8211; A la pr\u00e9paration et l\u2019analyse des \u00e9tats financiers de filiales ou d\u2019entreprises cibles<\/p>\n\n\n\n<p>&#8211; A la mod\u00e9lisation financi\u00e8re et la valorisation d\u2019entreprises<\/p>\n\n\n\n<p>&#8211; A la mise en \u0153uvre de la strat\u00e9gie groupe et au d\u00e9veloppement international<\/p>\n\n\n\n<p>&#8211; A l\u2019interface entre les actionnaires, filiales, juristes, financiers, partenaires, gouvernements et conseils<\/p>\n\n\n\n<p>&#8211; A la d\u00e9livrance de rapports p\u00e9riodiques et \u00e0 la pr\u00e9paration des board meeting<\/p>\n\n\n\n<p>PROFIL RECHERCHE<\/p>\n\n\n\n<p>&#8211; Grande Ecole de Commerce \/ Ecole d\u2019Ing\u00e9nieur \/ Master 2 en Finance \/ MBA<\/p>\n\n\n\n<p>&#8211; Bilingue Anglais\/Fran\u00e7ais (\u00e9crit et parl\u00e9)<\/p>\n\n\n\n<p>&#8211; Rigueur, curiosit\u00e9, esprit d\u2019initiative, capacit\u00e9 de synth\u00e8se et esprit d\u2019\u00e9quipe<\/p>\n\n\n\n<p>&#8211; Bonne pr\u00e9sentation, honn\u00eatet\u00e9 et sens de l\u2019\u00e9thique<\/p>\n\n\n\n<p>&#8211; Entrepreneur, rigoureux, autonome et dynamique<\/p>\n\n\n\n<p>&#8211; Homme de r\u00e9seaux, \u00e9coute et grandes qualit\u00e9s interpersonnelles<\/p>\n\n\n\n<p>&#8211; Capacit\u00e9 \u00e0 travailler vite et sous pression<\/p>\n\n\n\n<p>&#8211; 3 ans minimum d\u2019exp\u00e9rience r\u00e9ussie en M&amp;A, Private Equity, Audit ou Direction financi\u00e8re<\/p>\n\n\n\n<p>&#8211; Bonne connaissance de la technique financi\u00e8re, de la fiscalit\u00e9 locale et internationale<\/p>\n\n\n\n<p>SALAIRE<\/p>\n\n\n\n<p>Entre 150.000 et 450.000 FCFA fixe (En fonction des dipl\u00f4mes et exp\u00e9riences) + Bonus annuel + Frais<\/p>\n\n\n\n<p>LIEU<\/p>\n\n\n\n<p>Poste bas\u00e9 \u00e0 Yaound\u00e9 (Cameroun)<\/p>\n\n\n\n<p>PERIODE<\/p>\n\n\n\n<p>A partir de novembre 2024<\/p>\n\n\n\n<p>CONTACT<\/p>\n\n\n\n<p>madlyncazalis@gmail.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Charg\u00e9 d\u2019Affaires Corporate Finance MISSIONS Int\u00e9gr\u00e9(e) au sein de la Pr\u00e9sidence de la Holding, le Charg\u00e9 d\u2019Affaires Corporate Finance prendra part : &#8211; A l\u2019\u00e9laboration&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","categories":[23],"tags":[],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Charg\u00e9 d\u2019Affaires Corporate Finance","emplois_employeur":3140,"emplois_date_publication":"2024-10-31","emplois_heure_publication":"","emplois_date_cloture":"2024-11-14","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"madlyncazalis@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/50033"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=50033"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/50033\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3141"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=50033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=50033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=50033"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=50033"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=50033"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=50033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}