{"id":49942,"date":"2024-10-25T13:59:55","date_gmt":"2024-10-25T13:59:55","guid":{"rendered":""},"modified":"2024-10-25T16:20:41","modified_gmt":"2024-10-25T14:20:41","slug":"cuisiniere-caissiere-serveuse","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/cuisiniere-caissiere-serveuse\/","title":{"rendered":"Cuisini\u00e8re, Caissi\u00e8re, serveuse"},"content":{"rendered":"<p>Le snack bar restaurant sodab coffee situ&eacute; au carrefour sous manguier nkomo recherche des serveuses, caisi&egrave;res, cuisini&egrave;res, &acirc;g&eacute;es de 21ans &agrave; 35 ans. Les horaires de travail c&rsquo;est de 15h &agrave; X heure.<br \/>Contact 695 52 88 91 \/ 675 62 34 97<\/p>\n<p>Dossier : Demande d&#8217;emploi, CV, photocopie CNI et plan de localisation.<br \/>Envoi par mail: sodabcreative@gmail.com<br \/>Ou whatsapp 695528891<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le snack bar restaurant sodab coffee situ&eacute; au carrefour sous manguier nkomo recherche des serveuses, caisi&egrave;res, cuisini&egrave;res, &acirc;g&eacute;es de 21ans &agrave; 35 ans. Les horaires&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"open","template":"","categories":[4077],"tags":[],"villes":[136],"contrats":[148],"diplomes":[156],"louma_meta":{"emploi_title":"Cuisini\u00e8re, Caissi\u00e8re, serveuse","emplois_employeur":34258,"emplois_date_publication":"2024-10-25","emplois_heure_publication":"","emplois_date_cloture":"2024-11-10","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"youmbougnes@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/49942"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=49942"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/49942\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/34259"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=49942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=49942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=49942"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=49942"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=49942"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=49942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}