{"id":49345,"date":"2024-09-16T09:34:24","date_gmt":"2024-09-16T07:34:24","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=49345"},"modified":"2024-09-16T09:34:28","modified_gmt":"2024-09-16T07:34:28","slug":"02-infirmierses","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/02-infirmierses\/","title":{"rendered":"02 INFIRMIERS(ES)"},"content":{"rendered":"\n<p>IMC (International Medical Corps) Cameroun recherche pour les besoins de son programme<br>d\u2019appui aux r\u00e9fugi\u00e9s Nig\u00e9rians et populations h\u00f4tes install\u00e9s dans la r\u00e9gion de l\u2019Extr\u00eameNord, deux (2) Infirmiers(es).<br>Date de publication: 13 Septembre 2024<br>Date limite: 18 Septembre 2024<br>Localisation: Extr\u00eame-Nord\/ Mayo-Danay<br><strong>R\u00c9SUM\u00c9 DU POSTE<\/strong><br>L&rsquo;infirmier(e) s&rsquo;efforcera de contribuer \u00e0 l&rsquo;am\u00e9lioration de l&rsquo;\u00e9tat de sant\u00e9 g\u00e9n\u00e9ral de la<br>population cibl\u00e9e en fournissant des soins de sant\u00e9 de qualit\u00e9 (soins curatifs et pr\u00e9ventifs).<\/p>\n\n\n\n<p>Le titulaire de ce poste doit trier les patients, veiller \u00e0 ce que le flux de patients soit r\u00e9gulier,<br>fournir des soins cliniques, aider \u00e0 l&rsquo;orientation des patients si n\u00e9cessaire et assurer<br>l&rsquo;\u00e9ducation \u00e0 la sant\u00e9 et la promotion de l&rsquo;hygi\u00e8ne. En outre, l&rsquo;infirmier(e) peut \u00eatre amen\u00e9(e)<br>\u00e0 aider le personnel de sant\u00e9 dans d&rsquo;autres domaines, selon les besoins.<br>Pour mener \u00e0 bien ce travail, la personne doit \u00eatre capable de remplir chaque fonction<br>essentielle avec ou sans am\u00e9nagements raisonnables.<br><strong>A. PRINCIPALES T\u00c2CHES ET RESPONSABILIT\u00c9S<\/strong><br>\uf0b7 Fournir des services infirmiers cliniques conform\u00e9ment aux normes<br>internationalement reconnues.<br>\uf0b7 Assister les m\u00e9decins cliniciens, et collaborer avec les sages-femmes, les laboratoires,<br>les services de vaccination et la pharmacie dans l&rsquo;ex\u00e9cution des t\u00e2ches g\u00e9n\u00e9rales<br>d\u00e9sign\u00e9es par le superviseur.<br>\uf0b7 G\u00e9rer le triage, prendre les signes vitaux et organiser les patients pour la consultation.<br>\uf0b7 Effectuer les vaccinations des enfants et des femmes enceintes.<br>\uf0b7 Effectuer des pansements, des sutures de plaies profondes, etc.<br>\uf0b7 Dispenser des soins infirmiers aux patients conform\u00e9ment aux directives ; aux instructions du m\u00e9decin s&rsquo;il travaille dans un service d&rsquo;hospitalisation et effectuer des<br>t\u00e2ches conform\u00e9ment aux protocoles.<br>\uf0b7 Veiller \u00e0 la bonne gestion des donn\u00e9es en remplissant les fiches des patients, les<br>registres, les feuilles de comptage et les rapports.<br>\uf0b7 Contribuer \u00e0 la r\u00e9alisation d&rsquo;examens de laboratoire et d&rsquo;autres examens disponibles et<br>accessibles pour les patients.<br>\uf0b7 Assurer l&rsquo;\u00e9ducation sanitaire et la promotion de l&rsquo;hygi\u00e8ne aupr\u00e8s des patients en<br>fonction de leur diagnostic et des comorbidit\u00e9s, notamment en ce qui concerne le<br>r\u00e9gime alimentaire, l&rsquo;activit\u00e9, l&rsquo;hygi\u00e8ne et la pr\u00e9vention des maladies (comme la<br>n\u00e9cessit\u00e9 de se faire vacciner, de sugg\u00e9rer des changements de mode de vie, etc.)<br>\uf0b7 Assister \u00e0 l&rsquo;examen physique des patients en mati\u00e8re de sant\u00e9 sexuelle et g\u00e9n\u00e9sique, en<br>particulier pour un prestataire de soins de sant\u00e9 de sexe masculin, chaque fois que cela<br>est demand\u00e9.<br>\uf0b7 Veiller \u00e0 ce que les patients concern\u00e9s, y compris les enfants de moins de cinq ans,<br>fassent l&rsquo;objet d&rsquo;un d\u00e9pistage de la malnutrition ou fournir des services de lutte contre la malnutrition s&rsquo;ils ont \u00e9t\u00e9 form\u00e9s et si le superviseur leur a confi\u00e9 des responsabilit\u00e9s<br>\u00e0 cet \u00e9gard.<br>\uf0b7 Travailler avec le superviseur pour fournir une formation didactique et sur le terrain<br>afin de renforcer les capacit\u00e9s et d&rsquo;am\u00e9liorer les comp\u00e9tences d&rsquo;autres membres du<br>personnel tels que les ASC et les infirmi\u00e8res auxiliaires.<br>\uf0b7 Collaborer avec d&rsquo;autres services, si n\u00e9cessaire, pour assurer une mise en \u0153uvre et une<br>int\u00e9gration harmonieuse des services.<br>\uf0b7 Respecter les directives administratives en ce qui concerne les horaires de travail, la<br>tenue des dossiers, les communications avec les patients, la confidentialit\u00e9, le<br>r\u00e9approvisionnement en m\u00e9dicaments essentiels, consommables et autres fournitures<br>m\u00e9dicales.<br>\uf0b7 S&rsquo;acquitter des t\u00e2ches suppl\u00e9mentaires qui lui sont assign\u00e9es, notamment le triage, les<br>soins intensifs, le point focal pour la protection de l&rsquo;enfance, la distribution et\/ou la<br>gestion des donn\u00e9es, selon les besoins.<br>\uf0b7 Aider \u00e0 l&rsquo;installation, \u00e0 l&rsquo;entretien et \u00e0 la mobilisation des espaces cliniques, le cas<br>\u00e9ch\u00e9ant.<br>\uf0b7 Les t\u00e2ches et responsabilit\u00e9s \u00e9num\u00e9r\u00e9es sont repr\u00e9sentatives de la nature et du niveau<br>de travail assign\u00e9 et ne sont pas n\u00e9cessairement exhaustives. La nature urgente du<br>travail du CGI exige du personnel qu&rsquo;il s&rsquo;adapte \u00e0 un paysage en \u00e9volution rapide ; les t\u00e2ches peuvent \u00eatre reconfigur\u00e9es pour r\u00e9pondre aux exigences op\u00e9rationnelles.<br>Effectuer les autres t\u00e2ches qui lui sont confi\u00e9es. Les fonctions et responsabilit\u00e9s<br>\u00e9num\u00e9r\u00e9es dans le pr\u00e9sent document sont repr\u00e9sentatives de la nature et du volume du<br>travail assign\u00e9 et ne sont pas n\u00e9cessairement exhaustives.<br><strong>B. QUALIFICATIONS MINIMALES<\/strong><br>\uf0b7 Infirmier(e) qualifi\u00e9(e) et dipl\u00f4m\u00e9(e) d&rsquo;un institut de formation en soins infirmiers<br>reconnu par le gouvernement et titulaire d&rsquo;une licence d&rsquo;exercice valide ou d&rsquo;une<br>qualification similaire requise dans le pays pour le poste.<br>\uf0b7 Une exp\u00e9rience pr\u00e9alable dans la m\u00eame fonction sera un atout.<br>\uf0b7 Une exp\u00e9rience ant\u00e9rieure au sein d&rsquo;une ONG est pr\u00e9f\u00e9rable.<br>\uf0b7 Bonne capacit\u00e9 de communication, \u00e0 la fois orale et \u00e9crite.<\/p>\n\n\n\n<p>\uf0b7 Extr\u00eamement flexible et capable de faire face \u00e0 des situations de stress et de frustration.<br>\uf0b7 Capacit\u00e9 \u00e0 \u00e9tablir des relations avec le personnel et \u00e0 le motiver efficacement.<br>\uf0b7 Bonne capacit\u00e9 de prise de d\u00e9cision<br>\uf0b7 Doit travailler de mani\u00e8re ind\u00e9pendante dans des conditions difficiles.<br>\uf0b7 \u00catre capable d&rsquo;assumer des responsabilit\u00e9s non m\u00e9dicales de temps \u00e0 autre pour<br>remplacer d&rsquo;autres membres de l&rsquo;\u00e9quipe.<br>\uf0b7 Bonne capacit\u00e9 de lecture et d&rsquo;\u00e9criture en anglais.<br>\uf0b7 Ma\u00eetrise de la langue nationale et locale parl\u00e9e.<br>C. AUTRES<br>S\u00e9curit\u00e9:<br>Assurer le respect des protocoles et politiques de s\u00e9curit\u00e9;<br>Conduite \u00e9thique du personnel de IMC :<br>International Medical Corps maintient un code de normes de conduite qui r\u00e9git le rendement de ses<br>employ\u00e9s engag\u00e9s dans l\u2019attribution et l\u2019administration des contrats. Aucun employ\u00e9, dirigeant ou<br>mandataire ne doit participer \u00e0 la s\u00e9lection, \u00e0 l\u2019attribution ou \u00e0 l\u2019administration d\u2019un contrat financ\u00e9 par des fonds de donateurs s\u2019il s\u2019agit d\u2019un conflit d\u2019int\u00e9r\u00eats r\u00e9el ou apparent. Un tel conflit survient lorsque l\u2019employ\u00e9, le dirigeant ou l\u2019agent, un membre de sa famille imm\u00e9diate, un partenaire ou une organisation qui emploie ou est sur le point d\u2019employer l\u2019une des parties \u00e9num\u00e9r\u00e9es ci-dessus, a un int\u00e9r\u00eat financier ou autre dans l\u2019entreprise s\u00e9lectionn\u00e9e pour l\u2019attribution. Les dirigeants, employ\u00e9s ou agents de IMC ne doivent pas solliciter ou accepter de gratifications, de faveurs ou de toute autre chose ayant une valeur mon\u00e9taire de la part d\u2019entrepreneurs ou de parties \u00e0 des sous-accords. Ces normes pr\u00e9voient des mesures disciplinaires en cas de violation de ces normes par des dirigeants, des employ\u00e9s ou des agents de IMC.<br>Pr\u00e9vention de l&rsquo;exploitation et des abus sexuels:<br>Promouvoir activement les normes \u00ab PSEA \u00bb (Pr\u00e9vention de l&rsquo;Exploitation et des Abus Sexuels) au sein<br>d&rsquo;International Medical Corps et parmi les b\u00e9n\u00e9ficiaires desservis par International Medical Corps.<br>Code De Conduite :<br>En fonction du poste, le candidat doit promouvoir et encourager une culture de conformit\u00e9 et d&rsquo;\u00e9thique dans toute l&rsquo;organisation et maintenir une compr\u00e9hension claire des normes de conformit\u00e9 et d&rsquo;\u00e9thique<br>d&rsquo;International Medical Corps et des bailleurs et se conformer \u00e0 ces normes.<br>S&rsquo;il s&rsquo;agit d&rsquo;un poste de supervision, il faut donner l&rsquo;exemple d&rsquo;un comportement \u00e9thique par sa propre<br>conduite et la surveillance du travail des autres ; s&rsquo;assurer que ceux qui rel\u00e8vent de vous ont suffisamment de connaissances et de ressources pour suivre les normes d\u00e9crites dans le Code de conduite et d&rsquo;\u00e9thique ; surveiller la conformit\u00e9 des personnes que vous supervisez ; appliquer le code de conduite et d&rsquo;\u00e9thique et les politiques d&rsquo;International Medical Corps, y compris la politique de sauvegarde et la politique de protection contre le harc\u00e8lement, l&rsquo;intimidation et l&rsquo;inconduite sexuelle sur le lieu de travail, de mani\u00e8re coh\u00e9rente et \u00e9quitable ; soutenir les employ\u00e9s qui, de bonne foi, soul\u00e8vent des questions ou des pr\u00e9occupations.<br>Safeguarding :<br>Il est de la responsabilit\u00e9 et de l&rsquo;obligation partag\u00e9es de tout le personnel de sauvegarder et de prot\u00e9ger les; populations avec lesquelles nous travaillons, y compris les adultes qui peuvent \u00eatre particuli\u00e8rement vuln\u00e9rables et les enfants. Cela inclut la protection contre les comportements suivants de la part de notre personnel ou de nos partenaires : exploitation et abus sexuels ; l&rsquo;exploitation, la n\u00e9gligence ou la maltraitance d&rsquo;enfants, d&rsquo;adultes \u00e0 risque ou de personnes LGBTI ; et toute forme de traite des personnes.<br>Le personnel est \u00e9galement responsable de la pr\u00e9vention des violations de notre Code de conduite et<br>d&rsquo;\u00e9thique, qui peuvent impliquer des conflits d&rsquo;int\u00e9r\u00eats, la fraude, la corruption ou le harc\u00e8lement. Si vous voyez, entendez ou \u00eates inform\u00e9 de toute violation du Code de conduite et d&rsquo;\u00e9thique ou de la Politique de protection, vous avez l&rsquo;obligation de le signaler.<br>Egalit\u00e9 d\u2019opportunit\u00e9s :<br>International Medical Corps est fier d&rsquo;offrir des opportunit\u00e9s d&#8217;emploi \u00e9gales \u00e0 tous les employ\u00e9s et<br>candidats qualifi\u00e9s sans distinction de race, de couleur, de religion, de sexe, d&rsquo;orientation sexuelle, d&rsquo;origine nationale ou ethnique, d&rsquo;\u00e2ge, de handicap ou de statut d&rsquo;ancien combattant.<br>International Medical Corps ne sollicite aucun frais, ni paiement, ni aucune autre transaction<br>mon\u00e9taire des candidats \u00e0 un emploi. Si vous faites l\u2019objet d\u2019une sollicitation financi\u00e8re dans le<br>cadre de ce recrutement, veuillez-vous adresser \u00e0 International Medical Corps sur le site<br>Web:www.InternationalMedicalCorps.ethicspoint.com.<br><strong>Comment postuler<\/strong><br><strong>Composition du dossier de candidature\u00a0<\/strong>: CV et lettre de motivation ; Justificatifs du dipl\u00f4me et des<br>formations pr\u00e9sent\u00e9es ; Les attestations d\u2019emploi relatives \u00e0 l\u2019exp\u00e9rience professionnelle ; 3 R\u00e9f\u00e9rences<br>professionnelles ; Les dossiers de candidatures portant la mention \u00ab Candidature au poste d\u2019<br>d\u2019Infirmier (e)\u00bb\u00a0\u00e0 International Medical Corps \u00e0 l\u2019adresse \u00e9lectronique suivante<br> <br>NB : Seuls les Candidats pr\u00e9s\u00e9lectionn\u00e9s seront contact\u00e9s.<br><em>Pour Le Directeur National et par d\u00e9l\u00e9gation, la Coordonnatrice des Ressources Humaines<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via camrecruitments@internationalmedicalcorps.org<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[27],"tags":[],"villes":[141],"contrats":[236],"diplomes":[278],"louma_meta":{"emploi_title":"02 INFIRMIERS(ES)","emplois_employeur":3046,"emplois_date_publication":"2024-09-16","emplois_heure_publication":"08:34","emplois_date_cloture":"2024-09-18","emplois_heure_cloture":"17:00","emplois_experience_min":"2","emplois_experience_max":"","emploi_email":"camrecruitments@internationalmedicalcorps.org"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/49345"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=49345"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/49345\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=49345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=49345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=49345"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=49345"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=49345"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=49345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}