{"id":49343,"date":"2024-09-16T09:22:42","date_gmt":"2024-09-16T07:22:42","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=49343"},"modified":"2024-09-16T09:22:46","modified_gmt":"2024-09-16T07:22:46","slug":"logisticien-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/logisticien-2\/","title":{"rendered":"LOGISTICIEN"},"content":{"rendered":"\n<p>Cher reseau nous recrutons un logistien de terrain pour Bertoua.<br>Entreprise: Grassland Cameroon Ltd.<br>Superieur Hierarchique: Senior Procurement Officer<br>Lieu: R\u00e9gion de l\u2019Est Cameroun<br>Remuneration (net): 85 000 FCFA<\/p>\n\n\n\n<p>Grassland Cameroon Ltd. est une entreprise de stockage, de s\u00e9chage et de distribution de produits alimentaires qui s&rsquo;approvisionne aupr\u00e8s de petits agriculteurs que nous soutenons pendant la saison avec des pr\u00eats d&rsquo;intrants et une formation, afin qu&rsquo;ils puissent \u00eatre plus productifs. Nous transformons les produits des agriculteurs en produits standardis\u00e9s et class\u00e9s que nous vendons \u00e0 de grands acheteurs industriels qui peuvent \u00eatre s\u00fbrs de la qualit\u00e9 qu&rsquo;ils re\u00e7oivent.<\/p>\n\n\n\n<p><strong>Responsabilit\u00e9s<\/strong><br>Servir de convoyeur dans le camion de l&rsquo;entreprise et d\u2018agent logisticien sur le terrain;<br>Aider au suivi des travaux effectu\u00e9s par les camions sous contrat;<\/p>\n\n\n\n<p>Effectuez un entretien simple dans le camion : changement de pneus, vidange d&rsquo;huile;<br>Notez le poids des sacs de ma\u00efs lors des ramassages;<br>Effectuer des contr\u00f4les de qualit\u00e9 lors des ramassages;<br>Assister le chauffeur routier dans toutes ses activit\u00e9s;<br>Suivi des niveaux de carburant dans le camion.<\/p>\n\n\n\n<p><strong>Conditions<\/strong><br>Doit \u00eatre titulaire d\u2019un Baccalaur\u00e9at;<br>Avoir des connaissances en logistique;<br>Avoir des connaissances en m\u00e9canique de camion;<br>Doit \u00eatre capable \u00e0 s&rsquo;exprimer en anglais;<br>Avoir la capacit\u00e9 \u00e0 faire des rapports.<\/p>\n\n\n\n<p>Si vous \u00eates convaincu que ce poste est fait pour vous, nous avons h\u00e2te de faire votre connaissance.&nbsp;Veuillez postuler via ce lien (<a href=\"https:\/\/lnkd.in\/eKrMPAGH\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/lnkd.in\/eKrMPAGH<\/a>&nbsp;)&nbsp;au plus tard le 20.09.24.&nbsp;Dans votre lettre de motivation, veuillez pr\u00e9ciser ce qui vous motive le plus dans ce poste.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via https:\/\/lnkd.in\/eKrMPAGH<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[113],"tags":[],"villes":[144],"contrats":[148],"diplomes":[162],"louma_meta":{"emploi_title":"LOGISTICIEN","emplois_employeur":48690,"emplois_date_publication":"2024-09-16","emplois_heure_publication":"08:22","emplois_date_cloture":"2024-09-20","emplois_heure_cloture":"17:00","emplois_experience_min":"1","emplois_experience_max":"","emploi_email":"https:\/\/lnkd.in\/eKrMPAGH"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/49343"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=49343"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/49343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/48691"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=49343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=49343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=49343"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=49343"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=49343"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=49343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}