{"id":49260,"date":"2024-09-11T10:04:15","date_gmt":"2024-09-11T08:04:15","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=49260"},"modified":"2024-09-11T10:04:18","modified_gmt":"2024-09-11T08:04:18","slug":"02-charges-des-finances-h-f","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/02-charges-des-finances-h-f\/","title":{"rendered":"02 CHARGES DES FINANCES (H\/F)"},"content":{"rendered":"\n<p>POUR LE PROJET \u00ab DEVELOP, IMPLEMENT, AND SUSTAIN HIGH-QUALITY COMPREHENSIVE FACILITY AND COMMUNITY-BASED HIV 95-95-95<br>CASCADE ACTIVITIES FOR CHILDREN, ADOLESCENTS, AND ADULTS IN<br>CAMEROON UNDER THE PRESIDENT&rsquo;S EMERGENCY PLAN FOR AIDS<br>RELIEF (PEPFAR) \u00bb AU SEIN DE L&rsquo;ACMS<br>L&rsquo;Association Camerounaise pour le Marketing Social (ACMS), est une organisation non gouvernementale de droit Camerounais qui a pour mission principale d&rsquo;am\u00e9liorer de&nbsp; mani\u00e8re durable et mesurable la situation sociale de la population camerounaise et de promouvoir la sant\u00e9 et la prosp\u00e9rit\u00e9 des familles. Ainsi, ACMS travaille en coop\u00e9ration avec le gouvernement et ses partenaires des secteurs public et priv\u00e9 pour offrir des programmes de sant\u00e9 de haute qualit\u00e9, atteignant toutes les populations dans le besoin. Depuis plus de vingt-cinq ans, ACMS offre \u00e0 la population camerounaise des interventions de sant\u00e9 publique compl\u00e8tes et fond\u00e9es sur des preuves, notamment des programmes dans la sant\u00e9 de la reproduction, le paludisme et la pr\u00e9vention du VIH entre autres.<br>L&rsquo;Association Camerounaise pour le Marketing Social (ACMS) recherche des candidats (H IF) pour occuper les postes de Charges des Finances bas\u00e9s respectivement \u00e0 Ngaound\u00e9r\u00e9 et \u00e0 Garoua.<\/p>\n\n\n\n<p><br>Les Charg\u00e9s financiers auront la responsabilit\u00e9 globale d&rsquo;assurer l&rsquo;ensemble des op\u00e9rations financi\u00e8res men\u00e9es dans le cadre des contrats en conformit\u00e9 avec les politiques et proc\u00e9dures des bailleurs de fonds et celles de l&rsquo;ACMS. Ils travailleront sous la responsabilit\u00e9 du Responsable Financier Senior et du Coordonnateur r\u00e9gional avec pour principales responsabilit\u00e9s les fonctions suivantes<br>Assurer la r\u00e9ception et la revue de conformit\u00e9 et de compl\u00e9tude des documents financiers du projet en s&rsquo;appuyant sur les informations d\u00e9finies dans la check-list, le\u00a0 SOP ou le manuel de proc\u00e9dures administratif et financier ACMS<br>\u00a0\u00a0\u00a0 Bureau du Nord\u00a0\u00a0\u00a0 Bureau du Littoral\u00a0\u00a0\u00a0 Bureau de rExtr\u00eame-Nord<br>\u00a0\u00a0\u00a0 BP : 858 Garoua\u00a0\u00a0\u00a0 BP : 4989 Douala\u00a0\u00a0\u00a0 Maroua<br>\u00a0\u00a0\u00a0 T\u00e9l.: +(237) 693 92 92 56\u00a0\u00a0\u00a0 T\u00e9l.: +(237) 693 92 9256 E T\u00e9l.: +(237) 693 92 92 56<br><br>Bureau de l&rsquo;Adamaoua<br>Ngaound\u00e9r\u00e9<br>T\u00e9l.: +(237) 693 92 92 56<br>E-man : contact@acms.org www.acms-cm.org<br>1\u00a0\u00a0\u00a0 Bureau de rEst<br>Bertoua<br>T\u00e9l.: +(237) 693 92 92 56<br>Agr\u00e9\u00e9e par le<br>M%t\u00e8re de la Sant\u00e9 PubUque<br>NIU : M089600013745A<br><br>\u00a0 Contribuer \u00e0 la pr\u00e9paration des correspondances administratives, M\u00e9morandums, TDRs et pr\u00e9sentation PowerPoint des activit\u00e9s du service des finances du Projet\u00a0\u00a0\u00a0 Collaborer avec l&rsquo;\u00e9quipe du projet pour d\u00e9terminer le besoin de tr\u00e9sorerie sur une base mensuelle suivi de la transmission au Responsable Financier Senior ,<br>\u00a0 Pr\u00e9parer et r\u00e9aliser des paiements en esp\u00e8ce et via des plateformes de paiement mobile aux parties prenantes pour les activit\u00e9s en ce conform\u00e9ment aux diff\u00e9rents contr\u00f4les, proc\u00e9dures, politiques en vigueur \u00e0 ACMS et aux termes de r\u00e9f\u00e9rences approuv\u00e9s <\/p>\n\n\n\n<p><br>\u00a0 Assurer la revue de l&rsquo;exactitude des lignes budg\u00e9taires inscrites sur les demandes de paiement et les d\u00e9penses d&rsquo;activit\u00e9, la transmission au Responsable Financier Senior et le suivi de la validation ,<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Mettre \u00e0 jour quotidiennement l&rsquo;\u00e9tat de liquidation des avances aux staffs ;<br>\u00a0 Appuyer le Responsable Financier Senior dans le suivi ou la mise en \u0153uvre des recommandations d&rsquo;audits des processus financiers de la r\u00e9gion ,<br>\u00a0 Apporter une contribution \u00e0 la gestion des Audits Financiers en tant que premier rideau de contr\u00f4le de la qualit\u00e9 des pi\u00e8ces comptables, les contr\u00f4les des justificatifs et le contr\u00f4le du respect des proc\u00e9dures, ainsi qu&rsquo;\u00e0 la mise en oeuvre des\u00a0\u00a0 recommandations y relatives ,<br>\u00a0 Contribuer au rapprochement des comptes Orange Money du projet et aux lettrages des comptes du bilan ;<br>\u00a0 Produire et partager avec le Responsable Financier Senior mensuellement un \u00e9tat des rejets et r\u00e9clamations, effectuer des mises \u00e0 jour de cet \u00e9tat apr\u00e8s chaque paiement ;<br>\u00a0 Veiller \u00e0 l&rsquo;archivage syst\u00e9matique classique et \u00e9lectronique des pi\u00e8ces comptables, des dossiers li\u00e9s aux demandes d&rsquo;avances ;<br>\u00a0 Former et suivre les points focaux en mettant l&rsquo;accent sur les contr\u00f4les au niveau\u00a0 des lors du montage du masque de paiement de synth\u00e8se ,<br>\u00a0 Echanger avec les points focaux afin d&rsquo;obtenir les \u00e9tats de sommes dues num\u00e9riques (Excel) et les Pi\u00e8ces Jointes de qualit\u00e9 dans les d\u00e9lais ,<br>\u00a0 Compiler les \u00e9tats des sommes dues re\u00e7us des points focaux en vue de l&rsquo;\u00e9laboration de l&rsquo;\u00e9tat de paiement ;<br>\u00a0 V\u00e9rifier les doublons par district ;<br>\u00a0 Exploiter les proc\u00e8s-verbaux et les feuilles de travail des v\u00e9rifications des consultants afin d&rsquo;apurer l&rsquo;\u00e9tat de paiement ;<br>\u00a0\u00a0\u00a0\u00a0 Partager avec le Responsable Financier Senior, le Coordonnateur R\u00e9gional et le Sp\u00e9cialiste en Conformit\u00e9 les manquements qui n&rsquo;ont pas trouv\u00e9 solution \u00e0 son niveau ,<br>\u00a0 V\u00e9rifier les statistiques budg\u00e9taires (acteurs \/ activit\u00e9s \/ districts) ;<br>\u00a0 Faire la revue des pi\u00e8ces justificatives physiques avant initiation du paiement ,<br>\u00a0\u00a0\u00a0\u00a0 Transmettre l&rsquo;\u00e9tat de paiement par mail au Responsable Financier Senior et au Coordonnateur R\u00e9gional pour validation ;<br>\u00a0 Appuyer la pr\u00e9paration des d\u00e9penses d&rsquo;activit\u00e9s et assurer la mise \u00e0 jour quotidienne de l&rsquo;\u00e9tat des rejets classifi\u00e9 par cat\u00e9gorie de sa r\u00e9gion ,<br>\u00a0 Renseigner quotidiennement le tableau de suivi des paiements de sa r\u00e9gion afin d&rsquo;anticiper les doubles paiements ,<br>\u00a0 S&rsquo;assurer de la num\u00e9risation des pi\u00e8ces justificatives avant leur transmission pour comptabilisation.<br><strong>Qualifications et comp\u00e9tences requises :<\/strong><br>\u00a0 \u00catre titulaire au moins d&rsquo;un dipl\u00f4me de Bac + 3 en Comptabilit\u00e9, Finances, Contr\u00f4le de gestion ou autre dipl\u00f4me \u00e9quivalent ;<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Avoir au moins 3 ann\u00e9es d&rsquo;exp\u00e9rience \u00e0 un poste similaire dans d&rsquo;un organisme de d\u00e9veloppement, une ONG, un projet ou une entreprise de grande envergure.<br>&nbsp;Une exp\u00e9rience pertinente dans une ONG internationale sera un atout ,<br>&nbsp;&nbsp;&nbsp;&nbsp; Avoir de bonnes comp\u00e9tences communicationnelles et des connaissances de l&rsquo;outil informatique, logiciels du paquet Office (Word, Excel, Powerpoint, Outlook), la ma\u00eetrise d&rsquo;un logiciel de comptabilit\u00e9 serait un atout ,<br>0 Avoir des comp\u00e9tences en gestion des audits afin de pouvoir r\u00e9pondre aux diverses recommandations d&rsquo;audit de l&rsquo;ACMS et \u00eatre en mesure d&rsquo;am\u00e9liorer les op\u00e9rations en cons\u00e9quence.<br>Comment constituer votre Dossier de candidature ?<br>&nbsp;Une Lettre de motivation<br>&nbsp;Un curriculum vitae d\u00e9taill\u00e9 (CV)<br>&nbsp;&nbsp;&nbsp;&nbsp; Photocopies des dipl\u00f4mes exig\u00e9s. Une v\u00e9rification des Dipl\u00f4mes sera effectu\u00e9e pour le candidat retenu<br>&nbsp;&nbsp;&nbsp;&nbsp; Les photocopies des documents qui justifient l&rsquo;exp\u00e9rience du candidat, (Attestation,&nbsp; d&#8217;emploi, certificat de travail, ou tout autre document y relatif).<\/p>\n\n\n\n<p><strong>Votre dossier de candidature :<\/strong><br>Les&nbsp;&nbsp;&nbsp; dossiers&nbsp;&nbsp;&nbsp; complets&nbsp;&nbsp;&nbsp; seront&nbsp;&nbsp;&nbsp; envoy\u00e9s uniquement \u00e0&nbsp;&nbsp;&nbsp; l&rsquo;adresse suivante : CM_recrutement@acms-cmr.org<\/p>\n\n\n\n<p><br><strong>Notre politique d&#8217;emploi<\/strong><br>L&rsquo;ACMS est un employeur qui souscrit au principe de l&rsquo;\u00e9galit\u00e9 des chances et encourage les candidatures qualifi\u00e9es des personnes de tous les sexes.<br>Seuls les candidats pr\u00e9s\u00e9lectionn\u00e9s seront contact\u00e9s.<br>L&rsquo;ACMS se r\u00e9serve le droit de proc\u00e9der \u00e0 un recrutement \u00e0 un niveau inf\u00e9rieur ou sur la base d&rsquo;un profil de poste modifi\u00e9.<br>Le candidat retenu devra passer une v\u00e9rification des ant\u00e9c\u00e9dents.<br>\u00a0Les candidats fonctionnaires doivent \u00eatre en r\u00e8gle avec leur administration avant signature du contrat de travail d\u00e9finitif avec l&rsquo;ACMS.<br>Informations cl\u00e9s sur le poste :<br>Type de contrat : Permanent, Contrat \u00e0 Dur\u00e9e Ind\u00e9termin\u00e9e li\u00e9 au projet<br>Niveau du poste  \u202210i\u00e8me cat\u00e9gorie, du secteur tertiaire Il de la Convention<br>Collective Nationale du Commerce Lieu de travail : Ngaound\u00e9r\u00e9 et Garoua<br>Type de poste : Interm\u00e9diaire<br>Date de prise de fonction : octobre 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via CM_recrutement@acms-cmr.org<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[23],"tags":[],"villes":[2714],"contrats":[236],"diplomes":[212],"louma_meta":{"emploi_title":"02 CHARGES DES FINANCES (H\/F)","emplois_employeur":3436,"emplois_date_publication":"2024-09-11","emplois_heure_publication":"09:04","emplois_date_cloture":"2024-09-25","emplois_heure_cloture":"17:00","emplois_experience_min":"3","emplois_experience_max":"","emploi_email":"CM_recrutement@acms-cmr.org"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/49260"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=49260"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/49260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3437"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=49260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=49260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=49260"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=49260"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=49260"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=49260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}