{"id":49228,"date":"2024-09-09T10:13:34","date_gmt":"2024-09-09T08:13:34","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=49228"},"modified":"2024-09-09T10:13:38","modified_gmt":"2024-09-09T08:13:38","slug":"responsable-logistique-approvisionnement","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/responsable-logistique-approvisionnement\/","title":{"rendered":"Responsable Logistique\/Approvisionnement"},"content":{"rendered":"\n<p>Projet : Programme d\u2019Appui \u00e0 la R\u00e9silience Communautaire au<br>Cameroun<br>&nbsp;(PARC-Cameroun)<\/p>\n\n\n\n<p>FHI 360 est une organisation \u00e0 but non lucratif qui mobilise la recherche, lesaux opportunit\u00e9s dont elles ont besoin pour mener une vie saine et \u00e9panouie. Avec<br>des collaborations dans plus de 60 pays, nous travaillons directement avec les<br>dirigeants locaux pour faire progresser l&rsquo;\u00e9quit\u00e9 sociale et \u00e9conomique, am\u00e9liorer la<br>sant\u00e9 et le bien-\u00eatre, r\u00e9pondre aux crises humanitaires et renforcer la r\u00e9silience des<br>communaut\u00e9s. Nous partageons des connaissances fond\u00e9es sur des donn\u00e9es et des<br>outils \u00e9volutifs qui \u00e9largissent l&rsquo;acc\u00e8s et l&rsquo;\u00e9quit\u00e9 afin que les communaut\u00e9s puissent<br>relever efficacement des d\u00e9fis complexes, r\u00e9pondre aux crises et s&rsquo;assurer un avenir<br>prosp\u00e8re.<br>FHI 360 recrute actuellement un Responsable Logistique\/Approvisionnement,<br>S\u00fbret\u00e9 et S\u00e9curit\u00e9 pour le Programme d&rsquo;Appui \u00e0 la R\u00e9silience Communautaire au<br>Cameroun (PARC-Cameroun), financ\u00e9 par l&rsquo;USAID. PARC-Cameroun soutient le<br>renforcement des capacit\u00e9s institutionnelles des organisations de la soci\u00e9t\u00e9 civile<br>locale au Cameroun afin qu&rsquo;elles puissent mieux repr\u00e9senter et servir leurs<br>communaut\u00e9s et contribuer \u00e0 la r\u00e9alisation de leurs objectifs de d\u00e9veloppement.<br><strong>RESUME DU POSTE<\/strong><br>Le poste de Responsable Logistique\/Approvisionnement S\u00fbret\u00e9 &amp; S\u00e9curit\u00e9 sera<br>bas\u00e9 \u00e0 Yaound\u00e9, dans la r\u00e9gion du Centre et sera supervis\u00e9 par le Directeur de<br>ressources et les partenariats afin que les populations du monde entier aient acc\u00e8s l&rsquo;Administration et des Finances. Il\/elle sera responsable de toutes les activit\u00e9s li\u00e9es<br>\u00e0 l&rsquo;acquisition de biens et de services, y compris les services des fournisseurs et des<br>consultants pour le bureau. Il\/elle g\u00e8re tous les contrats de services et de consultants<br>ainsi que les subventions ou les sous-contrats pour s&rsquo;assurer que les termes et<br>conditions sont respect\u00e9s et que les contrats sont tenus \u00e0 jour.<br>Le Responsable de la logistique et de la s\u00e9curit\u00e9 ex\u00e9cutera tous les programmes,<br>plans et politiques de s\u00e9curit\u00e9 et de s\u00fbret\u00e9 pertinents pour le projet, y compris les proc\u00e9dures de s\u00e9curit\u00e9 d\u00e9taill\u00e9es conformes aux politiques de s\u00e9curit\u00e9 de FHI 360.<br>Cela comprendra des exercices d&rsquo;intervention d&rsquo;urgence et des proc\u00e9dures de<br>communication pour le projet.<\/p>\n\n\n\n<p><br><strong>FONCTIONS ET RESPONSABILIT\u00c9S<\/strong><br>\u2022 Assurer la s\u00e9curit\u00e9, la s\u00fbret\u00e9 et l&rsquo;att\u00e9nuation des risques et s&rsquo;assurer que le<br>personnel du projet respecte les proc\u00e9dures de s\u00e9curit\u00e9 du projet.<br>\u2022 Surveiller et analyser l&rsquo;environnement de menace continu auquel est<br>confront\u00e9 le projet et informer la direction en cons\u00e9quence. Distribuer les<br>avertissements de menace \u00e0 tout le personnel, le cas \u00e9ch\u00e9ant.<br>\u2022 Veiller \u00e0 ce que des mesures d&rsquo;att\u00e9nuation des risques appropri\u00e9es soient<br>prises par le projet pour r\u00e9pondre aux menaces ou aux changements de<br>menaces auxquels le projet est confront\u00e9. Cela doit inclure des mesures de protection physique, des routines de travail s\u00fbres, des restrictions de<br>mouvement, des \u00e9quipements de protection et la mise \u00e0 disposition de<br>personnel de s\u00e9curit\u00e9, selon les besoins.<br>\u2022 Superviser le contr\u00f4le et la coordination des mouvements pour le projet, le<br>transport et les d\u00e9placements du personnel.<br>\u2022 Superviser tout fournisseur de s\u00e9curit\u00e9 engag\u00e9 par le projet pour assurer la<br>conformit\u00e9 contractuelle et l&rsquo;ex\u00e9cution de leurs t\u00e2ches, et agir en tant que<br>point de contact central avec le fournisseur de s\u00e9curit\u00e9.<br>\u2022 Signaler les incidents de s\u00e9curit\u00e9, les violations et les actions correctives <\/p>\n\n\n\n<p>recommand\u00e9es, le cas \u00e9ch\u00e9ant, au COP, \u00e0 l&rsquo;autorit\u00e9 de nomination et au<br>D\u00e9partement de la s\u00e9curit\u00e9 du si\u00e8ge.<br>\u2022 S&rsquo;assurer que tous les nouveaux employ\u00e9s\/entrepreneurs re\u00e7oivent des<br>orientations et des briefings de s\u00e9curit\u00e9 appropri\u00e9s.<br>\u2022 V\u00e9rifier que tous les dispositifs de s\u00e9curit\u00e9 tels que les serrures, les alarmes,<br>les syst\u00e8mes d&rsquo;acc\u00e8s et les mesures de protection contre la force physique<br>sont op\u00e9rationnels ou signal\u00e9s pour r\u00e9paration.<br>\u2022 Veiller \u00e0 ce que les syst\u00e8mes d&rsquo;acc\u00e8s des visiteurs et de contr\u00f4le des v\u00e9hicules<br>soient efficaces et adapt\u00e9s \u00e0 l&rsquo;environnement de menace.<br>\u2022 Travailler avec le responsable de la s\u00e9curit\u00e9 du si\u00e8ge pour maintenir le plan<br>de r\u00e9ponse aux crises du projet en coordination avec le COP et s&rsquo;assurer que<br>les informations de contact qui y sont contenues sont toujours \u00e0 jour.<br>\u2022 Fournir un rapport de s\u00e9curit\u00e9 hebdomadaire \u00e0 la direction du projet et au<br>d\u00e9partement de s\u00e9curit\u00e9 du si\u00e8ge.<br>\u2022 \u00catre en mesure d&rsquo;aider \u00e0 l&rsquo;intervention d&rsquo;urgence en dehors des heures<br>d&rsquo;ouverture du projet, si n\u00e9cessaire.<br>\u2022 Servir de liaison avec l&rsquo;agent de s\u00e9curit\u00e9 r\u00e9gional de l&rsquo;ambassade des \u00c9tatsUnis et\/ou le personnel \u00e9quivalent du gouvernement am\u00e9ricain pour les<br>questions de s\u00e9curit\u00e9 du projet.<br>\u2022 Assister le projet avec la planification de la continuit\u00e9 des affaires, au besoin.<br>\u2022 G\u00e9rer le processus de tous les achats, y compris les appels d&rsquo;offres et le<br>processus de s\u00e9lection.<br>\u2022 Superviser et maintenir tous les contrats de service, les accords de consultants<br>et les baux pour tous les bureaux du Cameroun.<br>\u2022 Suivre tous les contrats, accords de consultants et autres achats pour<br>s&rsquo;assurer que la cl\u00f4ture, les renouvellements ou les nouvelles offres se font<br>en temps voulu.<br>\u2022 Suivre et surveiller les d\u00e9lais de livraison et fournir des mises \u00e0 jour r\u00e9guli\u00e8res<br>au personnel technique pour s&rsquo;assurer que les d\u00e9lais sont respect\u00e9s.<br>\u2022 Tenir \u00e0 jour tous les dossiers d&rsquo;approvisionnement, y compris toute la<br>documentation n\u00e9cessaire, pour les biens et services, les consultants, les<br>subventions et les contrats de sous-traitance et tout autre contrat ou accord.<br>\u2022 V\u00e9rifier les biens\/services re\u00e7us pour s&rsquo;assurer que les commandes sont<br>correctement remplies et que les biens r\u00e9pondent aux sp\u00e9cifications.<br>\u2022 Travailler avec le responsable des op\u00e9rations et des finances sur le processus<br>d&rsquo;approvisionnement pour tous les besoins de gestion du bureau.<br>\u2022 Aider \u00e0 l&rsquo;affichage des nouvelles embauches des consultants pour s&rsquo;assurer<br>que les offres d&#8217;emploi sont annonc\u00e9es de mani\u00e8re coh\u00e9rente avec les autres<br>achats et de la mani\u00e8re la plus efficace possible.<br>\u2022 Suivre les pr\u00e9occupations et r\u00e9pondre aux questions du personnel technique<br>concernant les contrats et la conformit\u00e9 des clients ; conseiller et prendre des<br>mesures correctives.<br>\u2022 N\u00e9gocier les prix et les conditions de tous les contrats et accords de<br>consultants.<br>\u2022 G\u00e9rer et examiner annuellement la performance des fournisseurs pour tous<br>les bureaux de projet, mener la documentation appropri\u00e9e et le processus de<br>nouvel appel d&rsquo;offres si n\u00e9cessaire en cas de non-performance du<br>fournisseur.<br>\u2022 Maintenir une connaissance \u00e0 jour des processus et politiques<br>d&rsquo;approvisionnement de FHI 360 ainsi que des lois locales et des meilleures<br>pratiques en mati\u00e8re d&rsquo;approvisionnement.<br>\u2022 Agir en tant que liaison avec la comptabilit\u00e9 pour s&rsquo;assurer que les bons de<br>commande sont pay\u00e9s \u00e0 \u00e9ch\u00e9ance et que les comptes sont tenus \u00e0 jour.<br>\u2022 Travailler avec l&rsquo;\u00e9quipe des op\u00e9rations sur le suivi des actifs pour tous les<br>actifs et s&rsquo;assurer que l&rsquo;inventaire annuel est complet.<br>\u2022 Former le personnel aux proc\u00e9dures et politiques d&rsquo;approvisionnement et aux<br>exigences en mati\u00e8re de documentation.<br>\u2022 Participer \u00e0 l&rsquo;\u00e9laboration et \u00e0 la r\u00e9vision des proc\u00e9dures et politiques<br>d&rsquo;approvisionnement.<br>\u2022 Effectuer d&rsquo;autres t\u00e2ches selon les besoins.<br>CONNAISSANCES, COMP\u00c9TENCES ET CAPACIT\u00c9S, EXPERTISE ET COMPLEXIT\u00c9<br>\u2022 Articulation, professionnalisme et capacit\u00e9 \u00e0 communiquer de mani\u00e8re claire<br>et positive avec les clients.<br>\u2022 Connaissance approfondie des normes et pratiques en mati\u00e8re<br>d&rsquo;approvisionnement.<br>\u2022 Connaissance pratique des politiques et proc\u00e9dures de l&rsquo;entreprise<br>concernant les achats, les consultants et les contrats.<br>\u2022 Capacit\u00e9 \u00e0 travailler de mani\u00e8re ind\u00e9pendante et \u00e0 g\u00e9rer les processus et les<br>d\u00e9lais avec une supervision limit\u00e9e.<br>\u2022 Excellente aptitude \u00e0 travailler en \u00e9quipe.<br>\u2022 Poss\u00e9der de bonnes comp\u00e9tences en mati\u00e8re de planification, d&rsquo;organisation<br>et de relations interpersonnelles.<br>\u2022 Capacit\u00e9 d&rsquo;analyser l&rsquo;information et d&rsquo;exercer son jugement lors de la prise<br>de d\u00e9cisions dans le contexte des politiques et proc\u00e9dures \u00e9tablies.<br>\u2022 Ma\u00eetrise des logiciels informatiques, par exemple MS-Word, MS-Excel, MS<br>Outlook et MS PowerPoint.<br>\u2022 Doit \u00eatre autonome et avoir le souci du d\u00e9tail.<br>\u2022 Familiarit\u00e9 avec le travail avec les organisations internationales et les<br>r\u00e8glements de l&rsquo;USAID.<\/p>\n\n\n\n<p><br>EXIGENCES MINIMALES<br>\u2022 Licence ou son \u00e9quivalent international en administration des affaires ou dans<br>un domaine connexe.<br>\u2022 Minimum de 5 ans d&rsquo;exp\u00e9rience en approvisionnement.<br>\u2022 Doit avoir une exp\u00e9rience professionnelle pr\u00e9alable sur des programmes<br>financ\u00e9s par l&rsquo;USAID.<br>\u2022 Connaissance pratique des logiciels de bureautique, notamment WORD, Excel,<br>PowerPoint, Outlook et Microsoft Teams.<br>\u2022 Doit avoir d&rsquo;excellentes comp\u00e9tences en communication et une bonne<br>ma\u00eetrise de l&rsquo;anglais et du fran\u00e7ais \u00e9crit et parl\u00e9.<br>\u2022 Doit faire preuve d&rsquo;une grande int\u00e9grit\u00e9.<br>\u2022 Exp\u00e9rience de l&rsquo;\u00e9tablissement de solides relations de travail avec des<br>coll\u00e8gues d&rsquo;organisations et de cultures diff\u00e9rentes.<br>\u2022 Capacit\u00e9 \u00e0 respecter les d\u00e9lais avec une forte attention \u00e0 la coh\u00e9rence, aux<br>d\u00e9tails et \u00e0 la qualit\u00e9.<br>\u2022 Capacit\u00e9 \u00e0 voyager dans le pays si n\u00e9cessaire.<br>\u2022 Autorisation de travailler au Cameroun.<\/p>\n\n\n\n<p>La pr\u00e9sente description de poste r\u00e9sume les principales fonctions du poste. Elle ne<br>prescrit ni ne restreint les t\u00e2ches exactes qui peuvent \u00eatre assign\u00e9es pour mener \u00e0<br>bien ces fonctions. Ce document ne doit en aucun cas \u00eatre interpr\u00e9t\u00e9 comme<br>repr\u00e9sentant un contrat de travail. La direction se r\u00e9serve le droit de revoir et de<br>r\u00e9viser ce document \u00e0 tout moment.<\/p>\n\n\n\n<p><br>COMMENT POSTULER<br>Les candidats doivent soumettre leur candidature, y compris leur CV et leur lettre de<br>motivation, par courriel \u00e0 l\u2019adresse cameroonrecruitment@fhi360.org au plus tard le<br>20 Septembre 2024, \u00e0 17 heures, du Cameroun.<br>L&rsquo;objet du courriel doit inclure \u00ab\u00a0Responsable Logistique\/Approvisionnement<br>S\u00fbret\u00e9 &amp; S\u00e9curit\u00e9\u00a0\u00bb. Nous appr\u00e9cions tout int\u00e9r\u00eat pour ce poste, mais seuls les<br>candidats pr\u00e9s\u00e9lectionn\u00e9s seront contact\u00e9s. Aussit\u00f4t, le profil recherch\u00e9 trouv\u00e9,<br>l\u2019offre sera ferm\u00e9e.<br>FHI 360 est un employeur qui pr\u00f4ne l&rsquo;\u00e9galit\u00e9 des chances et l&rsquo;action positive. FHI 360<br>est un employeur qui pr\u00f4ne l&rsquo;\u00e9galit\u00e9 d&rsquo;acc\u00e8s \u00e0 l&#8217;emploi et l&rsquo;action positive et qui ne<br>s&rsquo;engage pas dans des pratiques discriminatoires \u00e0 l&rsquo;\u00e9gard des personnes<br>employ\u00e9es ou \u00e0 la recherche d&rsquo;un emploi sur la base de la race, de la couleur, de la<br>religion, du sexe, de l&rsquo;orientation sexuelle, de l&rsquo;identit\u00e9 de genre, de l&rsquo;origine<br>nationale ou ethnique, de l&rsquo;\u00e2ge, de l&rsquo;\u00e9tat civil, du handicap, du statut d&rsquo;ancien<br>combattant, de l&rsquo;information g\u00e9n\u00e9tique ou de tout autre statut ou caract\u00e9ristique<br>prot\u00e9g\u00e9 par la l\u00e9gislation en vigueur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via  cameroonrecruitment@fhi360.org<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[3006],"tags":[],"villes":[136],"contrats":[236],"diplomes":[212],"louma_meta":{"emploi_title":"Responsable Logistique\/Approvisionnement","emplois_employeur":12877,"emplois_date_publication":"2024-09-09","emplois_heure_publication":"09:13","emplois_date_cloture":"2024-09-20","emplois_heure_cloture":"17:00","emplois_experience_min":"5","emplois_experience_max":"","emploi_email":" cameroonrecruitment@fhi360.org"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/49228"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=49228"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/49228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/12878"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=49228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=49228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=49228"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=49228"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=49228"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=49228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}