{"id":49195,"date":"2024-09-03T14:18:36","date_gmt":"2024-09-03T12:18:36","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=49195"},"modified":"2024-09-03T14:18:39","modified_gmt":"2024-09-03T12:18:39","slug":"assistant-administratif","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/assistant-administratif\/","title":{"rendered":"Assistant Administratif"},"content":{"rendered":"\n<figure class=\"wp-block-table\"><table><tbody><tr><td colspan=\"2\">&nbsp; Accueil physique et t\u00e9l\u00e9phonique des usagers&nbsp;;Gestion de l\u2019agenda du promoteur&nbsp;;Concevoir le calendrier acad\u00e9mique et veiller \u00e0 son application&nbsp;;Produire les comptes rendus&nbsp;de r\u00e9unions ;Veiller au respect des engagements de l\u2019\u00e9tablissement vis-\u00e0-vis de ses diff\u00e9rents partenaires et vice versa&nbsp;;Planifier les enseignements et veiller au remplissage des cahiers de texte&nbsp;;Planifier et superviser les pratiques sur le site&nbsp;;G\u00e9rer les dossiers d\u2019inscriptions des \u00e9tudiants&nbsp;et requ\u00eates ;Veiller au respect et \u00e0 l\u2019application des diff\u00e9rents programmes de cours (respect du syllabus)&nbsp;;G\u00e9rer les diff\u00e9rents courriers de la structure ;Produire les lettres d\u2019engagement des diff\u00e9rents \u00e9tudiants&nbsp;;Organiser les diff\u00e9rents examens et&nbsp;g\u00e9rer le secr\u00e9tariat de ceux-ci&nbsp;;Veiller au respect des proc\u00e9dures et du r\u00e8glement int\u00e9rieur&nbsp;en vigueur ;Suivre les activit\u00e9s de la ferme dans sa globalit\u00e9&nbsp;et produire le reporting ;G\u00e9rer des audiences&nbsp;;Assurer la distribution des tenues de pratiques aux apprenants&nbsp;;Veiller au respect des r\u00e8gles d\u2019hygi\u00e8ne et \u00e0 la propret\u00e9 des locaux&nbsp;;Effectuer le classement et l\u2019archivage des documents administratifs&nbsp;;Effectuer toute autres t\u00e2ches professionnelles confi\u00e9es par la hi\u00e9rarchie.<\/td><\/tr><tr><td><strong>&nbsp;<\/strong> <strong>QUALIFICATIONS ET EXPERIENCE REQUISES<\/strong><\/td><td><strong>&nbsp;<\/strong> <strong>COMPETENCES REQUISES<\/strong><\/td><\/tr><tr><td>Niveau acad\u00e9mique&nbsp;: <strong>Minimum BTS<\/strong>&nbsp;en&nbsp;: Comptabilit\u00e9, Secr\u00e9tariat de Direction, Gestion des ressources humaines, marketing strat\u00e9gique, communication et organisation des entreprises.<strong>Exp\u00e9rience professionnelle<\/strong>&nbsp;: <strong>Deux (02) ans minimum \u00e0 un poste similaire<\/strong>Des connaissances en&nbsp;:Maitrise des outils informatiques (Tableur, Traitement de texte\u2026) et t\u00e9l\u00e9phoniques.Notions en droits et management&nbsp;;N\u00e9gociation et vente. <strong>&nbsp;<\/strong><\/td><td><strong><u>Savoir Faire<\/u><\/strong>&nbsp;: Traiter les requ\u00eates des apprenants&nbsp;;R\u00e9pondre aux appels t\u00e9l\u00e9phoniques et mails&nbsp;; <strong><u>Savoir-\u00catre&nbsp;:<\/u><\/strong> Forte capacit\u00e9 d\u2019adaptation&nbsp;;Avoir un esprit d\u2019initiative&nbsp;;Courtoisie&nbsp;;Un sens de l\u2019\u00e9coute et de disponibilit\u00e9&nbsp;;Dynamisme, ma\u00eetrise de soi, Autonomie, Bonne capacit\u00e9 communicationnelle&nbsp;;Bonne capacit\u00e9 r\u00e9dactionnelle ;Capable de diriger une \u00e9quipe&nbsp;;Rigueur, organisation et sens des priorit\u00e9s&nbsp;;Avoir le go\u00fbt des chiffres&nbsp;; \u00catre force de proposition.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong><em><u>D\u00e9p\u00f4t des candidatures<\/u><\/em><\/strong>&nbsp;:<\/p>\n\n\n\n<p>Vous \u00eates pri\u00e9s de bien vouloir nous faire parvenir vos <strong>lettres de motivation<\/strong> et <strong>Curriculum Vitae (CV)<\/strong> \u00e0 l\u2019adresse&nbsp;: <a href=\"mailto:groupeemakfish@gmail.com\"><strong>groupeemakfish@gmail.com<\/strong><\/a><strong> ou via WhatsApp au num\u00e9ro 659 59 37 34 <\/strong>au plus tard le<strong> mercredi 11 Septembre 2024 \u00e0 17h30 min<\/strong> en pr\u00e9cisant en objet&nbsp;: <strong>Assistant(e) Administratif(e<\/strong>).<strong><\/strong><\/p>\n\n\n\n<p><strong>N.B&nbsp;: <\/strong>Les candidatures f\u00e9minines sont vivement encourag\u00e9es<strong>. <\/strong>Vous devez vivre aux environs<strong> <\/strong>des quartiers ci-apr\u00e8s<strong>&nbsp;: <\/strong>NGOUSSO<strong>,<\/strong> NKOABANG, ELEVEUR, FOUGEROL, SOA, MIMBOMAN.<strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><strong>Toute candidature re\u00e7ue par un canal autre que celui indiqu\u00e9 ne sera pas pris en compte.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via groupeemakfish@gmail.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[2519],"tags":[],"villes":[136],"contrats":[148],"diplomes":[248],"louma_meta":{"emploi_title":"Assistant Administratif","emplois_employeur":3046,"emplois_date_publication":"2024-09-03","emplois_heure_publication":"13:18","emplois_date_cloture":"2024-09-11","emplois_heure_cloture":"17:30","emplois_experience_min":"2","emplois_experience_max":"","emploi_email":"groupeemakfish@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/49195"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=49195"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/49195\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=49195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=49195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=49195"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=49195"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=49195"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=49195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}