{"id":49153,"date":"2024-09-02T10:04:38","date_gmt":"2024-09-02T08:04:38","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=49153"},"modified":"2024-09-02T10:04:45","modified_gmt":"2024-09-02T08:04:45","slug":"information-technology-as","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/information-technology-as\/","title":{"rendered":"Information Technology AS"},"content":{"rendered":"\n<p>CHOCOCAM TIGER BRANDS recherche pour les besoins de ses activit\u00e9s 01 Information Technology Application Specialist.<\/p>\n\n\n\n<p><strong>MISSION PRINCIPALE<\/strong><\/p>\n\n\n\n<p>Sous la responsabilit\u00e9 du IT Manager, l\u2019IT Applications Specialist a pour principale mission de garantir le bon fonctionnement du Syst\u00e8me d&rsquo;Information, tant sur la disponibilit\u00e9 que sur la fiabilit\u00e9 et l\u2019\u00e9volution de l\u2019ensemble du parc applicatif de l\u2019entreprise.<\/p>\n\n\n\n<p><strong>Que Ferez-vous ?<\/strong><\/p>\n\n\n\n<p>Assurer un support technique de niveau 1 aux utilisateurs;<br>\u00a0Reporter et suivre les incidents de niveau 2 et 3 \u00e0 l\u2019\u00e9quipe Support du Groupe;<\/p>\n\n\n\n<p>R\u00e9diger et maintenir les documentations fonctionnelles permettant la r\u00e9solution et le traitement des incidents et des demandes des utilisateurs;<br>Assister les utilisateurs lors des tests de recette de projet;<br>\u00a0Participer \u00e0 l\u2019analyse fonctionnelle d\u00e9taill\u00e9e des besoins utilisateurs;<br>\u00a0\u00c9tudier les opportunit\u00e9s et la faisabilit\u00e9 technologique des applications;<br>\u00a0\u00c9laborer et r\u00e9diger les cahiers des charges techniques n\u00e9cessaires, \u00e0 partir des sp\u00e9cifications fonctionnelles;<br>D\u00e9velopper les \u00ab univers \u00bb et les rapports;<br>Int\u00e9grer les nouvelles donn\u00e9es dans le reporting existant;<br>\u00a0Assurer la pr\u00e9sentation des donn\u00e9es selon les besoins des utilisateurs;<br>\u00a0Assurer la formation des utilisateurs \u00e0 l\u2019utilisation des outils d\u00e9cisionnels;<br>\u00a0G\u00e9rer les acc\u00e8s utilisateurs aux diff\u00e9rentes applications et effectuer le contr\u00f4le des habilitations;<br>\u00a0S\u2019assurer que les sauvegardes sont bien effectu\u00e9es aussi bien pour les applications que pour les bases de donn\u00e9es;<br>\u00a0S\u2019assurer de la r\u00e9cup\u00e9ration des donn\u00e9es et la remise en condition op\u00e9rationnelle des bases de donn\u00e9es et applications en cas d\u2019incident (disaster recovery);<\/p>\n\n\n\n<p>&nbsp;Assurer une veille technologique afin de maintenir l\u2019ad\u00e9quation des sp\u00e9cificit\u00e9s des applications aux besoins de l\u2019entreprise;<br>&nbsp;Suivre et contr\u00f4ler les \u00e9volutions de version des applications existantes pour les faire \u00e9voluer<br>&nbsp;Assurer la mise \u00e0 jour de la documentation sur la structure de la base des donn\u00e9es, des applications et les proc\u00e9dures d\u2019exploitation et de production;<br>&nbsp;Proposer et pr\u00e9senter de nouveaux produits ou les nouvelles versions au Management.<\/p>\n\n\n\n<p><strong>Qualification et exp\u00e9rience professionnelle<\/strong><br>&nbsp;BAC+3\/4 dans une fili\u00e8re d\u2019ing\u00e9nierie informatique avec au moins trois (03) ans d\u2019exp\u00e9rience dans le domaine informatique.<\/p>\n\n\n\n<p>Exigences particuli\u00e8res (Savoirs \u2013 Savoir-faire \u2013 Savoir-\u00eatre) :<br>&nbsp;Bonne connaissance en informatique de gestion (logiciels et progiciels) ;<br>Bonne connaissance des bases de donn\u00e9es Oracle, MS SQL Server;<br>&nbsp;Bonne maitrise des outils de reporting statique de type Business Object (BO) BAC+3\/4 dans une fili\u00e8re d\u2019ing\u00e9nierie informatique, Oracle Toad ;<br>&nbsp;\u00catre capable de d\u00e9velopper des applications avec Microsoft Office 365 ;<br>Avoir le sens de l\u2019\u00e9coute ;<br>Avoir un sens \u00e9lev\u00e9 d\u2019analyse ;<br>Polyvalence;<br>Int\u00e9grit\u00e9.<\/p>\n\n\n\n<p>Cat\u00e9gorie du poste<br>Max : Cat\u00e9gorie 9<br>Min : Cat\u00e9gorie 8<\/p>\n\n\n\n<p><strong>COMMENT POSTULER<\/strong> ?<\/p>\n\n\n\n<p>Veuillez nous envoyer votre CV et lettre de motivation (de pr\u00e9f\u00e9rence sous fichier non modifiable) \u00e0 l\u2019adresse : chococam.recruit@tigerbrands.com<\/p>\n\n\n\n<p>Date de Cl\u00f4ture de r\u00e9ception des CVs et lettre de motivation : 08\/09\/2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via  chococam.recruit@tigerbrands.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[22],"tags":[],"villes":[135],"contrats":[148],"diplomes":[212,159],"louma_meta":{"emploi_title":"Information Technology AS","emplois_employeur":5282,"emplois_date_publication":"2024-09-02","emplois_heure_publication":"09:01","emplois_date_cloture":"2024-09-08","emplois_heure_cloture":"17:00","emplois_experience_min":"3","emplois_experience_max":"","emploi_email":" chococam.recruit@tigerbrands.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/49153"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=49153"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/49153\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/5283"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=49153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=49153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=49153"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=49153"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=49153"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=49153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}