{"id":48914,"date":"2024-08-13T18:16:12","date_gmt":"2024-08-13T18:16:12","guid":{"rendered":""},"modified":"2024-08-13T20:57:30","modified_gmt":"2024-08-13T18:57:30","slug":"comptable-39","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/comptable-39\/","title":{"rendered":"COMPTABLE"},"content":{"rendered":"<div>NYAMORO GROUP SA est une entreprise sp&eacute;cialis&eacute;e dans l&rsquo;incubation de projets innovants et le placement financier. Elle dispose en son sein de plusieurs autres entit&eacute;s qui composent son groupe de soci&eacute;t&eacute;s.<\/div>\n<div>&nbsp;<\/div>\n<div>Le poste ouvert dans notre branche financi&egrave;re vise &agrave; contr&ocirc;ler les flux, traiter des actions financi&egrave;res, p&eacute;renniser l&rsquo;&eacute;volution des finances, surveiller les activit&eacute;s marchandes, faire la comptabilit&eacute;, et s&rsquo;obliger &agrave; une croissance. Ce poste exige beaucoup d&rsquo;assiduit&eacute;, un QI assez en place, et beaucoup de d&eacute;vouement ; Car NYAMORO GROUP SA est un v&eacute;ritable challenge.<\/div>\n<div>&nbsp;<\/div>\n<div>Nous souhaitons une personne tr&egrave;s Intelligente, capable de r&eacute;fl&eacute;chir de mani&egrave;re autonome et assidue, QI sup&eacute;rieur ou &eacute;gal &agrave; 100 ; bonne organisation du travail et des dossiers ; parfaite connaissance des logiciels de comptabilit&eacute; et les outils informatiques (Microsoft Office, Access, Sage Sari )<\/div>\n<div>&nbsp;<\/div>\n<div>POSTE : Comptable<\/div>\n<div>&nbsp;<\/div>\n<div>PR&Eacute;REQUIS<\/div>\n<div>&nbsp;<\/div>\n<div>Age : Entre 20 et 27 ans<\/div>\n<div>&nbsp;<\/div>\n<div>Lieu de travail : Yaound&eacute;<\/div>\n<div>&nbsp;<\/div>\n<div>CV avec photo obligatoire : Tr&egrave;s important (Sinon dossier rejet&eacute;)<\/div>\n<div>&nbsp;<\/div>\n<div>Salaire de base : 150 000 FCFA<\/div>\n<div>&nbsp;<\/div>\n<div>Sexe : Masculin<\/div>\n<div>&nbsp;<\/div>\n<div>Exp&eacute;rience requise : Jeune dipl&ocirc;m&eacute; ou&nbsp; exp&eacute;rience &agrave; partir de 06 mois.<\/div>\n<div>&nbsp;<\/div>\n<div>Niveau d&rsquo;&eacute;tude : Minimum BAC+5<\/div>\n<div>&nbsp;<\/div>\n<div>Langue parl&eacute;e ; Fran&ccedil;ais, Anglais<\/div>\n<div>&nbsp;<\/div>\n<div>Date limite de d&eacute;p&ocirc;t des dossiers : 29\/08\/2024.<\/div>\n<div>&nbsp;<\/div>\n<div>Adresse de transmission de dossier : mailto:drh@nyamoro-group.com<\/div>\n<div>&nbsp;<\/div>\n<div>NB : Seuls les candidats ayant re&ccedil;u et r&eacute;pondu au mail de pr&eacute;s&eacute;lection participeront au test de QI et &agrave; l&rsquo;entretien d&#8217;embauche.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>NYAMORO GROUP SA est une entreprise sp&eacute;cialis&eacute;e dans l&rsquo;incubation de projets innovants et le placement financier. Elle dispose en son sein de plusieurs autres entit&eacute;s&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"open","template":"","categories":[282],"tags":[],"villes":[136],"contrats":[148],"diplomes":[159],"louma_meta":{"emploi_title":"COMPTABLE","emplois_employeur":3046,"emplois_date_publication":"2024-08-13","emplois_heure_publication":"","emplois_date_cloture":"2024-08-29","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"drh@nyamoro-group.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/48914"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=48914"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/48914\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=48914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=48914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=48914"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=48914"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=48914"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=48914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}