{"id":4861,"date":"2020-07-15T04:46:30","date_gmt":"2020-07-15T02:46:30","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=4861"},"modified":"2020-07-15T04:46:55","modified_gmt":"2020-07-15T02:46:55","slug":"technicien-de-surface-coursier","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/technicien-de-surface-coursier\/","title":{"rendered":"Technicien de surface &#8211; Coursier"},"content":{"rendered":"<p>Technicien de surface &#8211; Coursier<\/p>\n<p>Type d\u2019offre : Temporaire<br \/>\nSecteur : immobilier<br \/>\nLieu : Akwa-Douala<br \/>\nDomaine de l\u2019offre : Technicien de surface<\/p>\n<p>Missions \u2013 Technicien de surface :<br \/>\n\u2022 Assurer le nettoyage et l\u2019entretien des locaux en respectant m\u00e9thodiquement le planning de travail<br \/>\n\u2022 Veiller \u00e0 la bonne utilisation, l\u2019entretien du mat\u00e9riel et des produits mis \u00e0 disposition<br \/>\n\u2022 Veiller \u00e0 ne pas endommager tout objet meublant, mat\u00e9riel et support pendant le processus de nettoyage<br \/>\n\u2022 Respecter toutes les r\u00e8gles d\u2019hygi\u00e8ne et s\u00e9curit\u00e9<br \/>\n\u2022 Rendre compte \u00e0 qui de droit de tout dysfonctionnement ou de toute anomalie<br \/>\n\u2022 Assurer l\u2019entretien courant des mat\u00e9riels et ou machines utilis\u00e9es<br \/>\n\u2022 Effectuer des courses concernant l\u2019entreprise<br \/>\nProfil recherch\u00e9<br \/>\n&#8211; Niveau minimum : BEPC ou tout dipl\u00f4me \u00e9quivalent<br \/>\n&#8211; Exp\u00e9rience professionnelle : Au moins 6 mois dans le domaine<br \/>\n&#8211; Age : 25-30 ans<br \/>\nAptitudes :<br \/>\n\u2022 Bonne pr\u00e9sentation physique<br \/>\n\u2022 Savoir parler et \u00e9crire le Fran\u00e7ais<br \/>\n\u2022 Faire preuve de discr\u00e9tion<br \/>\n\u2022 Avoir une bonne capacit\u00e9 d\u2019adaptation<br \/>\n\u2022 \u00catre travailleur et dynamique<\/p>\n<p>Envoyez votre CV \u00e0 : contact@sai-latoile.com<br \/>\nEn pr\u00e9cisant en Objet : Technicien de Surface<br \/>\nDate limite : 27\/07\/2020<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Technicien de surface &#8211; Coursier Type d\u2019offre : Temporaire Secteur : immobilier Lieu : Akwa-Douala Domaine de l\u2019offre : Technicien de surface Missions \u2013 Technicien&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[3],"tags":[],"villes":[136],"contrats":[234],"diplomes":[164],"louma_meta":{"emploi_title":"Technicien de surface - Coursier","emplois_employeur":3046,"emplois_date_publication":"2020-07-15","emplois_heure_publication":"","emplois_date_cloture":"2020-07-27","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"contact@sai-latoile.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/4861"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=4861"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/4861\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3031"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=4861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=4861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=4861"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=4861"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=4861"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=4861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}