{"id":48582,"date":"2024-07-22T18:19:35","date_gmt":"2024-07-22T16:19:35","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=48582"},"modified":"2024-07-22T18:19:38","modified_gmt":"2024-07-22T16:19:38","slug":"un-e-responsable-dagence","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/un-e-responsable-dagence\/","title":{"rendered":"UN.E RESPONSABLE D&rsquo;AGENCE"},"content":{"rendered":"\n<p>NOUS RECRUTONS UN.E RESPONSABLE D&rsquo;AGENCE<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MISSIONS PRINCIPALES:<\/h2>\n\n\n\n<ul>\n<li>Fid\u00e9liser et d\u00e9velopper le portefeuille clients de l&rsquo;agence tout en assurant une bonne gestion des risques op\u00e9rationnels, juridiques, de contrepartie ;<\/li>\n\n\n\n<li>Etablir le plan d&rsquo;action commercial de l&rsquo;agence, le d\u00e9cliner par collaborateur et suivre sa r\u00e9alisation;<\/li>\n\n\n\n<li>Accompagner et assurer la gestion administrative de ses \u00e9quipes individuellement et collectivement de concert avec son responsable de groupe;<\/li>\n\n\n\n<li>Suivre le niveau de conformit\u00e9 en agence, d\u00e9ployer les actions de contr\u00f4le interne et mettre en place les actions correctives;<\/li>\n\n\n\n<li>Contr\u00f4ler la conformit\u00e9 de toutes les op\u00e9rations effectu\u00e9es ;<\/li>\n\n\n\n<li>Assurer le suivi et la mise en \u0153uvre des recommandations de l&rsquo;audit et du contr\u00f4le interne ;<\/li>\n\n\n\n<li>Coordonner l&rsquo;identification et la remont\u00e9e des incidents op\u00e9rationnels ainsi que le maintien de la culture du risque ;<\/li>\n\n\n\n<li>V\u00e9rifier la conformit\u00e9 des pratiques suivants les r\u00e8gles de gestion et normes en vigueur;<\/li>\n\n\n\n<li>Identifier, mettre en place et superviser les actions de r\u00e9alignement sur les r\u00e8gles de gestion et normes en vigueur.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">COMP\u00c9TENCES:<\/h2>\n\n\n\n<ul>\n<li>Management d&rsquo;\u00e9quipe,<\/li>\n\n\n\n<li>D\u00e9veloppement des produits et services aux particuliers et professionnels,<\/li>\n\n\n\n<li>Pilotage de l&rsquo;activit\u00e9 commerciale,<\/li>\n\n\n\n<li>Techniques de prospection et de vente,<\/li>\n\n\n\n<li>Gestion d&rsquo;un portefeuille client,<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Niveau Requis:<br><\/h2>\n\n\n\n<ul>\n<li>Ma\u00eetrise des contr\u00f4les internes,<\/li>\n\n\n\n<li>Bac + 4\/5 en Gestion, Economie, Commerce, etc.<\/li>\n\n\n\n<li>Analyse d&rsquo;un dossier de cr\u00e9dit,<\/li>\n<\/ul>\n\n\n\n<p>Exp\u00e9rience:<\/p>\n\n\n\n<ul>\n<li>8 ans d&rsquo;exp\u00e9rience en banque ou finances<\/li>\n\n\n\n<li>Type de contrat: CDI<\/li>\n\n\n\n<li>Offre commerciale et techniques de n\u00e9gociation Maitrise de l&rsquo;\u00e9cosyst\u00e8me bancaire et financier,<\/li>\n\n\n\n<li>Syst\u00e8mes d&rsquo;information bancaires,<\/li>\n\n\n\n<li>Gestion des normes et de la r\u00e9glementation,<\/li>\n\n\n\n<li>Suite Office (Word, Excel, Powerpoint).<\/li>\n<\/ul>\n\n\n\n<p><br>Date limite de r\u00e9ception des candidatures 26\/07\/2024 \u00e0 17h30<\/p>\n\n\n\n<p>PROFIL:<\/p>\n\n\n\n<ul>\n<li>Niveau d&rsquo;\u00e9tude : Bac + 4\/5 en Gestion, Economie, Banque et Finances, Commerce \/ Action Commerciale;<\/li>\n\n\n\n<li>Ma\u00eetrise du fran\u00e7ais et\/ou l&rsquo;anglais;<\/li>\n\n\n\n<li>Avoir minimum 8 ans ans d&rsquo;exp\u00e9rience professionnelle;<\/li>\n\n\n\n<li>Avoir un dipl\u00f4me ITB ou une certification en lien avec le m\u00e9tier serait un atout.<\/li>\n<\/ul>\n\n\n\n<p>MODALIT\u00c9S PRATIQUES:<br><\/p>\n\n\n\n<p>Pour postuler, envoyez votre candidature (CV actualis\u00e9 + lettre de motivation) en pr\u00e9cisant en objet l&rsquo;intitul\u00e9 du poste \u00e0 pourvoir \u00e0 l&rsquo;adresse suivante : recrutementrh@scbcameroun.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOUS RECRUTONS UN.E RESPONSABLE D&rsquo;AGENCE MISSIONS PRINCIPALES: COMP\u00c9TENCES: Niveau Requis: Exp\u00e9rience: Date limite de r\u00e9ception des candidatures 26\/07\/2024 \u00e0 17h30 PROFIL: MODALIT\u00c9S PRATIQUES: Pour postuler,&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","categories":[21,23],"tags":[],"villes":[135],"contrats":[234],"diplomes":[159],"louma_meta":{"emploi_title":"UN.E RESPONSABLE D'AGENCE","emplois_employeur":6367,"emplois_date_publication":"2024-07-22","emplois_heure_publication":"","emplois_date_cloture":"2024-08-05","emplois_heure_cloture":"","emplois_experience_min":"8","emplois_experience_max":"","emploi_email":"recrutementrh@scbcameroun.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/48582"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=48582"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/48582\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/6368"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=48582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=48582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=48582"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=48582"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=48582"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=48582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}