{"id":48570,"date":"2024-07-19T17:48:00","date_gmt":"2024-07-19T15:48:00","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=48570"},"modified":"2024-07-19T17:48:06","modified_gmt":"2024-07-19T15:48:06","slug":"une-01-adjointe-marketing-et-communication","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/une-01-adjointe-marketing-et-communication\/","title":{"rendered":"UN(E) (01) ADJOINT(E) MARKETING ET COMMUNICATION"},"content":{"rendered":"\n<p>UN(E) (01) ADJOINT(E) MARKETING ET COMMUNICATION <\/p>\n\n\n\n<p>Localisation : Yaound\u00e9 \u2013 Cameroun. <\/p>\n\n\n\n<p>Mission principale : <\/p>\n\n\n\n<p>Rattach\u00e9 au D\u00e9partement Commercial, du Marketing et de la Communication \u00e0 la Direction g\u00e9n\u00e9rale, l\u2019Adjointe(e) marketing et communication aura pour missions : <\/p>\n\n\n\n<ul>\n<li>&#8211; Accompagner la hi\u00e9rarchie dans le d\u00e9ploiement du plan d\u2019action marketing, le lancement de services ou de produits, la conception et la mise en \u0153uvre des leviers de d\u00e9veloppement des ventes et la fid\u00e9lisation des clients ; <\/li>\n\n\n\n<li>&#8211; Participer \u00e0 la promotion des produits et services de Vision Finance S.A ; <\/li>\n\n\n\n<li>&#8211; Assurer la mise en \u0153uvre des actions marketing ; <\/li>\n\n\n\n<li>&#8211; Veiller et participer au d\u00e9veloppement de l\u2019offre produits ; <\/li>\n\n\n\n<li>&#8211; Participer au pilotage de plans d\u2019action marketing et la mise en \u0153uvre de ces derniers ;<\/li>\n\n\n\n<li> &#8211; Utiliser des techniques de commercialisation pour multiplier les ventes des produits et services de Vision Finance S.A ; <\/li>\n\n\n\n<li>&#8211; Promouvoir l\u2019image et les valeurs de l\u2019entreprise ; <\/li>\n\n\n\n<li>&#8211; Assurer via un programme d\u2019actions, le webmaster dont il\/elle assure le suivi et la croissance des ventes de produits et des prospects online ;<\/li>\n\n\n\n<li> &#8211; Se charger des t\u00e2ches administratives quotidiennes pour assurer la fonctionnalit\u00e9 et la coordination des activit\u00e9s du Service En raison du caract\u00e8re transversal de sa mission, il\/elle travaille en collaboration \u00e9troite avec l\u2019ensemble des acteurs de l\u2019entreprise. <\/li>\n<\/ul>\n\n\n\n<p>I. LES PRINCIPALES ACTIVITES<\/p>\n\n\n\n<ul>\n<li> &#8211; Participation \u00e0 la mise en \u0153uvre du plan marketing et communication op\u00e9rationnel ; <\/li>\n\n\n\n<li>&#8211; Participation \u00e0 la politique d&rsquo;actions marketing et communication ; <\/li>\n\n\n\n<li>&#8211; Participation \u00e0 la mise en place, \u00e0 l\u2019application et au suivi des actions de communication ; <\/li>\n\n\n\n<li>&#8211; Analyse des performances &#8211; Conseil, accompagnement et aide \u00e0 la vente pour les commerciaux ;<\/li>\n\n\n\n<li>Valorisation de l\u2019image de l\u2019entreprise ;<\/li>\n\n\n\n<li> &#8211; Pilotage par la performance et optimisation de la strat\u00e9gie ; <\/li>\n\n\n\n<li>&#8211; Production des outils d\u2019aide \u00e0 la vente ; <\/li>\n\n\n\n<li>&#8211; Participation au pilotage des campagnes de communication ; <\/li>\n\n\n\n<li>&#8211; Gestion des relations m\u00e9dias ; &#8211; Production de contenus ; <\/li>\n\n\n\n<li>&#8211; Activit\u00e9 de veille et d\u2019analyse statistique ; <\/li>\n\n\n\n<li>&#8211; Production des outils d\u2019aide \u00e0 la vente. <\/li>\n<\/ul>\n\n\n\n<p>II. COMPETENCES<\/p>\n\n\n\n<p> Profil de base : <\/p>\n\n\n\n<ul>\n<li>&#8211; Titulaire au minimum Bac+3 ; <\/li>\n\n\n\n<li>&#8211; Et\/ou 01 an d\u2019exp\u00e9rience professionnelle en milieu bancaire. <\/li>\n<\/ul>\n\n\n\n<p>Comp\u00e9tences techniques requises :<\/p>\n\n\n\n<ul>\n<li> &#8211; Excellente ma\u00eetrise des outils bureautiques (pack Office : PowerPoint, Word, Excel) ; <\/li>\n\n\n\n<li>&#8211; Bonne ma\u00eetrise des outils informatiques de cr\u00e9ation graphique (Adobe Creative Cloud, Canva\u2026) &#8211; Connaissance des logiciels de gestion d\u2019e-mailing (Mailchimp, Sendinblue\u2026) ; <\/li>\n\n\n\n<li>&#8211; Connaissance des logiciels de gestion de la relation client (CRM) ; <\/li>\n\n\n\n<li>&#8211; Bonne ma\u00eetrise des outils de marketing digital ; <\/li>\n\n\n\n<li>&#8211; Excellente ma\u00eetrise de la langue fran\u00e7aise (syntaxe, orthographe, vocabulaire, style) <\/li>\n\n\n\n<li>&#8211; Bonne ma\u00eetrise des outils et techniques marketing : segmentation, analyses de march\u00e9\u2026. <\/li>\n<\/ul>\n\n\n\n<p>Aptitudes requises : <\/p>\n\n\n\n<ul>\n<li>-Int\u00e9r\u00eat pour le digital, les r\u00e9seaux sociaux et les nouvelles technologies ; <\/li>\n\n\n\n<li>-Capacit\u00e9 \u00e0 travailler sur plusieurs projets en parall\u00e8le ; <\/li>\n\n\n\n<li>-Organisation et rigueur ; <\/li>\n\n\n\n<li>-Go\u00fbt pour les chiffres ; <\/li>\n\n\n\n<li>-Cr\u00e9ativit\u00e9 ; <\/li>\n\n\n\n<li>-Force de proposition ; <\/li>\n\n\n\n<li>-Aptitudes commerciales ; <\/li>\n\n\n\n<li>-Reporting.<\/li>\n<\/ul>\n\n\n\n<p>Dossier de candidature : <\/p>\n\n\n\n<p>&#8211; Une demande adress\u00e9e \u00e0 Madame le Directeur G\u00e9n\u00e9ral de Vision Finance S.A ; &#8211; Une lettre de motivation adress\u00e9e Madame le Directeur G\u00e9n\u00e9ral de Vision Finance S.A ; &#8211; Un curriculum vitae avec photo d\u00e9taill\u00e9 sinc\u00e8re, dat\u00e9 et sign\u00e9 ; &#8211; Une photocopie de la CNI en couleur de la candidate. Le dossier de candidature, devra \u00eatre d\u00e9pos\u00e9 exclusivement \u00e0 l\u2019adresse e-mail : recruterh@visionfinancesa.com avec pour objet \u00ab UN(E) (01) ADJOINT(E) MARKETING ET COMMUNICATION \u00bb au plus tard le 26 juillet 2024 \u00e0 16h30min. Seuls les candidats pr\u00e9s\u00e9lectionn\u00e9s seront contact\u00e9s. Confidentialit\u00e9 assur\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>UN(E) (01) ADJOINT(E) MARKETING ET COMMUNICATION Localisation : Yaound\u00e9 \u2013 Cameroun. Mission principale : Rattach\u00e9 au D\u00e9partement Commercial, du Marketing et de la Communication \u00e0&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","categories":[25,24],"tags":[],"villes":[136],"contrats":[234],"diplomes":[212],"louma_meta":{"emploi_title":"UN(E) (01) ADJOINT(E) MARKETING ET COMMUNICATION ","emplois_employeur":43443,"emplois_date_publication":"2024-07-19","emplois_heure_publication":"","emplois_date_cloture":"2024-07-26","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"recruterh@visionfinancesa.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/48570"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=48570"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/48570\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/43444"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=48570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=48570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=48570"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=48570"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=48570"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=48570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}