{"id":48562,"date":"2024-07-19T16:47:53","date_gmt":"2024-07-19T14:47:53","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=48562"},"modified":"2024-07-19T16:47:57","modified_gmt":"2024-07-19T14:47:57","slug":"un-01-gestionnaire-de-risques","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/un-01-gestionnaire-de-risques\/","title":{"rendered":"UN (01) GESTIONNAIRE DE RISQUES"},"content":{"rendered":"\n<p>UN (01) GESTIONNAIRE DE RISQUES <\/p>\n\n\n\n<p>Localisation : Yaound\u00e9 \u2013 Cameroun. <\/p>\n\n\n\n<p>Mission principale : Rattach\u00e9 au Contr\u00f4le interne \u00e0 la Direction g\u00e9n\u00e9rale, le gestionnaire de risques aura pour missions : d\u2019identifier et analyser divers risques ; de d\u00e9velopper des contr\u00f4les de gestion des risques et des plans d\u2019urgence et de communiquer des recommandations \u00e0 la Direction G\u00e9n\u00e9rale. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">I. LES PRINCIPALES ACTIVITES <\/h2>\n\n\n\n<ul>\n<li>&#8211; D\u00e9finir, d\u00e9ployer et animer le dispositif de gestion des risques de l\u2019entreprise, <\/li>\n\n\n\n<li>&#8211; Proposer des solutions de traitement optimis\u00e9 ;<\/li>\n\n\n\n<li> &#8211; Participer \u00e0 l\u2019\u00e9laboration et la mise \u00e0 jour de la cartographie des risques ; <\/li>\n\n\n\n<li>&#8211; Contribuer \u00e0 l\u2019\u00e9laboration et la mise en \u0153uvre d\u2019un plan de maitrise des risques ; <\/li>\n\n\n\n<li>&#8211; Veiller au respect de la conformit\u00e9, de l\u2019\u00e9thique et de la bonne gouvernance ; <\/li>\n\n\n\n<li>&#8211; Contribuer \u00e0 diffuser et mettre en \u0153uvre la culture du risque au sein de l\u2019entreprise ainsi qu\u2019\u00e0 la mise en \u0153uvre de la politique de pr\u00e9vention de risques. <\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">II. COMPETENCES <\/h2>\n\n\n\n<p>Profil de base :  <\/p>\n\n\n\n<ul>\n<li>-Titulaire au minimum Bac+4\/5 en Comptabilit\u00e9 et Finance, Audit et contr\u00f4le de gestion, management ; <\/li>\n\n\n\n<li>-Et\/ou 03 ans d\u2019exp\u00e9rience professionnelle de pr\u00e9f\u00e9rence en milieu bancaire ; <\/li>\n\n\n\n<li>&#8211; Avoir de solides comp\u00e9tences analytiques (capacit\u00e9 d\u2019extraction, de compilation et d\u2019analyse des donn\u00e9es) ; &#8211; Avoir une bonne capacit\u00e9 d\u2019organisation et de suivi ; <\/li>\n\n\n\n<li> Avoir une bonne comp\u00e9tence en communication verbale et \u00e9crite en fran\u00e7ais ; <\/li>\n\n\n\n<li> Avoir une bonne connaissance en gestion des syst\u00e8mes d\u2019information. <\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Comp\u00e9tences techniques : <\/h2>\n\n\n\n<p> Capacit\u00e9 d\u2019\u00e9coute, d\u2019observation et d\u2019analyse ;<\/p>\n\n\n\n<ul>\n<li>Bonne connaissance du management des risques ; <\/li>\n\n\n\n<li>&#8211; Capacit\u00e9 \u00e0 n\u00e9gocier et \u00e0 proposer les \u00e9volutions susceptibles d\u2019am\u00e9liorer les performances des unit\u00e9s audit\u00e9es ; <\/li>\n\n\n\n<li>&#8211; Aptitude \u00e0 r\u00e9diger de mani\u00e8re claire et synth\u00e9tique ; <\/li>\n\n\n\n<li>&#8211; Ma\u00eetrise des outils informatiques de base (World, Excel, PowerPoint) ; <\/li>\n\n\n\n<li>&#8211; Maitrise des techniques de mod\u00e9lisation de processus ; <\/li>\n\n\n\n<li>&#8211; Connaissance des m\u00e9thodes, normes et proc\u00e9dures de conduite des missions d\u2019audit ; <\/li>\n\n\n\n<li>&#8211; Connaissance financi\u00e8res solides ; <\/li>\n\n\n\n<li>&#8211; Connaissance et compr\u00e9hension des m\u00e9canismes budg\u00e9taires et proc\u00e9dure de d\u00e9pense en vigueur au sein de l\u2019entreprise ; <\/li>\n\n\n\n<li>&#8211; Maitrise de l\u2019organisation comptable du syst\u00e8me ; <\/li>\n\n\n\n<li>&#8211; Vous appr\u00e9ciez travailler en \u00e9quipe et \u00eates r\u00e9sistant au stress ; <\/li>\n\n\n\n<li>&#8211; Votre r\u00e9activit\u00e9, votre disponibilit\u00e9, vous permettront de vous \u00e9panouir pleinement au sein de notre entreprise. <\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Dossier de candidature : <\/h2>\n\n\n\n<ul>\n<li>&#8211; Une demande adress\u00e9e \u00e0 Madame le Directeur G\u00e9n\u00e9ral de Vision Finance S.A ; <\/li>\n\n\n\n<li>&#8211; Une lettre de motivation adress\u00e9e Madame le Directeur G\u00e9n\u00e9ral de Vision Finance S.A ; <\/li>\n\n\n\n<li>&#8211; Un curriculum vitae avec photo d\u00e9taill\u00e9 sinc\u00e8re, dat\u00e9 et sign\u00e9 ; <\/li>\n\n\n\n<li>&#8211; Une photocopie de la CNI en couleur de la candidate. <\/li>\n<\/ul>\n\n\n\n<p>Le dossier de candidature, devra \u00eatre d\u00e9pos\u00e9 exclusivement \u00e0 l\u2019adresse e-mail recruterh@visionfinancesa.com avec pour objet \u00ab GESTIONNAIRE DE RISQUES \u00bb au plus tard le 26 juillet 2024 \u00e0 16h30min. Seuls les candidats pr\u00e9s\u00e9lectionn\u00e9s seront contact\u00e9s. Confidentialit\u00e9 assur\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>UN (01) GESTIONNAIRE DE RISQUES Localisation : Yaound\u00e9 \u2013 Cameroun. Mission principale : Rattach\u00e9 au Contr\u00f4le interne \u00e0 la Direction g\u00e9n\u00e9rale, le gestionnaire de risques&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","categories":[23],"tags":[],"villes":[136],"contrats":[234],"diplomes":[159],"louma_meta":{"emploi_title":"UN (01) GESTIONNAIRE DE RISQUES ","emplois_employeur":43443,"emplois_date_publication":"2024-07-19","emplois_heure_publication":"","emplois_date_cloture":"2024-07-26","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"recruterh@visionfinancesa.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/48562"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=48562"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/48562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/43444"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=48562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=48562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=48562"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=48562"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=48562"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=48562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}